{"id":43206,"date":"2022-09-05T10:39:46","date_gmt":"2022-09-05T13:39:46","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43206"},"modified":"2022-09-05T10:39:47","modified_gmt":"2022-09-05T13:39:47","slug":"mercado-financeiro-reduz-projecao-da-inflacao-de-67-para-661","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/05\/mercado-financeiro-reduz-projecao-da-inflacao-de-67-para-661\/","title":{"rendered":"Mercado financeiro reduz proje\u00e7\u00e3o da infla\u00e7\u00e3o de 6,7% para 6,61%"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Previs\u00e3o para o PIB subiu de 2,1% para 2,26% em 2022<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"> Por Andreia Verd\u00e9lio \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/180961.mp3\"><\/h4>\n\n\n\n<p>A previs\u00e3o do mercado financeiro para o \u00cdndice Nacional de Pre\u00e7os ao Consumidor Amplo (IPCA), considerada a infla\u00e7\u00e3o oficial do pa\u00eds, caiu de 6,7% para 6,6% neste ano. \u00c9 a d\u00e9cima redu\u00e7\u00e3o consecutiva da proje\u00e7\u00e3o. A estimativa est\u00e1 no&nbsp;<em>boletim Focus<\/em>&nbsp;de hoje (5), pesquisa divulgada semanalmente pelo Banco Central (BC), com a expectativa de institui\u00e7\u00f5es para os principais indicadores econ\u00f4micos.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1480756&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1480756&amp;o=node\"><\/p>\n\n\n\n<p>Para 2023, a estimativa de infla\u00e7\u00e3o ficou em 5,27%. Para 2024 e 2025, as previs\u00f5es s\u00e3o de infla\u00e7\u00e3o em 3,43% e 3%, respectivamente.<\/p>\n\n\n\n<p>A previs\u00e3o para 2022 est\u00e1 acima da meta de infla\u00e7\u00e3o que deve ser perseguida pelo BC. A meta, definida pelo Conselho Monet\u00e1rio Nacional, \u00e9 de 3,5% para este ano, com intervalo de toler\u00e2ncia de 1,5 ponto percentual para cima ou para baixo. Ou seja, o limite inferior \u00e9 2,25% e o superior 5,25%.<\/p>\n\n\n\n<p>Em julho, a&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2022-08\/ipca-tem-deflacao-de-068-em-julho-menor-taxa-da-serie-historica\" target=\"_blank\" rel=\"noreferrer noopener\">infla\u00e7\u00e3o recuou 0,68%<\/a>, ap\u00f3s aumento de 0,67% registrada em junho. Com o resultado, o IPCA acumula alta de 4,77%, no ano, e 10,07%, em 12 meses.<\/p>\n\n\n\n<p>Os dados de agosto ser\u00e3o divulgados na sexta-feira (9). Mas, o IPCA-15, a pr\u00e9via da infla\u00e7\u00e3o oficial,&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2022-08\/ipca15-tem-deflacao-em-agosto\" target=\"_blank\" rel=\"noreferrer noopener\">tamb\u00e9m registrou defla\u00e7\u00e3o<\/a>&nbsp;no m\u00eas passado, de 0,73%, menor que a de julho (alta de 0,13%), segundo o Instituto Brasileiro de Geografia e Estat\u00edstica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Taxa de juros<\/h2>\n\n\n\n<p>Para alcan\u00e7ar a meta de infla\u00e7\u00e3o, o Banco Central usa como principal instrumento a taxa b\u00e1sica de juros, a Selic, definida em 13,75% ao ano pelo Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom). A taxa est\u00e1 no maior n\u00edvel desde janeiro de 2017, quando tamb\u00e9m estava em 13,75% ao ano.<\/p>\n\n\n\n<p>Para o mercado financeiro, a expectativa \u00e9 de que a Selic encerre o ano nesse patamar. Para o fim de 2023, a estimativa \u00e9 de que a taxa b\u00e1sica caia para 11,25% ao ano. E para 2024 e 2025, a previs\u00e3o \u00e9 de Selic em 8% ao ano e 7,5% ao ano, respectivamente.<\/p>\n\n\n\n<p>Quando o Copom aumenta a taxa b\u00e1sica de juros, a finalidade \u00e9 conter a demanda aquecida, e isso causa reflexos nos pre\u00e7os porque os juros mais altos encarecem o cr\u00e9dito e estimulam a poupan\u00e7a. Desse modo, taxas mais altas tamb\u00e9m podem dificultar a expans\u00e3o da economia. Al\u00e9m da taxa Selic, os bancos consideram outros fatores na hora de definir os juros cobrados dos consumidores, como risco de inadimpl\u00eancia, lucro e despesas administrativas.<\/p>\n\n\n\n<p>Quando o Copom reduz a Selic, a tend\u00eancia \u00e9 de que o cr\u00e9dito fique mais barato, com incentivo \u00e0 produ\u00e7\u00e3o e ao consumo, reduzindo o controle da infla\u00e7\u00e3o e estimulando a atividade econ\u00f4mica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">PIB e c\u00e2mbio<\/h2>\n\n\n\n<p>As institui\u00e7\u00f5es financeiras consultadas pelo BC elevaram a proje\u00e7\u00e3o para o crescimento da economia brasileira este ano de 2,10% para 2,26%. Para 2023, a expectativa para o Produto Interno Bruto (PIB) &#8211; a soma de todos os bens e servi\u00e7os produzidos no pa\u00eds &#8211; \u00e9 de crescimento de 0,47%. Em 2024 e 2025, o mercado financeiro projeta expans\u00e3o do PIB em 1,8% e 2%, respectivamente.<\/p>\n\n\n\n<p>A expectativa para a cota\u00e7\u00e3o do d\u00f3lar manteve-se em R$ 5,20 para o final deste ano. Para o fim de 2023, a previs\u00e3o \u00e9 de que a moeda americana tamb\u00e9m fique nesse mesmo patamar.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Denise Griesinger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Previs\u00e3o para o PIB subiu de 2,1% para 2,26% em 2022 Por Andreia Verd\u00e9lio \u2013<\/p>\n","protected":false},"author":2,"featured_media":43207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-43206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43206"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43206\/revisions"}],"predecessor-version":[{"id":43208,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43206\/revisions\/43208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43207"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}