{"id":43224,"date":"2022-09-05T12:13:33","date_gmt":"2022-09-05T15:13:33","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43224"},"modified":"2022-09-05T12:13:34","modified_gmt":"2022-09-05T15:13:34","slug":"fiocruz-firma-parceria-com-a-prefeitura-de-petropolis-para-desenvolver-acoes-de-prevencao-em-areas-atingidas-pelas-tragedias","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/05\/fiocruz-firma-parceria-com-a-prefeitura-de-petropolis-para-desenvolver-acoes-de-prevencao-em-areas-atingidas-pelas-tragedias\/","title":{"rendered":"Fiocruz firma parceria com a Prefeitura de Petr\u00f3polis para desenvolver a\u00e7\u00f5es de preven\u00e7\u00e3o em \u00e1reas atingidas pelas trag\u00e9dias"},"content":{"rendered":"\n<p>Uma parceria entre o F\u00f3rum Itabora\u00ed: Pol\u00edtica, Ci\u00eancia e Cultura na Sa\u00fade, programa da presid\u00eancia da Fiocruz em Petr\u00f3polis, e a Prefeitura Municipal, foi firmada a fim de desenvolver um plano de preven\u00e7\u00e3o de doen\u00e7as e promo\u00e7\u00e3o da sa\u00fade para as \u00e1reas atingidas pelas trag\u00e9dias de fevereiro e mar\u00e7o deste ano.<\/p>\n\n\n\n<p>A equipe, de 16 t\u00e9cnicos que j\u00e1 iniciaram o trabalho nesses territ\u00f3rios, conta com psiquiatra, enfermeiros, t\u00e9cnicos de enfermagem, assistentes sociais e psic\u00f3logos. Os profissionais foram contratados pela Funda\u00e7\u00e3o para o Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico em Sa\u00fade (Fiotec) e trabalhar\u00e3o com o assessoramento t\u00e9cnico do F\u00f3rum Itabora\u00ed.<\/p>\n\n\n\n<p>A atua\u00e7\u00e3o das equipes ao longo do per\u00edodo de tr\u00eas meses ser\u00e1 nos territ\u00f3rios de Alto da Serra e adjac\u00eancias, como Vila Felipe e Ch\u00e1cara Flora, Sargento Boening, Floresta, Caxambu Lusitano, Sim\u00e9ria, S\u00e3o Sebasti\u00e3o e 24 de Maio. O trabalho tem previs\u00e3o de dura\u00e7\u00e3o de tr\u00eas meses e visa elaborar, em conjunto com as comunidades, um diagn\u00f3stico das principais car\u00eancias e fragilidades sanit\u00e1rias, econ\u00f3micas, sociais e ambientais desses territ\u00f3rios. Um documento contendo os principais resultados, assim como propostas de solu\u00e7\u00e3o, ser\u00e1 encaminhado para o poder p\u00fablico municipal a fim de orientar a\u00e7\u00f5s espec\u00edficas e concretos nessas \u00e1reas.<\/p>\n\n\n\n<p>Diretor do F\u00f3rum Itabora\u00ed, Felix Rosenberg, destaca a import\u00e2ncia desta parceria com a Prefeitura. \u201c\u00c9 fundamental que ocorra essa for\u00e7a tarefa para identificar quais estrat\u00e9gias precisam ser tomadas nessas \u00e1reas. Sabemos que as trag\u00e9dias deixam grandes impactos nas pessoas, que perderam parentes, passaram pela situa\u00e7\u00e3o traum\u00e1tica e ficaram sem suas casas.<br>Atuar na promo\u00e7\u00e3o da sa\u00fade dessas \u00e1reas \u00e9 um trabalho de fortalecimento dessas comunidades para que tenham condi\u00e7\u00e3o de atravessar essa fase e superar e prevenir os desafios impostos pelos desastres\u201d, afirma.<\/p>\n\n\n\n<p>Norma Pontes, apoiadora institucional do departamento de aten\u00e7\u00e3o b\u00e1sica da Secretaria de Sa\u00fade de Petr\u00f3polis, explica que o trabalho em conjunto ser\u00e1 fundamental para colher informa\u00e7\u00f5es nesses territ\u00f3rios que possam, futuramente, subsidiar pol\u00edticas p\u00fablicas de enfrentamento aos desastres, assim como das condi\u00e7\u00f5es sociais e econ\u00f4micas dessas \u00e1reas atingidas a partir do olhar dos pr\u00f3prios moradores. \u201cQue essas pol\u00edticas trabalhem a gest\u00e3o do risco, preven\u00e7\u00e3o de novos desastres, como tamb\u00e9m direcionem para promo\u00e7\u00e3o da sa\u00fade e melhoria da qualidade de vida dessas popula\u00e7\u00f5es\u201d, afirma.<\/p>\n\n\n\n<p>Atua\u00e7\u00e3o nas comunidades<br>Nas \u00faltimas semanas, est\u00e3o sendo realizados no F\u00f3rum Itabora\u00ed treinamentos das equipes a fim de capacitar esses profissionais contratados para a realiza\u00e7\u00e3o do Diagn\u00f3stico R\u00e1pido Participativo (DRP), metodologia de trabalho que consiste em ouvir a popula\u00e7\u00e3o e os atores que t\u00eam rela\u00e7\u00e3o com cada comunidade.<\/p>\n\n\n\n<p>Assistente Social do F\u00f3rum Itabora\u00ed, Marina de Jesus, explica que o documento final deve ser entregue at\u00e9 novembro, antes do per\u00edodo de chuvas. \u201cDurante o processo do DRP, ser\u00e3o trabalhadas propostas para melhorar a qualidade de vida das pessoas que vivem nessas \u00e1reas e tamb\u00e9m ser\u00e1 discutida a viabilidade da implementa\u00e7\u00e3o de a\u00e7\u00f5es concretas\u201d, explica.<\/p>\n\n\n\n<p>Os profissionais ser\u00e3o respons\u00e1veis por fazer um reconhecimento junto \u00e0 comunidade para entender onde est\u00e3o essas fam\u00edlias atingidas pelas trag\u00e9dias, o que elas passaram e quais s\u00e3o os v\u00ednculos delas com o territ\u00f3rio, al\u00e9m de buscar informa\u00e7\u00f5es sobre rotas de fuga. \u201cO objetivo \u00e9 a promo\u00e7\u00e3o da sa\u00fade a partir da perspectiva territorial e do olhar das pessoas que vivem nessas regi\u00f5es e que sinalizam as vulnerabilidades e potencialidades. A forma como cada morador faz a leitura do territ\u00f3rio\u201d, diz Marina.<\/p>\n\n\n\n<p>Sobre o F\u00f3rum Itabora\u00ed<\/p>\n\n\n\n<p>Inaugurado em 18 de outubro de 2011, como uma unidade especial da Presid\u00eancia da Fiocruz, o Pal\u00e1cio Itabora\u00ed abriga o F\u00f3rum Itabora\u00ed: Pol\u00edtica, Ci\u00eancia e Cultura na Sa\u00fade. O F\u00f3rum \u00e9 um espa\u00e7o permanente de reflex\u00e3o e gera\u00e7\u00e3o de ideias, que tem como principal objetivo reunir intelectuais, cientistas, artistas, gestores e usu\u00e1rios de educa\u00e7\u00e3o e sa\u00fade do Brasil e do estrangeiro, para gerar formula\u00e7\u00f5es de pol\u00edticas e pr\u00e1ticas tendentes a reduzir as desigualdades sociais na sa\u00fade.<\/p>\n\n\n\n<p>O F\u00f3rum tamb\u00e9m desenvolve a\u00e7\u00f5es comunit\u00e1rias que permitam p\u00f4r em pr\u00e1tica atividades inter e transetoriais destinadas a contribuir com a redu\u00e7\u00e3o de desigualdades sociais.<\/p>\n\n\n\n<p>Entre essas pr\u00e1ticas se destacam: a Trilha do Arboreto, uma cole\u00e7\u00e3o viva com diversos tipos de plantas, tendo o foco nas esp\u00e9cies medicinais; o Arranjo Produtivo Local de Plantas Medicinais, implantado em v\u00e1rias localidades de Petr\u00f3polis; a Orquestra de C\u00e2mara do Pal\u00e1cio Itabora\u00ed &#8211; OCPIT, voltada \u00e0 inclus\u00e3o e profissionaliza\u00e7\u00e3o de jovens instrumentistas; incluem-se, tamb\u00e9m, a disponibiliza\u00e7\u00e3o de espa\u00e7os de estudos com acesso a bibliotecas virtuais; atividades de inser\u00e7\u00e3o digital; de apoio \u00e0 capacita\u00e7\u00e3o tecnol\u00f3gica para trabalhadores de sa\u00fade; debates culturais, projetos, eventos, concertos e exposi\u00e7\u00f5es de artes e cultura.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma parceria entre o F\u00f3rum Itabora\u00ed: Pol\u00edtica, Ci\u00eancia e Cultura na Sa\u00fade, programa da presid\u00eancia<\/p>\n","protected":false},"author":2,"featured_media":43225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-43224","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43224"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43224\/revisions"}],"predecessor-version":[{"id":43226,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43224\/revisions\/43226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43225"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}