{"id":43233,"date":"2022-09-05T15:35:33","date_gmt":"2022-09-05T18:35:33","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43233"},"modified":"2022-09-05T15:35:34","modified_gmt":"2022-09-05T18:35:34","slug":"circuito-diversidade-dos-sons-com-dudu-lima-no-centro-de-cultura","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/05\/circuito-diversidade-dos-sons-com-dudu-lima-no-centro-de-cultura\/","title":{"rendered":"&#8220;Circuito diversidade dos sons&#8221; com Dudu Lima no Centro de Cultura"},"content":{"rendered":"\n<p>Com apoio da Prefeitura, a Gravat\u00e1s Arte &amp; Cultura apresenta o \u201cCircuito Diversidade dos Sons\u201d com Dudu Lima e convidados nesta quarta-feira (7), no Centro de Cultura Raul de Leoni. O espet\u00e1culo, com entrada gratuita, foi contemplado no edital Retomada Cultural RJ2 promovido pela Secretaria de Estado de Cultura e Economia Criativa do Rio de Janeiro.<\/p>\n\n\n\n<p>Dudu Lima \u00e9 contrabaixista, arranjador e compositor; al\u00e9m de ser reconhecido como um dos maiores instrumentistas brasileiros na atualidade. O show apresenta trabalho autoral do artista que comemora 35 anos de carreira.<\/p>\n\n\n\n<p>Dudu Lima tamb\u00e9m vai receber no palco convidados especiais. S\u00e3o eles: Caetano Brasil (clarinete e sax) Fernanda Ca (voz), Marcos Falc\u00e3o (viol\u00e3o e guitarra), Leandro Scio (bateria).<\/p>\n\n\n\n<p>Servi\u00e7o:<br>Circuito Diversidade dos sons &#8211; Dudu Lima<br>Data: 07 de setembro<br>Hora: 17h<br>Local: Centro de Cultura Raul de Leoni<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com apoio da Prefeitura, a Gravat\u00e1s Arte &amp; Cultura apresenta o \u201cCircuito Diversidade dos Sons\u201d<\/p>\n","protected":false},"author":2,"featured_media":43234,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-43233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43233"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43233\/revisions"}],"predecessor-version":[{"id":43235,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43233\/revisions\/43235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43234"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}