{"id":43236,"date":"2022-09-05T16:57:18","date_gmt":"2022-09-05T19:57:18","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43236"},"modified":"2022-09-05T16:57:19","modified_gmt":"2022-09-05T19:57:19","slug":"presidente-sanciona-lei-que-reduz-idade-minima-para-laqueadura","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/05\/presidente-sanciona-lei-que-reduz-idade-minima-para-laqueadura\/","title":{"rendered":"Presidente sanciona lei que reduz idade m\u00ednima para laqueadura"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Lei reduz de 25 para 21 anos idade para esteriliza\u00e7\u00e3o volunt\u00e1ria<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Fl\u00e1via Albuquerque \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; S\u00e3o Paulo<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/181035.mp3\"><\/h4>\n\n\n\n<p>O presidente Jair Bolsonaro sancionou a Lei 14.443\/22 que diminui de 25 para 21 anos a idade m\u00ednima para esteriliza\u00e7\u00e3o volunt\u00e1ria e permite que, na mulher, o procedimento seja feito logo ap\u00f3s o parto. O texto, que altera a Lei do Planejamento Familiar, tamb\u00e9m exclui da legisla\u00e7\u00e3o a necessidade de consentimento expresso de ambos os c\u00f4njuges para a esteriliza\u00e7\u00e3o.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1480804&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1480804&amp;o=node\"><\/p>\n\n\n\n<p>De acordo com o texto, a idade m\u00ednima n\u00e3o \u00e9 exigida de quem j\u00e1 tiver pelo menos dois filhos vivos. A lei mant\u00e9m o prazo m\u00ednimo de 60 dias entre a manifesta\u00e7\u00e3o da vontade e o procedimento cir\u00fargico de esteriliza\u00e7\u00e3o, mas inova ao permitir \u00e0 mulher a esteriliza\u00e7\u00e3o durante o per\u00edodo do parto.<br><br>O texto garante ainda a oferta de qualquer m\u00e9todo e t\u00e9cnica de contracep\u00e7\u00e3o no prazo m\u00e1ximo de 30 dias.<\/p>\n\n\n\n<p>Atualmente a Portaria 48\/99 do Minist\u00e9rio da Sa\u00fade, que regulamenta a lei, pro\u00edbe a laqueadura durante per\u00edodos de parto, aborto ou at\u00e9 o 42\u00ba dia do p\u00f3s-parto ou aborto, exceto nos casos de comprovada necessidade.<\/p>\n\n\n\n<p>A lei foi publicada no&nbsp;<em>Di\u00e1rio Oficial da Uni\u00e3o&nbsp;<\/em>de hoje (5) entrar\u00e1 em vigor 180 dias ap\u00f3s a publica\u00e7\u00e3o.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: N\u00e1dia Franco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lei reduz de 25 para 21 anos idade para esteriliza\u00e7\u00e3o volunt\u00e1ria Por Fl\u00e1via Albuquerque \u2013<\/p>\n","protected":false},"author":2,"featured_media":43237,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-43236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43236"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43236\/revisions"}],"predecessor-version":[{"id":43238,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43236\/revisions\/43238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43237"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}