{"id":43248,"date":"2022-09-05T17:09:05","date_gmt":"2022-09-05T20:09:05","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43248"},"modified":"2022-09-05T17:09:48","modified_gmt":"2022-09-05T20:09:48","slug":"taxista-reage-a-tentativa-de-assalto-e-mata-criminoso-em-petropolis","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/05\/taxista-reage-a-tentativa-de-assalto-e-mata-criminoso-em-petropolis\/","title":{"rendered":"Taxista reage a tentativa de assalto e mata criminoso em Petr\u00f3polis"},"content":{"rendered":"\n<p>Neste domingo (4), um assaltante morreu no Vila Felipe, em Petr\u00f3polis. O motorista estava trabalhando quando foi abordado por um homem que dizia estar precisando de uma corrida, at\u00e9 o ponto final do bairro. Em seguida o homem teria anunciado o assaltado e rendido o taxista com uma faca. Mas o motorista conseguiu se defender e reagiu, atingindo o assaltante com a arma branca. <\/p>\n\n\n\n<p>De acordo com outros taxistas, que tamb\u00e9m atuam em Petr\u00f3polis, \u00e9 preciso estar atento j\u00e1 que casos como este n\u00e3o s\u00e3o t\u00e3o raros na cidade. \u201cA gente precisa estar sempre vigilante porque voc\u00ea n\u00e3o sabe como essas pessoas v\u00e3o te abordar. Eu tomo muito cuidado mas j\u00e1 sofri uma tentativa de assalto h\u00e1 4 anos. Consegui me desvencilhar, mas tem gente que n\u00e3o consegue e acaba se ferindo\u201d, disse o taxista Ricardo Magalh\u00e3es.<\/p>\n\n\n\n<p>O caso est\u00e1 sendo investigado pela 105\u00aa Delegacia de Pol\u00edcia, no Retiro, como tentativa de roubo e a rea\u00e7\u00e3o do taxista como leg\u00edtima defesa. Segundo a pol\u00edcia, a per\u00edcia foi realizada no local e as investiga\u00e7\u00f5es est\u00e3o em andamento para esclarecimento dos fatos.<\/p>\n\n\n\n<p>\u201cEu acho que a situa\u00e7\u00e3o para os taxistas j\u00e1 foi bem pior na cidade. A gente sofria at\u00e9 tr\u00eas assaltos por semana. Ningu\u00e9m traz letreiro, sabe? As pessoas entram no nosso carro sem a gente saber quem s\u00e3o\u201d, explicou o tamb\u00e9m taxista, Jorge Rabello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste domingo (4), um assaltante morreu no Vila Felipe, em Petr\u00f3polis. O motorista estava trabalhando<\/p>\n","protected":false},"author":2,"featured_media":43249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-43248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43248"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43248\/revisions"}],"predecessor-version":[{"id":43251,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43248\/revisions\/43251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43249"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}