{"id":43271,"date":"2022-09-06T12:47:10","date_gmt":"2022-09-06T15:47:10","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43271"},"modified":"2022-09-06T17:37:06","modified_gmt":"2022-09-06T20:37:06","slug":"apos-manifestacao-durante-realizacao-da-bauernfest-prefeitura-afirma-que-profissionais-da-educacao-terao-enquadramento","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/06\/apos-manifestacao-durante-realizacao-da-bauernfest-prefeitura-afirma-que-profissionais-da-educacao-terao-enquadramento\/","title":{"rendered":"Ap\u00f3s manifesta\u00e7\u00e3o durante realiza\u00e7\u00e3o da Bauernfest prefeitura afirma que profissionais da Educa\u00e7\u00e3o ter\u00e3o enquadramento"},"content":{"rendered":"\n<p>Ap\u00f3s se manifestaram durante uma das principais festas do calend\u00e1rio oficial de Petr\u00f3polis, a Bauernfest,  representantes do Sindicato Estadual dos Profissionais da Educa\u00e7\u00e3o (Sepe Petr\u00f3polis), foram recebidos pelo prefeito Rubens Bomtempo, para uma reuni\u00e3o. No encontro foi informado que os profissionais da educa\u00e7\u00e3o, que t\u00eam direito ao enquadramento por forma\u00e7\u00e3o e tempo de servi\u00e7o, receber\u00e3o o benef\u00edcio ainda no m\u00eas de setembro.<\/p>\n\n\n\n<p>A reuni\u00e3o contou com os secret\u00e1rios municipais de Educa\u00e7\u00e3o, Adriana de Paula; de Administra\u00e7\u00e3o, Ramon Mello; e de Articula\u00e7\u00e3o Institucional, Rafael Sim\u00e3o; al\u00e9m dos representantes do Sepe, Daniel Salom\u00e3o e Rose Silveira.<\/p>\n\n\n\n<p>A secret\u00e1ria de Educa\u00e7\u00e3o, Adriana de Paula, lembrou outros benef\u00edcios concedidos a categoria desde que o atual governo assumiu, em dezembro. \u201cConcedemos dois rateios do super\u00e1vit do Fundeb, um dezembro e outro no m\u00eas de abril\u201d, frisou a secret\u00e1ria.<\/p>\n\n\n\n<p>O diss\u00eddio dos cerca de 11 mil servidores municipais tamb\u00e9m foi discutido no encontro. Segundo o prefeito Rubens Bomtempo uma nova reuni\u00e3o com representante do Sindicato dos Servidores P\u00fablicos Municipais de Petr\u00f3polis (Sisep) ser\u00e1 marcada. \u201cVamos continuar discutindo essa pauta. Enfrentamos problemas econ\u00f4micos e financeiros, mas mesmo assim temos o compromisso com o servidor\u201d, ressaltou o secret\u00e1rio de Administra\u00e7\u00e3o, Ramon Mello.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ap\u00f3s se manifestaram durante uma das principais festas do calend\u00e1rio oficial de Petr\u00f3polis, a Bauernfest,<\/p>\n","protected":false},"author":2,"featured_media":43272,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-43271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43271"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43271\/revisions"}],"predecessor-version":[{"id":43306,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43271\/revisions\/43306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43272"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}