{"id":43280,"date":"2022-09-06T13:19:22","date_gmt":"2022-09-06T16:19:22","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=43280"},"modified":"2022-09-06T13:19:23","modified_gmt":"2022-09-06T16:19:23","slug":"fgv-alugueis-residenciais-ficam-176-mais-caros-em-agosto","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/06\/fgv-alugueis-residenciais-ficam-176-mais-caros-em-agosto\/","title":{"rendered":"FGV: alugu\u00e9is residenciais ficam 1,76% mais caros em agosto"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Acumulado em 12 meses ficou em 10,41%<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Akemi Nitahara \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio\u00a0de Janeiro<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/181308.mp3\"><\/h4>\n\n\n\n<p>O \u00cdndice de Varia\u00e7\u00e3o de Alugu\u00e9is Residenciais (Ivar) registrou alta de 1,76% em agosto, acelerando em rela\u00e7\u00e3o ao aumento de 1,05% registrado em julho. Com isso, o indicador acumula alta de 10,41% em 12 meses. No m\u00eas anterior, o acumulado estava em 8,65%. Os dados foram divulgados&nbsp;hoje&nbsp;(6) pelo Instituto Brasileiro de Economia da Funda\u00e7\u00e3o Getulio Vargas (FGV Ibre).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1480890&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1480890&amp;o=node\"><\/p>\n\n\n\n<p>De acordo com o instituto, todas as cidades pesquisadas tiveram eleva\u00e7\u00e3o na taxa&nbsp;de julho&nbsp;para agosto. O maior reajuste foi verificado em Belo Horizonte, com alta de 3,10%, seguido de Porto Alegre, com 2,63%. Rio&nbsp;de Janeiro&nbsp;registrou aumento de 1,15% e em S\u00e3o Paulo os alugueis ficaram 1,04% mais caros em agosto.<\/p>\n\n\n\n<p>Na compara\u00e7\u00e3o anual do acumulado de 12 meses, houve acelera\u00e7\u00e3o nas quatro cidades pesquisadas: S\u00e3o Paulo (de 8,99% para 10,53%), Rio&nbsp;de Janeiro&nbsp;(10,41% para 11,34%), Belo Horizonte (9,71% para 12,61%) e Porto Alegre (de 6,31% para 8,32%).<\/p>\n\n\n\n<p>O Ivar mede a evolu\u00e7\u00e3o mensal dos valores de alugu\u00e9is residenciais do mercado de im\u00f3veis no Brasil, a partir do levantamento feito com base nos contratos de loca\u00e7\u00e3o de quatro das principais capitais brasileiras.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Maria Claudia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Acumulado em 12 meses ficou em 10,41% Por Akemi Nitahara \u2013 Rep\u00f3rter da Ag\u00eancia Brasil<\/p>\n","protected":false},"author":2,"featured_media":43281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-43280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=43280"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43280\/revisions"}],"predecessor-version":[{"id":43282,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/43280\/revisions\/43282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/43281"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=43280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=43280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=43280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}