{"id":44803,"date":"2022-09-30T15:45:11","date_gmt":"2022-09-30T18:45:11","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=44803"},"modified":"2022-09-30T15:45:12","modified_gmt":"2022-09-30T18:45:12","slug":"ouvidoria-do-mprj-recebera-denuncias-relacionadas-a-eleicao","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/09\/30\/ouvidoria-do-mprj-recebera-denuncias-relacionadas-a-eleicao\/","title":{"rendered":"Ouvidoria do MPRJ receber\u00e1 den\u00fancias relacionadas \u00e0 elei\u00e7\u00e3o"},"content":{"rendered":"\n<p>A Ouvidoria do Minist\u00e9rio P\u00fablico do Estado do Rio de Janeiro estar\u00e1 de plant\u00e3o neste domingo de elei\u00e7\u00e3o (02\/10), de 7h \u00e0s 18h, para o recebimento de den\u00fancias referentes ao pleito eleitoral. As comunica\u00e7\u00f5es poder\u00e3o ser encaminhadas pelos canais da Ouvidoria: o Call Center via telefone 127 (liga\u00e7\u00e3o gratuita dentro do Estado), o Whatsapp 21-993663100 (mensagens escritas e liga\u00e7\u00f5es), e o formul\u00e1rio eletr\u00f4nico no site https:\/\/www.mprj.mp.br\/comunicacao\/ouvidoria\/formulario<\/p>\n\n\n\n<p>Entre as irregularidades mais comuns que podem ser denunciadas durante a vota\u00e7\u00e3o est\u00e3o: a pr\u00e1tica de boca de urna (propaganda em frente \u00e0s se\u00e7\u00f5es eleitorais, distribui\u00e7\u00e3o de material gr\u00e1fico), tumulto e aglomera\u00e7\u00f5es que prejudiquem o exerc\u00edcio do voto, transporte indevido de eleitores e compra de votos.<\/p>\n\n\n\n<p>As den\u00fancias recebidas pela Ouvidoria no domingo ser\u00e3o encaminhadas ao Centro de Apoio Operacional das Promotorias Eleitorais (CAO Eleitoral\/MPRJ), que tamb\u00e9m estar\u00e1 de plant\u00e3o para acionar os promotores eleitorais presentes nas zonas eleitorais fiscalizando as se\u00e7\u00f5es. A Coordenadoria de Seguran\u00e7a e Intelig\u00eancia (CSI\/MPRJ) tamb\u00e9m encaminhar\u00e1 comunica\u00e7\u00f5es recebidas via o Disque-Den\u00fancia (2253-1177). As irregularidades constatadas ser\u00e3o encaminhadas aos Promotores de Justi\u00e7a designados para as fun\u00e7\u00f5es eleitorais bem como \u00e0 Procuradoria Regional Eleitoral.<\/p>\n\n\n\n<p>Segundo o Tribunal Regional Eleitoral (TRE), o Estado do Rio conta com 12.827.296 eleitores aptos a votar em 34.068 se\u00e7\u00f5es nos 4.844 locais de vota\u00e7\u00e3o. S\u00f3 no munic\u00edpio do Rio de Janeiro ser\u00e3o 5.002.621 eleitores em 1.404 locais de vota\u00e7\u00e3o.<\/p>\n\n\n\n<p>Por MPRJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Ouvidoria do Minist\u00e9rio P\u00fablico do Estado do Rio de Janeiro estar\u00e1 de plant\u00e3o neste<\/p>\n","protected":false},"author":2,"featured_media":44804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-44803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=44803"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44803\/revisions"}],"predecessor-version":[{"id":44805,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44803\/revisions\/44805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/44804"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=44803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=44803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=44803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}