{"id":44821,"date":"2022-10-01T05:30:00","date_gmt":"2022-10-01T08:30:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=44821"},"modified":"2022-09-30T17:20:45","modified_gmt":"2022-09-30T20:20:45","slug":"dia-do-idoso-uma-a-cada-tres-pessoas-com-mais-de-65-anos-sofre-pelo-menos-uma-queda-por-ano","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/10\/01\/dia-do-idoso-uma-a-cada-tres-pessoas-com-mais-de-65-anos-sofre-pelo-menos-uma-queda-por-ano\/","title":{"rendered":"Dia do idoso: uma a cada tr\u00eas pessoas com mais de 65 anos sofre pelo menos uma queda por ano"},"content":{"rendered":"\n<p>Queda \u00e9 sin\u00f4nimo de transtorno em qualquer idade, mas quando falamos em quedas de idosos, as consequ\u00eancias podem ser ainda maiores. Muitos idosos que sofrem quedas demandam cuidados hospitalares que exigem maior tempo para uma boa recupera\u00e7\u00e3o. De acordo com dados do Minist\u00e9rio da Sa\u00fade, o somat\u00f3rio de interna\u00e7\u00f5es por fraturas de f\u00eamur de idosos no Brasil foi de 220.712 entre os anos de 2017 e 2021 e o n\u00famero de \u00f3bitos entre 2018 e 2021 foi de 11.546. Dados do Instituto Nacional de Traumatologia e Ortopedia (INTO), do Minist\u00e9rio da Sa\u00fade, apontam que uma a cada tr\u00eas pessoas com mais de 65 anos sofre pelo menos uma queda por ano. E para cada 20 idosos que ca\u00edram, pelo menos um sofre uma fratura ou precisa ser internado.<\/p>\n\n\n\n<p>No dia 1\u00ba de outubro \u00e9 comemorado o Dia Internacional do Idoso e o fisioterapeuta especialista em Gerontologia e docente do curso de Fisioterapia da Est\u00e1cio, Matheus Maciel Pauferro, alerta que diante do crescimento acelerado da popula\u00e7\u00e3o idosa, torna-se fundamental que o governo estabele\u00e7a estrat\u00e9gias e a\u00e7\u00f5es direcionadas a esse grupo populacional, devendo-se priorizar a\u00e7\u00f5es que objetivem a preven\u00e7\u00e3o e promo\u00e7\u00e3o da sa\u00fade, uma vez que essa popula\u00e7\u00e3o consome, hoje, em m\u00e9dia 26% dos gastos com hospitaliza\u00e7\u00f5es no Brasil.<\/p>\n\n\n\n<p>Ele explica que o envelhecimento causa mudan\u00e7as no funcionamento de todos os sistemas do nosso corpo, deixando as rea\u00e7\u00f5es corporais mais lentas, causando desequil\u00edbrio ou um colapso nos sistemas posturais do idoso, onde ele n\u00e3o consegue reagir corporalmente \u00e0s perturba\u00e7\u00f5es externas do ambiente, facilitando as quedas. Matheus informa ainda que mulheres idosas caem mais que homens idosos, devido a fatores hormonais.<\/p>\n\n\n\n<p>\u201cAl\u00e9m das mulheres, idosos com doen\u00e7as pr\u00e9-existentes, idosos institucionalizados e idosos com mais de 80 anos t\u00eam chances maiores de cair que idosos com menos idade, por consequ\u00eancia de fatores individuais, corporais, mentais, ambientais, sociais, n\u00edvel de escolaridade, intera\u00e7\u00e3o de efeitos de medicamentos, insufici\u00eancia familiar, dentre outros fatores\u201d, informou.<\/p>\n\n\n\n<p>De acordo com o especialista, a maior parte dos idosos caem dentro de casa e isso ocorre por ser o local onde eles se sentem autoconfiantes por conhecerem o ambiente que residem, gerando uma sensa\u00e7\u00e3o falsa de percep\u00e7\u00e3o ambiental.<\/p>\n\n\n\n<p>\u201cBanheiro, quarto e cozinha s\u00e3o os locais onde mais ocorrem esse tipo de acidente. Os outros locais que predisp\u00f5em quedas em idosos s\u00e3o: nas ruas, devido \u00e0s cal\u00e7adas irregulares, buracos. Ambientes como o transporte p\u00fablico, quando o \u00f4nibus acelera ou freia bruscamente, podem tamb\u00e9m provocar quedas em idosos\u201d, alertou o coordenador da Est\u00e1cio, que destacou os principais problemas de sa\u00fade causados pelas quedas em idosos.<\/p>\n\n\n\n<p>\u201cEsses problemas podem ser divididos entre estruturais, sociais e comportamentais. De ordem estrutural s\u00e3o as fraturas e comprometimentos de sistemas corporais. Com rela\u00e7\u00e3o aos problemas sociais, podemos citar o isolamento social. J\u00e1 de ordem comportamental, que envolve o psicol\u00f3gico e o mental, podemos relacionar a depress\u00e3o, baixa autoestima, perda de confian\u00e7a, al\u00e9m do medo de cair, gerando um grande impacto na sa\u00fade, reduzindo as atividades de vida di\u00e1ria e depend\u00eancia funcional do idoso para realiza\u00e7\u00e3o de tarefas b\u00e1sicas\u201d, detalha.<\/p>\n\n\n\n<p><strong>Preven\u00e7\u00e3o e cuidados<\/strong><\/p>\n\n\n\n<p>Entre os cuidados necess\u00e1rios para a preven\u00e7\u00e3o de quedas em pessoas idosas, o especialista destaca: evitar objetos espalhados pelo ch\u00e3o; retirar tapetes e panos escorregadios; evitar animais dom\u00e9sticos soltos; ao tomar banho enxugar os p\u00e9s, e ap\u00f3s o banho n\u00e3o passar cremes ou \u00f3leos na planta dos p\u00e9s ou entre os dedos; cortar as unhas sem tirar cut\u00edculas para evitar ferimentos; n\u00e3o utilizar bancos para alcan\u00e7ar objetos ou utens\u00edlios em lugares muito altos; inserir barras de seguran\u00e7a em corredores e banheiro; adaptar a mob\u00edlia e equipamentos de ilumina\u00e7\u00e3o; usar cal\u00e7ados confort\u00e1veis que tenham correias que prendam nos p\u00e9s; evitar meias apertadas para n\u00e3o ocorrer edemas e m\u00e1 circula\u00e7\u00e3o, al\u00e9m de dar prefer\u00eancia \u00e0s meias de algod\u00e3o; realizar consultas e exames peri\u00f3dicos com o m\u00e9dico; idosos com altera\u00e7\u00f5es visuais devem fazer uso de \u00f3culos e idosos com altera\u00e7\u00f5es de equil\u00edbrio e mobilidade reduzida devem fazer uso de dispositivos auxiliares de marcha como bengalas e andadores.<\/p>\n\n\n\n<p>Matheus Maciel Pauferro ainda salienta que a Fisioterapia pode ser uma aliada na preven\u00e7\u00e3o de quedas, atuando na promo\u00e7\u00e3o de sa\u00fade, informando a popula\u00e7\u00e3o sobre os cuidados e a import\u00e2ncia de manter h\u00e1bitos de vida saud\u00e1veis para um envelhecimento ativo e com qualidade de vida.<\/p>\n\n\n\n<p>\u201cAl\u00e9m do trabalho de educa\u00e7\u00e3o em sa\u00fade e orienta\u00e7\u00f5es na adequa\u00e7\u00e3o do ambiente, a Fisioterapia utiliza de avalia\u00e7\u00f5es individualizadas, t\u00e9cnicas, m\u00e9todos e exerc\u00edcios de flexibilidade, for\u00e7a muscular, equil\u00edbrio e coordena\u00e7\u00e3o motora, simulando atividades e situa\u00e7\u00f5es do dia a dia para trabalhar todos os sistemas corporais integrativos relacionados ao controle postural, preparando o corpo desse idoso, caso ele sofra alguma perturba\u00e7\u00e3o postural que provoque queda\u201d, afirmou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Queda \u00e9 sin\u00f4nimo de transtorno em qualquer idade, mas quando falamos em quedas de idosos,<\/p>\n","protected":false},"author":2,"featured_media":30790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-44821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=44821"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44821\/revisions"}],"predecessor-version":[{"id":44822,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44821\/revisions\/44822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/30790"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=44821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=44821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=44821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}