{"id":44855,"date":"2022-10-01T05:09:00","date_gmt":"2022-10-01T08:09:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=44855"},"modified":"2022-10-01T09:10:34","modified_gmt":"2022-10-01T12:10:34","slug":"soberano-itaipava-recebe-paulinho-moska-e-violoes-fenix-do-museu-nacional-2","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/10\/01\/soberano-itaipava-recebe-paulinho-moska-e-violoes-fenix-do-museu-nacional-2\/","title":{"rendered":"Soberano Itaipava recebe Paulinho Moska e viol\u00f5es F\u00eanix do Museu Nacional"},"content":{"rendered":"\n<p>O Soberano Itaipava estar\u00e1 sob os acordes dos \u201cViol\u00f5es F\u00eanix do Museu Nacional\u201d em apresenta\u00e7\u00f5es especiais do cantor Paulinho Moska nos dias 7 e 8 de outubro. Os instrumentos guardam mais de 200 anos de hist\u00f3ria e ir\u00e3o ecoar em Itaipava com o melhor da m\u00fasica. As pe\u00e7as foram lapidadas manualmente, a partir do reaproveitamento de madeiras que foram recolhidas do inc\u00eandio que destruiu grande parte do Museu Nacional. Foram as m\u00e3os habilidosas do subtenente e luthier, Davi Lopes, que esculpiram as sobras, que comp\u00f5em parte da cultura brasileira. Davi atuou no combate ao inc\u00eandio e aplicou a t\u00e9cnica de reaproveitamento que j\u00e1 desenvolvia anteriormente. A iniciativa ganhou o apoio de jornalistas, artistas e produtores, culminando na cria\u00e7\u00e3o do projeto &#8220;F\u00eanix&#8221;, que virou document\u00e1rio da GloboNews.<br>O cantor e compositor Paulinho Moska \u00e9 um dos sete integrantes do grupo F\u00eanix, e sua can\u00e7\u00e3o \u201cTudo Novo de Novo\u201d foi escolhida como tema principal do filme. Os seis instrumentos produzidos pertencem ao museu, mas Moska \u00e9 \u201cpadrinho\u201d de dois deles e j\u00e1 os levou para uma turn\u00ea em Portugal. Agora, o show e os viol\u00f5es chegam \u00e0 Itaipava e junto com as belas can\u00e7\u00f5es do m\u00fasico, certamente ir\u00e3o encantar o p\u00fablico no Soberano.<br>A apresenta\u00e7\u00e3o \u201cPaulinho Moska: Os Viol\u00f5es F\u00eanix do Museu Nacional\u201d relembra grandes sucessos da carreira do cantor, e oferece ao p\u00fablico um presente \u00e0 parte: uma composi\u00e7\u00e3o in\u00e9dita do mestre Pixinguinha, que recentemente, foi letrada por Moska: \u201cA Dor Traz o Presente\u201d.<\/p>\n\n\n\n<p><em>Can\u00e7\u00f5es de Piaf encerram as apresenta\u00e7\u00f5es de setembro<\/em><br>O Soberano se rende ao melhor estilo da m\u00fasica francesa com sucessos de Edith Piaf na linda voz de Let\u00edcia Carvalho. A apresenta\u00e7\u00e3o intimista acontece no dia 30 e tem no viol\u00e3o, Fernando Carvalho. No repert\u00f3rio, cl\u00e1ssicos que encantaram plateias em Paris e no mundo como &#8220;La vie en Rose&#8221;, &#8220;Sous le ciel de Paris&#8221;, &#8220;L\u2019\u00e9tranger&#8221;, &#8220;Padam, padam&#8221;, &#8220;L\u2019accordeoniste&#8221;, &#8220;Mon Dieu&#8221;, &#8220;Non, je ne regrette rien&#8221;, &#8220;Mon man\u00e8ge \u00e0 moi&#8221;, &#8220;Hymne \u00e0 l&#8217;amour&#8221; e &#8220;La Foul\u201d. Os arranjos especiais do violonista Fernando Carvalho conferem emo\u00e7\u00e3o e personalidade ao repert\u00f3rio, trazendo frescor \u00e0s can\u00e7\u00f5es e aproximando a obra da artista do p\u00fablico. Al\u00e9m dos cl\u00e1ssicos que deixaram saudade, passagens da vida de Piaf tamb\u00e9m s\u00e3o contadas no palco.<\/p>\n\n\n\n<p><em>Sobre o Soberano Itaipava<\/em><br>Criado para propiciar uma experi\u00eancia \u00fanica unindo o melhor das artes e uma gastronomia inovadora, o Soberano est\u00e1 aberto de quinta a domingo no Shopping Esta\u00e7\u00e3o Itaipava. O espa\u00e7o oferece coquet\u00e9is elaborados especialmente para os convidados em um ambiente amplo e arejado. O espa\u00e7o tem 180m\u00b2 de instala\u00e7\u00e3o interna, incluindo um mezanino, e 100m\u00b2 de espa\u00e7o externo coberto. A casa conta com seguran\u00e7as 24h, estacionamento privativo com 160 vagas e acessibilidade em rampas e banheiros.<br>Um dos diferenciais do Soberano \u00e9 o espa\u00e7o Havana, destinado exclusivamente aos amantes de charuto, um ambiente ideal para desfrutar da iguaria. A casa conta ainda com o Espa\u00e7o Ruy Castro \u2013 \u00e1rea aberta que complementa o ambiente.<\/p>\n\n\n\n<p><em>Servi\u00e7o:<\/em><br><em>Local:<\/em> Soberano Itaipava &#8211; Estrada Uni\u00e3o Ind\u00fastria, 11000\/LJ 104 &#8211; Shopping Esta\u00e7\u00e3o Itaipava, Petr\u00f3polis.<\/p>\n\n\n\n<p><em>Atra\u00e7\u00f5es:<\/em><\/p>\n\n\n\n<p><em>30 de setembro<\/em><br>Leticia Carvalho Canta Edith Piaf, a partir de 22h<br><em>7 e 8 de outubro<\/em><br>Paulinho Moska: Os viol\u00f5es F\u00eanix do Museu Nacional \u2013 22h<br><em>Contato Imprensa:<\/em> Jaqueline Ribeiro\/ Assessoria Soberano: (24) 9.9221-6186<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Soberano Itaipava estar\u00e1 sob os acordes dos \u201cViol\u00f5es F\u00eanix do Museu Nacional\u201d em apresenta\u00e7\u00f5es<\/p>\n","protected":false},"author":2,"featured_media":44856,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-44855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=44855"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44855\/revisions"}],"predecessor-version":[{"id":44857,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/44855\/revisions\/44857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/44856"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=44855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=44855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=44855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}