{"id":46675,"date":"2022-10-30T08:05:22","date_gmt":"2022-10-30T11:05:22","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=46675"},"modified":"2022-10-30T08:05:24","modified_gmt":"2022-10-30T11:05:24","slug":"boca-de-urna-pode-gerar-pena-de-ate-um-ano-de-prisao-alerta-tse","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2022\/10\/30\/boca-de-urna-pode-gerar-pena-de-ate-um-ano-de-prisao-alerta-tse\/","title":{"rendered":"Boca de urna pode gerar pena de at\u00e9 um ano de pris\u00e3o, alerta TSE"},"content":{"rendered":"\n<p>No primeiro turno das elei\u00e7\u00f5es gerais deste ano, a boca de urna foi um dos crimes eleitorais que, ao lado da compra de votos, mais chamaram a aten\u00e7\u00e3o das autoridades p\u00fablicas encarregadas de coibir pr\u00e1ticas il\u00edcitas capazes de interferir no resultado do pleito.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1490870&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1490870&amp;o=node\"><\/p>\n\n\n\n<p>Segundo o Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica, entre 15 de agosto e 2 de outubro, foram registrados, em todo o pa\u00eds, 444 flagrantes de candidatos, representantes de partidos, cabos eleitorais ou simpatizantes abordando eleitores com o prop\u00f3sito de convenc\u00ea-los a votar em determinada pessoa ou legenda.<\/p>\n\n\n\n<p>Nesta sexta-feira (28), ao declarar que os \u00f3rg\u00e3os de seguran\u00e7a p\u00fablica&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/justica\/noticia\/2022-10\/estamos-preparados-para-o-segundo-turno-diz-ministro-da-justica\" target=\"_blank\" rel=\"noreferrer noopener\">n\u00e3o tolerar\u00e3o a boca de urna e demais crimes eleitorais<\/a>, o ministro da Justi\u00e7a e Seguran\u00e7a P\u00fablica, Anderson Torres, ecoou alerta feito na quinta-feira (27) pelo Tribunal Superior Eleitoral (TSE), ao destacar que quem for flagrado aliciando eleitores no domingo corre o risco de parar atr\u00e1s das grades.<\/p>\n\n\n\n<p>Pela&nbsp;<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/leis\/L9504.htm\" target=\"_blank\" rel=\"noreferrer noopener\">Lei das Elei\u00e7\u00f5es&nbsp;<\/a>(n\u00ba 9.504, de 1997), quem for pego fazendo propaganda de boca de urna no dia da vota\u00e7\u00e3o pode ser punido com deten\u00e7\u00e3o de seis meses a um ano, mais pagamento de multa de at\u00e9 R$ 15,96 mil.<\/p>\n\n\n\n<p>As puni\u00e7\u00f5es podem ser aplicadas tanto para eleitores quanto para representantes de partidos ou candidatos. Por isso, alerta o TSE, \u00e9 importante saber o que pode e o que n\u00e3o pode ser feito durante as elei\u00e7\u00f5es.<\/p>\n\n\n\n<p>Al\u00e9m de proibir a propaganda de boca de urna ou qualquer iniciativa de arregimenta\u00e7\u00e3o eleitoral, a legisla\u00e7\u00e3o veda a realiza\u00e7\u00e3o de com\u00edcios ou carreatas no dia da elei\u00e7\u00e3o, bem como o uso de alto-falantes e amplificadores de som para promo\u00e7\u00e3o pol\u00edtico-partid\u00e1ria.<\/p>\n\n\n\n<p>A distribui\u00e7\u00e3o de material gr\u00e1fico de campanha \u00e9 permitida s\u00f3 at\u00e9 as 22h da v\u00e9spera, e aglomera\u00e7\u00f5es que possam ser interpretadas como manifesta\u00e7\u00e3o coletiva de apoio pol\u00edtico, com ou sem o uso de ve\u00edculos, s\u00e3o autorizadas apenas ap\u00f3s o t\u00e9rmino da vota\u00e7\u00e3o, \u00e0s 17h de domingo (30).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No primeiro turno das elei\u00e7\u00f5es gerais deste ano, a boca de urna foi um dos<\/p>\n","protected":false},"author":2,"featured_media":46676,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-46675","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/46675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=46675"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/46675\/revisions"}],"predecessor-version":[{"id":46677,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/46675\/revisions\/46677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/46676"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=46675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=46675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=46675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}