{"id":52462,"date":"2023-01-29T13:00:38","date_gmt":"2023-01-29T16:00:38","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=52462"},"modified":"2023-01-29T13:00:39","modified_gmt":"2023-01-29T16:00:39","slug":"defesa-civil-emite-alerta-via-sms-sobre-previsao-de-pancadas-de-chuva-em-petropolis","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/01\/29\/defesa-civil-emite-alerta-via-sms-sobre-previsao-de-pancadas-de-chuva-em-petropolis\/","title":{"rendered":"Defesa Civil emite alerta via SMS sobre previs\u00e3o de pancadas de chuva em Petr\u00f3polis"},"content":{"rendered":"\n<p>A Defesa Civil do munic\u00edpio emitiu, \u00e0s 12h deste domingo (29), alerta via SMS de pancadas isoladas de chuva moderada a ocasionalmente forte na tarde e noite de hoje em Petr\u00f3polis.<\/p>\n\n\n\n<p>A Defesa Civil pede que a popula\u00e7\u00e3o fique atenta \u00e0s pr\u00f3ximas atualiza\u00e7\u00f5es.<\/p>\n\n\n\n<p>Cadastre o seu CEP atrav\u00e9s do envio de mensagem de texto para o n\u00famero 40199 para receber os alertas e acompanhe o portal da Prefeitura de Petr\u00f3polis.<\/p>\n\n\n\n<p>O Boletim Meteorol\u00f3gico atualizar\u00e1 a previs\u00e3o do tempo para a cidade, podendo ser acessado atrav\u00e9s do link: https:\/\/bit.ly\/3vmRgZ2.<\/p>\n\n\n\n<p>Foto: divulga\u00e7\u00e3o rede social <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Defesa Civil do munic\u00edpio emitiu, \u00e0s 12h deste domingo (29), alerta via SMS de<\/p>\n","protected":false},"author":2,"featured_media":52212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-52462","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/52462","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=52462"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/52462\/revisions"}],"predecessor-version":[{"id":52463,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/52462\/revisions\/52463"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/52212"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=52462"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=52462"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=52462"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}