{"id":59107,"date":"2023-05-10T14:08:29","date_gmt":"2023-05-10T17:08:29","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=59107"},"modified":"2023-05-10T14:08:30","modified_gmt":"2023-05-10T17:08:30","slug":"teresopolis-recebe-tres-ambulancias-do-programa-samu-100-rj","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/05\/10\/teresopolis-recebe-tres-ambulancias-do-programa-samu-100-rj\/","title":{"rendered":"Teres\u00f3polis recebe tr\u00eas ambul\u00e2ncias do programa \u2018SAMU 100% RJ\u2019"},"content":{"rendered":"\n<p>Em breve Teres\u00f3polis vai ganhar mais duas bases do SAMU &#8211;&nbsp;Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia: uma em \u00c1gua Quente e outra em Bonsucesso, na \u00e1rea rural do munic\u00edpio. O an\u00fancio foi feito pelo Prefeito Vinicius Claussen nesta ter\u00e7a-feira, 09\/05, durante a entrega de 03 ambul\u00e2ncias do projeto \u2018SAMU 100% RJ\u2019, feita pelo Governador em exerc\u00edcio, Thiago Pampolha, e o secret\u00e1rio de Estado de Sa\u00fade, Dr. Luizinho.<\/p>\n\n\n\n<p>\u201cO Governo do Estado destinar\u00e1 recursos para a instala\u00e7\u00e3o das bases avan\u00e7adas de \u00c1gua Quente e Bonsucesso, na \u00e1rea rural. As pr\u00f3ximas etapas s\u00e3o a elabora\u00e7\u00e3o de projeto e realiza\u00e7\u00e3o de procedimento licitat\u00f3rio para obras e contrata\u00e7\u00e3o de pessoal. A previs\u00e3o \u00e9 que comecem a funcionar no 2\u00ba semestre. Agrade\u00e7o ao Governo Claudio Castro por continuar contemplando Teres\u00f3polis com obras e servi\u00e7os em benef\u00edcio de nossa gente\u201d, destacou o prefeito.<\/p>\n\n\n\n<p>A cerim\u00f4nia aconteceu na Pra\u00e7a Ol\u00edmpica Lu\u00eds de Cam\u00f5es, na V\u00e1rzea, onde foram entregues outras 04 ambul\u00e2ncias, para os munic\u00edpios de Cachoeiras de Macacu (01), S\u00e3o Jos\u00e9 do Vale do Rio Preto (01), Sapucaia (01) e Sumidouro (01).<\/p>\n\n\n\n<p>\u201cEsta \u00e9 uma entrega extremamente necess\u00e1ria para garantir o \u00e1gil atendimento prestado pelo SAMU. Continuaremos investindo em sa\u00fade p\u00fablica para honrar os cidad\u00e3os. O Governo do Estado precisa manter o di\u00e1logo permanente, com a\u00e7\u00f5es e investimentos em todas as cidades do estado do Rio de Janeiro\u201d, pontuou o Governador em exerc\u00edcio, Thiago Pampolha.<\/p>\n\n\n\n<p><strong>O programa&nbsp;<\/strong>\u2013 O \u2018SAMU 100% RJ\u2019 est\u00e1 disponibilizando 249 ve\u00edculos para os 92 munic\u00edpios fluminenses, totalizando um investimento de R$ 87 milh\u00f5es. At\u00e9 agora foram entregues 235 ambul\u00e2ncias para 84 cidades. O programa inclui o repasse do custeio do servi\u00e7o, no valor de R$ 49,7 milh\u00f5es ao ano, para as prefeituras que est\u00e3o implantando o atendimento, al\u00e9m de financiamento para a constru\u00e7\u00e3o de bases avan\u00e7adas.<\/p>\n\n\n\n<p>\u201cS\u00e3o tr\u00eas ambul\u00e2ncias adaptadas para UTI M\u00f3vel, que v\u00e3o refor\u00e7ar o atendimento no SAMU Teres\u00f3polis. Vamos apoiar a constru\u00e7\u00e3o das bases avan\u00e7adas de \u00c1gua Quente e Bonsucesso, anunciadas pelo Prefeito Vinicius Claussen. Avaliamos como podemos ajudar ainda mais a cidade de Teres\u00f3polis, que \u00e9 polo no atendimento em oncologia e cirurgia vascular e possui in\u00fameros prestadores de servi\u00e7os de sa\u00fade\u201d, assinalou o secret\u00e1rio de Estado de Sa\u00fade, Dr. Luizinho.<\/p>\n\n\n\n<p><strong><em>Fotos: Bruno Nepomuceno<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em breve Teres\u00f3polis vai ganhar mais duas bases do SAMU &#8211;&nbsp;Servi\u00e7o de Atendimento M\u00f3vel de<\/p>\n","protected":false},"author":2,"featured_media":59108,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-59107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=59107"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59107\/revisions"}],"predecessor-version":[{"id":59109,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59107\/revisions\/59109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/59108"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=59107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=59107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=59107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}