{"id":59147,"date":"2023-05-11T05:00:00","date_gmt":"2023-05-11T08:00:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=59147"},"modified":"2023-05-10T17:37:46","modified_gmt":"2023-05-10T20:37:46","slug":"cadastro-para-mutiroes-de-castracao-de-caes-e-gatos-ja-tem-data-para-ser-liberado","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/05\/11\/cadastro-para-mutiroes-de-castracao-de-caes-e-gatos-ja-tem-data-para-ser-liberado\/","title":{"rendered":"Cadastro para mutir\u00f5es de castra\u00e7\u00e3o de c\u00e3es e gatos j\u00e1 tem data para ser liberado"},"content":{"rendered":"\n<p>Os dois primeiros mutir\u00f5es de castra\u00e7\u00e3o de 2023 j\u00e1 tem data marcada, em Petr\u00f3polis. O primeiro ser\u00e1 realizado entre os dias 24 e 30 de julho, na regi\u00e3o do Itamarati e de 1 a 9 de agosto, no Centro. Os cadastros, no entanto, devem ser feitos com anteced\u00eancia e, por isso, equipes da Coordenadoria de Vigil\u00e2ncia Ambiental prepararam um calend\u00e1rio e estar\u00e3o recebendo os tutores e respons\u00e1veis pelos animais nos PSFs, UBS e outras pontos dentro da regi\u00e3o contemplada em cada uma das a\u00e7\u00f5es.<\/p>\n\n\n\n<p>O objetivo \u00e9 realizar quatro mutir\u00f5es entre os meses de julho e dezembro deste ano, atendendo cerca de quatro mil c\u00e3es e gatos. A iniciativa \u00e9 importante porque, segundo o secret\u00e1rio de Sa\u00fade, Marcus Curvelo, contribui tanto para o controle das zoonoses, que s\u00e3o doen\u00e7as transmitidas aos seres humanos, quanto para a sa\u00fade e bem estar dos animais. \u201cAl\u00e9m disso, a castra\u00e7\u00e3o tamb\u00e9m \u00e9 a forma mais eficaz para o controle populacional de animais\u201d, adianta Curvelo.<\/p>\n\n\n\n<p>Para as inscri\u00e7\u00f5es, que v\u00e3o acontecer de 9h \u00e0s 16h, os tutores e respons\u00e1veis dever\u00e3o apresentar carteira de identidade, CPF e comprovante de resid\u00eancia. Confira o calend\u00e1rio para cadastramento para castra\u00e7\u00e3o.<\/p>\n\n\n\n<p>15\/05\/2023 \u2013 PSF Estrada da Saudade<br>PSF Boa Vista<br>PSF Machado Fagundes<br>PSF Nova Cascatinha<br>16\/05\/2023 \u2013 PSF Estrada da Saudade<br>UBS Itamarati<br>Igreja Menino Jesus de Praga \u2013 Rua Doutor Jo\u00e3o Glass Veiga, s\/n \u2013 Floresta<br>17\/05\/2023 \u2013 UBS Itamarati<br>18\/05\/2023 &#8211; UBS Itamarati<br>Largo da Provis\u00f3ria<br>Par\u00f3quia Sant\u2019Ana e S\u00e3o Joaquim &#8211; Rua Monsenhor Achilles de Melo, 1, Cascatinha.<br>19\/05\/2023 &#8211; Par\u00f3quia Sant\u2019Ana e S\u00e3o Joaquim &#8211; Rua Monsenhor Achilles de Melo, 1. Cascatinha,<br>Capela Ascen\u00e7\u00e3o do Senhor &#8211; Rua Luis Salom\u00e3o Viana, 128 &#8211; Samambaia<\/p>\n\n\n\n<p>29\/05\/2023 \u2013 PSF 24 de Maio<br>PSF Alto da Serra<br>UBS Morin<br>30\/05\/2023 &#8211; PSF Alto da Serra<br>UBS Morin<br>PSF Vila Felipe<br>31\/05\/2023 \u2013 PSF Alto da Serra<br>Sargento Boening \u2013 BNH (Sal\u00e3o de festas)<br>Sargento Boening \u2013 Estrada do Para\u00edso, 800 (Ponto Final do 419)<\/p>\n\n\n\n<p>01\/06\/2023 \u2013 Associa\u00e7\u00e3o de Moradores da Vila S\u00e3o Jos\u00e9 \u2013 Rua Paulino Afonso, sn<br>Associa\u00e7\u00e3o de Moradores da Comunidade Osvaldo Cruz<br>Associa\u00e7\u00e3o de Moradores da Ch\u00e1cara Flora \u2013 Rua Carmem Ponte Marcolino, 815.<br>02\/06\/2023 \u2013 PSF Caxamb\u00fa Santa Isabel<br>PSF Caxamb\u00fa Lusitano<br>Rua Waldemar Ferreira da Silva, 20. Caxamb\u00fa<\/p>\n\n\n\n<p>Foto: Ag\u00eancia Brasil\/Rovena Rosa <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os dois primeiros mutir\u00f5es de castra\u00e7\u00e3o de 2023 j\u00e1 tem data marcada, em Petr\u00f3polis. O<\/p>\n","protected":false},"author":2,"featured_media":59148,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-59147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=59147"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59147\/revisions"}],"predecessor-version":[{"id":59149,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59147\/revisions\/59149"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/59148"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=59147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=59147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=59147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}