{"id":59249,"date":"2023-05-12T13:57:06","date_gmt":"2023-05-12T16:57:06","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=59249"},"modified":"2023-05-12T13:57:06","modified_gmt":"2023-05-12T16:57:06","slug":"governo-libera-r-4-bi-para-ampliar-vagas-de-tempo-integral-em-escolas","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/05\/12\/governo-libera-r-4-bi-para-ampliar-vagas-de-tempo-integral-em-escolas\/","title":{"rendered":"Governo libera R$ 4 bi para ampliar vagas de tempo integral em escolas"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Medida provis\u00f3ria foi assinada pelo presidente Lula nesta sexta-feira<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Andreia Verd\u00e9lio \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/203344.mp3\"><\/audio><\/h4>\n\n\n\n<p>O presidente Luiz In\u00e1cio Lula da Silva assinou, nesta sexta-feira (12), a Medida Provis\u00f3ria que cria o Programa Escolas de Tempo Integral. Com investimento de R$ 4 bilh\u00f5es, o governo quer ampliar em 1 milh\u00e3o as vagas de tempo integral nas escolas de educa\u00e7\u00e3o b\u00e1sica do pa\u00eds.&nbsp;<\/p>\n\n\n\n<p>Os recursos ser\u00e3o repassados para estados e munic\u00edpios para que possam expandir as matr\u00edculas em suas redes de ensino. A a\u00e7\u00e3o \u00e9 destinada a todos os entes federados, que dever\u00e3o fazer a ades\u00e3o e pactuar metas junto ao Minist\u00e9rio da Educa\u00e7\u00e3o (MEC).&nbsp;<\/p>\n\n\n\n<p>\u201cN\u00e3o existe na hist\u00f3ria nenhum pa\u00eds que conseguiu se desenvolver sem investir na educa\u00e7\u00e3o\u201d, disse Lula, destacando a import\u00e2ncia da qualifica\u00e7\u00e3o da popula\u00e7\u00e3o para o desenvolvimento econ\u00f4mico do pa\u00eds. \u201cPara que daqui a alguns anos esse pa\u00eds n\u00e3o deva nada a ningu\u00e9m na qualidade da educa\u00e7\u00e3o do nosso povo\u201d, acrescentou.&nbsp;<\/p>\n\n\n\n<p>O an\u00fancio ocorreu no Centro de Eventos do Cear\u00e1, em Fortaleza. Antes, Lula visitou a Escola de Ensino M\u00e9dio em Tempo Integral Johnson, tamb\u00e9m na capital cearense. As escolas em tempo integral s\u00e3o aquelas cuja jornada escolar \u00e9 igual ou superior a sete horas di\u00e1rias ou 35 horas semanais.&nbsp;<\/p>\n\n\n\n<p>Na primeira etapa do programa, o MEC vai estabelecer, junto a estados e munic\u00edpios, as metas de matr\u00edculas em tempo integral. Os recursos ser\u00e3o transferidos levando em conta as matr\u00edculas pactuadas, o valor do fomento e crit\u00e9rios de equidade.&nbsp;<\/p>\n\n\n\n<p>Durante o evento, o ministro da Educa\u00e7\u00e3o, Camilo Santana, anunciou ainda que o Banco de Desenvolvimento da Am\u00e9rica Latina (CAF) vai abrir uma linha de cr\u00e9dito e disponibilizar R$ 2,5 bilh\u00f5es para que estados e munic\u00edpios construam novas escolas no Brasil. Segundo ele, o Banco Nacional de Desenvolvimento Econ\u00f4mico e Social (BNDES) tamb\u00e9m colocar\u00e1 recursos a disposi\u00e7\u00e3o de governadores e prefeitos para o mesmo fim.&nbsp;<\/p>\n\n\n\n<p>\u201cEscola em tempo integral n\u00e3o \u00e9 s\u00f3 aumentar o tempo, \u00e9 acolher os alunos, \u00e9 dar oportunidade, \u00e9 valorizar o professor e integrar a comunidade\u201d, disse Santana.&nbsp;<\/p>\n\n\n\n<p>Nas etapas seguintes do Programa Escolas de Tempo Integral, o MEC dever\u00e1 implementar estrat\u00e9gias de assist\u00eancia t\u00e9cnica junto \u00e0s redes de ensino para a ado\u00e7\u00e3o do tempo integral, com foco para a redu\u00e7\u00e3o das desigualdades. Est\u00e3o previstas a\u00e7\u00f5es para forma\u00e7\u00e3o de educadores, orienta\u00e7\u00f5es curriculares, fomento a projetos inovadores, est\u00edmulo a arranjos intersetoriais para preven\u00e7\u00e3o e prote\u00e7\u00e3o social, melhoria de infraestrutura, al\u00e9m da cria\u00e7\u00e3o de indicadores de avalia\u00e7\u00e3o e sistema de avalia\u00e7\u00e3o continuada.&nbsp;<\/p>\n\n\n\n<p>O Programa Escolas de Tempo Integral busca viabilizar a meta 6 do Plano Nacional de Educa\u00e7\u00e3o (PNE), que estabelece a oferta de \u201ceduca\u00e7\u00e3o em tempo integral em, no m\u00ednimo, 50% das escolas p\u00fablicas, de forma a atender, pelo menos, 25% dos estudantes da educa\u00e7\u00e3o b\u00e1sica\u201d at\u00e9 2024. \u201cO Relat\u00f3rio do 4\u00ba Ciclo de Monitoramento das Metas do PNE 2022 mostra que o percentual de matr\u00edculas em tempo integral na rede p\u00fablica brasileira caiu de 17,6%, em 2014, para 15,1%, em 2021\u201d, explicou a Presid\u00eancia.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Dia das M\u00e3es&nbsp;<\/h2>\n\n\n\n<p>Durante seu discurso, Lula lembrou ainda que o pr\u00f3ximo domingo (14) \u00e9 Dia das M\u00e3es no Brasil. \u201cN\u00e3o existe nada mais valoroso na humanidade que uma m\u00e3e\u201d, disse.&nbsp;<\/p>\n\n\n\n<p>Por isso, para o presidente, \u00e9 importante que as pessoas tenham gestos valorosos para as m\u00e3es. \u201cN\u00e3o precisa dar presente, se n\u00e3o tiver dinheiro n\u00e3o fa\u00e7a sacrif\u00edcio, d\u00ea um beijo na testa da sua m\u00e3e e agrade\u00e7a por ela estar viva. \u00c9 importante voltarmos a ser carinhosos porque o Brasil est\u00e1 deixando de ser o pa\u00eds do \u00f3dio\u201d, disse Lula.&nbsp;<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Maria Claudia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Medida provis\u00f3ria foi assinada pelo presidente Lula nesta sexta-feira Por Andreia Verd\u00e9lio \u2013 Rep\u00f3rter da<\/p>\n","protected":false},"author":2,"featured_media":59250,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-59249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=59249"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59249\/revisions"}],"predecessor-version":[{"id":59251,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/59249\/revisions\/59251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/59250"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=59249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=59249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=59249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}