{"id":61202,"date":"2023-06-09T12:27:48","date_gmt":"2023-06-09T15:27:48","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61202"},"modified":"2023-06-09T12:46:06","modified_gmt":"2023-06-09T15:46:06","slug":"incendio-em-automoveis-deixa-transito-no-quitandinha-em-meia-pista","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/09\/incendio-em-automoveis-deixa-transito-no-quitandinha-em-meia-pista\/","title":{"rendered":"Inc\u00eandio em autom\u00f3veis deixa tr\u00e2nsito no Quitandinha em meia pista"},"content":{"rendered":"\n<p>Um inc\u00eandio em autom\u00f3veis , estacionados no p\u00e1tio do Hiper Bramil Quitandinha, deixa o tr\u00e2nsito em meia pista, com o fluxo sendo liberado no sistema pare e siga.<\/p>\n\n\n\n<p>Equipes do Corpo de Bombeiros est\u00e3o no local atendendo a ocorr\u00eancia e a CPTrans auxilia aos motoristas que passam pelo local.<\/p>\n\n\n\n<p>A Petro Ita informou que, todas as linhas de \u00f4nibus que passam nas imedia\u00e7\u00f5es das ruas General Rondon e Coronel Veiga, est\u00e3o sofrendo atrasos na opera\u00e7\u00e3o, ap\u00f3s o registro de um inc\u00eandio no p\u00e1tio de um supermercado localizado na regi\u00e3o. Neste momento, pelo menos, 25 linhas de \u00f4nibus est\u00e3o retidas no tr\u00e2nsito.<\/p>\n\n\n\n<p>De acordo com a assessoria do Bramil Supermercados, um carro pegou fogo e as chamas atingiram o ve\u00edculo que estava estacionado ao lado. Funcion\u00e1rios da loja agiram no combate \u00e0s chamas, at\u00e9 a chegada do Corpo de Bombeiros. Ningu\u00e9m ficou ferido. Parte da fachada da loja sofreu danos. A per\u00edcia ser\u00e1 realizada no local, e o caso registrado na 105\u00aa delegacia de pol\u00edcia.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Foto: Larissa Martins<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um inc\u00eandio em autom\u00f3veis , estacionados no p\u00e1tio do Hiper Bramil Quitandinha, deixa o tr\u00e2nsito<\/p>\n","protected":false},"author":2,"featured_media":61203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-61202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61202"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61202\/revisions"}],"predecessor-version":[{"id":61212,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61202\/revisions\/61212"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/61203"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}