{"id":61275,"date":"2023-06-10T11:56:39","date_gmt":"2023-06-10T14:56:39","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61275"},"modified":"2023-06-10T11:56:40","modified_gmt":"2023-06-10T14:56:40","slug":"laginha-e-vera-cruz-disputam-final-do-campeonato-municipal-de-futebol-sub-20-neste-sabado-10","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/10\/laginha-e-vera-cruz-disputam-final-do-campeonato-municipal-de-futebol-sub-20-neste-sabado-10\/","title":{"rendered":"Laginha e Vera Cruz disputam final do Campeonato Municipal de Futebol Sub-20 neste s\u00e1bado (10)"},"content":{"rendered":"\n<p>No \u00faltimo fim de semana, foram disputadas as semifinais do Campeonato Municipal de Futebol de Campo Sub-20 em Petr\u00f3polis. Ap\u00f3s as disputas, Laginha e Vera Cruz garantiram a vaga na decis\u00e3o que ser\u00e1 disputada neste s\u00e1bado (10). O torneio \u00e9 realizado pela Liga Petropolitana de Desportos (LPD).<\/p>\n\n\n\n<p>O primeiro duelo semifinal foi realizado entre Laginha e Cascatinha, na casa do Laginha. Aos 22 minutos da primeira etapa, a equipe da casa saiu na frente e a primeira etapa terminou em 1 a 0. No segundo tempo, o Laginha ampliou o placar e, mesmo com o Cascatinha buscando a rea\u00e7\u00e3o, conseguiu marcar mais gols, vencendo por 6 a 2. O destaque foi o atleta William Tavares, que fez 3 gols na partida e \u00e9 o artilheiro do campeonato, com 7 gols.<\/p>\n\n\n\n<p>A outra semifinal foi entre Vera Cruz e Carangola, no Est\u00e1dio 7 de Setembro, casa do Vera. O time mandante chegou a abrir 2 a 0 no placar, mas viu o Carangola reagir na partida e buscar o empate. Com a partida empatada, o jogo foi para a decis\u00e3o por p\u00eanaltis e o Vera Cruz levou a melhor, ganhando de 4 a 3.<\/p>\n\n\n\n<p>A grande final ir\u00e1 acontecer no s\u00e1bado, no Est\u00e1dio Jos\u00e9 Cresc\u00eancio da Costa, casa do Laginha, por ter a melhor campanha no campeonato. A partida ser\u00e1 \u00e0s 15h. Se houver empate no tempo regulamentar, o campe\u00e3o ser\u00e1 decidido nos p\u00eanaltis.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo fim de semana, foram disputadas as semifinais do Campeonato Municipal de Futebol de<\/p>\n","protected":false},"author":2,"featured_media":61276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-61275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61275"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61275\/revisions"}],"predecessor-version":[{"id":61277,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61275\/revisions\/61277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/61276"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}