{"id":61375,"date":"2023-06-12T12:00:22","date_gmt":"2023-06-12T15:00:22","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61375"},"modified":"2023-06-12T12:00:23","modified_gmt":"2023-06-12T15:00:23","slug":"junho-vermelho-nova-friburgo-realiza-campanha-de-doacao-de-sangue","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/12\/junho-vermelho-nova-friburgo-realiza-campanha-de-doacao-de-sangue\/","title":{"rendered":"Junho Vermelho: Nova Friburgo realiza campanha de doa\u00e7\u00e3o de sangue"},"content":{"rendered":"\n<p>Esse m\u00eas \u00e9 dedicado \u00e0 campanha de doa\u00e7\u00e3o de sangue e, justamente por isso, \u00e9 denominado de \u2018\u2019Junho Vermelho\u2019\u2019. Em Nova Friburgo, a Prefeitura possui um Hemocentro Regional, que atende ao munic\u00edpio e mais 13 cidades vizinhas, al\u00e9m de prestar apoio \u00e0 rede particular.&nbsp;<\/p>\n\n\n\n<p>A unidade, que fica ao lado do Hospital Municipal Raul Sert\u00e3, funciona das 8h \u00e0s 17h30. Para doar n\u00e3o \u00e9 preciso muito! Basta ter entre 16 e 60 anos &#8211;&nbsp;sendo que menores de idade devem estar acompanhados de um respons\u00e1vel -, pesar mais de 50 quilos e estar bem de sa\u00fade. \u00c9 preciso estar hidratado e ter se alimentado com comidas leves, evitando derivados de leite ou itens gordurosos.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o pode doar sangue quem possui ou j\u00e1 teve alguma doen\u00e7a&nbsp;como, por exemplo, hepatite, mal\u00e1ria, AIDS, doen\u00e7a de chagas e mal de Parkinson. Tamb\u00e9m n\u00e3o pode doar sangue quem \u00e9 usu\u00e1rio de drogas il\u00edcitas injet\u00e1veis.<\/p>\n\n\n\n<p>H\u00e1 alguns fatores que impossibilitam, temporariamente, a doa\u00e7\u00e3o, como: estar gr\u00e1vida ou amamentando, ter sofrido aborto ou ter tido o parto, ter feito tatuagem em menos de 12 meses, ter realizado endoscopia ou colonoscopia em menos de seis meses e ter tido gripe ou covid-19 em menos de 15 dias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esse m\u00eas \u00e9 dedicado \u00e0 campanha de doa\u00e7\u00e3o de sangue e, justamente por isso, \u00e9<\/p>\n","protected":false},"author":2,"featured_media":16017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61375","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61375"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61375\/revisions"}],"predecessor-version":[{"id":61376,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61375\/revisions\/61376"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/16017"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}