{"id":61477,"date":"2023-06-13T17:36:10","date_gmt":"2023-06-13T20:36:10","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61477"},"modified":"2023-06-13T17:36:21","modified_gmt":"2023-06-13T20:36:21","slug":"comissoes-especiais-da-camara-municipal-ja-tem-integrantes","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/13\/comissoes-especiais-da-camara-municipal-ja-tem-integrantes\/","title":{"rendered":"Comiss\u00f5es especiais da C\u00e2mara Municipal j\u00e1 tem integrantes"},"content":{"rendered":"\n<p>As comiss\u00f5es especiais criadas pela C\u00e2mara Municipal para acompanhar a situa\u00e7\u00e3o do transporte p\u00fablico e inclus\u00e3o nas escolas j\u00e1 contam com integrantes. Os nomes foram divulgados ao longo das \u00faltimas semanas e os trabalhos dos grupos devem come\u00e7ar em breve.<\/p>\n\n\n\n<p>Em rela\u00e7\u00e3o ao transporte p\u00fablico, a comiss\u00e3o vai acompanhar os desdobramentos do inc\u00eandio na garagem das empresas Petro Ita e Cascatinha. Ser\u00e1 presidida por L\u00e9o Fran\u00e7a (PSB) e contar\u00e1 Gil Magno (DC), Mauro Peralta (PRTB), Julia Casamasso (PSOL) e Marcelo Lessa (SD).<\/p>\n\n\n\n<p>Esta comiss\u00e3o estar\u00e1 em vigor por 180 dias e deve acompanhar as investiga\u00e7\u00f5es, al\u00e9m da situa\u00e7\u00e3o dos coletivos que sobraram. O inc\u00eandio no dia 9 de maio destruiu 74 \u00f4nibus, dos quais 48 estavam em uso, segundo as via\u00e7\u00f5es.<\/p>\n\n\n\n<p>J\u00e1 a comiss\u00e3o da inclus\u00e3o escolar, deve contar com a participa\u00e7\u00e3o de Eduardo do Blog (Rep) e L\u00e9o Fran\u00e7a (PSB). A vereadora Gilda Beatriz (PSD) vai assumir a presid\u00eancia do grupo.<\/p>\n\n\n\n<p>Em maio, a vereadora tentou uma audi\u00eancia p\u00fablica para debater a quest\u00e3o, mas a prefeitura n\u00e3o enviou representantes. H\u00e1 uma lei federal que determina um sistema educacional inclusivo em todos os n\u00edveis \u00e0s pessoas com necessidades educacionais especiais.<\/p>\n\n\n\n<p>\u201cN\u00f3s temos recebido muitas den\u00fancias de pais, com rela\u00e7\u00e3o \u00e0 falta do mediador escolar para acompanhar as crian\u00e7as com defici\u00eancia nas escolas municipais. A educa\u00e7\u00e3o inclusiva \u00e9 um direito e n\u00e3o um favor\u201d, disse a vereadora no an\u00fancio da audi\u00eancia.<\/p>\n\n\n\n<p>Por Wellington Daniel\/Foto: divulga\u00e7\u00e3o <br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>As comiss\u00f5es especiais criadas pela C\u00e2mara Municipal para acompanhar a situa\u00e7\u00e3o do transporte p\u00fablico e<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-61477","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61477"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61477\/revisions"}],"predecessor-version":[{"id":61479,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61477\/revisions\/61479"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}