{"id":61547,"date":"2023-06-14T17:24:49","date_gmt":"2023-06-14T20:24:49","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61547"},"modified":"2023-06-14T17:24:50","modified_gmt":"2023-06-14T20:24:50","slug":"senadores-da-comissao-yanomami-entram-em-acordo-e-aprovam-relatorio","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/14\/senadores-da-comissao-yanomami-entram-em-acordo-e-aprovam-relatorio\/","title":{"rendered":"Senadores da Comiss\u00e3o Yanomami entram em acordo e aprovam relat\u00f3rio"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Relator acatou sugest\u00f5es de quatro membros e incluiu na vers\u00e3o final<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"> Lucas Pordeus Le\u00f3n &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/204917.mp3\"><\/audio><\/h4>\n\n\n\n<p>Ap\u00f3s quatro senadoras apresentarem voto em separado por n\u00e3o concordarem com o relat\u00f3rio final da Comiss\u00e3o Tempor\u00e1ria Externa do Senado que apurou a situa\u00e7\u00e3o dos yanamomi e dos garimpeiros, em Roraima, os parlamentares entraram em acordo e aprovaram&nbsp;nesta quarta-feira (14), por unanimidade, o texto final do relator, o senador Dr. Hiran (PP-RR).&nbsp;<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1538228&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1538228&amp;o=node\"><\/p>\n\n\n\n<p>Instalada em&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2023-03\/comissao-para-ac-situacao-yanomami-adia-votacao-de-plano-de-trabalho\" target=\"_blank\" rel=\"noreferrer noopener\">15 de fevereiro<\/a>&nbsp;deste ano, a comiss\u00e3o teve como objetivo acompanhar de perto&nbsp;a situa\u00e7\u00e3o dos yanomami e a sa\u00edda dos garimpeiros do territ\u00f3rio ind\u00edgena. Ao iniciar a sess\u00e3o para votar o relat\u00f3rio final do trabalho da comiss\u00e3o, a senadora Eliziane Gama (PSD-MA) apontou problemas no texto.&nbsp;<\/p>\n\n\n\n<p>\u201cN\u00e3o abordou, de forma aprofundada, a crise humanit\u00e1ria na Terra Yanomami. A preocupa\u00e7\u00e3o principal deveria ser a prote\u00e7\u00e3o dos yanomami, que foram v\u00edtimas de uma invas\u00e3o consentida e estimulada ao longo dos \u00faltimos anos, mas o relat\u00f3rio acabou desviando o foco para defender a legaliza\u00e7\u00e3o da minera\u00e7\u00e3o em terras ind\u00edgenas e o Linh\u00e3o de Tucuru\u00ed\u201d, afirmou a senadora maranhense. &nbsp;<\/p>\n\n\n\n<p>O Linh\u00e3o do Tucuru\u00ed \u00e9 um projeto que visa construir linhas de transmiss\u00e3o de energia para ligar o estado de Roraima ao restante do sistema el\u00e9trico brasileiro. A obra \u00e9 pol\u00eamica porque atravessaria territ\u00f3rios ind\u00edgenas.&nbsp;<\/p>\n\n\n\n<p>A senadora Eliziane acrescentou que o relator reconheceu a facilidade para comercializar o ouro ilegal, mas que n\u00e3o apontou solu\u00e7\u00f5es para o problema. \u201cCurioso que n\u00e3o se preocupe com isso, enquanto d\u00e1 mais aten\u00e7\u00e3o aos traficantes que atuam na Venezuela\u201d, destacou. &nbsp;<\/p>\n\n\n\n<p>Como a metade da comiss\u00e3o, formada por oito senadores, apoiou o voto em separado, o impasse poderia impedir a aprova\u00e7\u00e3o do relat\u00f3rio final. O relator Dr. Hiran se justificou. \u201cEu tive o cuidado de elaborar um relat\u00f3rio eminentemente t\u00e9cnico e afastar desse relat\u00f3rio vieses ideol\u00f3gicos. Aquilo que eu coloquei no relat\u00f3rio foi fruto daquelas oitivas que foram consignadas aqui nas audi\u00eancias p\u00fablicas que n\u00f3s tivemos. Eu considerei todos os posicionamentos\u201d, afirmou. &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Acordo&nbsp;&nbsp;<\/h2>\n\n\n\n<p>Ap\u00f3s as cr\u00edticas da senadora, a sess\u00e3o foi suspensa por alguns minutos. Em seguida, os senadores chegaram a um acordo. O relator se comprometeu a fazer altera\u00e7\u00f5es no texto final e incluir no relat\u00f3rio a recomenda\u00e7\u00e3o para o Congresso Nacional aprovar dois projetos de lei. &nbsp;<\/p>\n\n\n\n<p>O primeiro deles estabelece procedimentos para certifica\u00e7\u00e3o do ouro produzido no pa\u00eds, com rastreamento da produ\u00e7\u00e3o para evitar o com\u00e9rcio ilegal do min\u00e9rio. O segundo projeto aceito como sugest\u00e3o pelo relator combate os crimes de discrimina\u00e7\u00e3o, preconceito e intoler\u00e2ncia contra povos ind\u00edgenas, alterando a Lei n\u00ba 7.716 de 1989, que define os crimes resultantes de preconceito de ra\u00e7a ou de cor. &nbsp;<\/p>\n\n\n\n<p>A mudan\u00e7a foi comemorada pelas senadoras que assinaram o voto em separado que, al\u00e9m da Eliziane, foram as senadoras Zenaide Maia (PSD-RN), Leila Barros (PDT-DF) e Tereza Leit\u00e3o (PT-PE). Os demais membros da Comiss\u00e3o s\u00e3o os senadores Astronauta Marcos Pontes (PL-SP), Mecias de Jesus (Republicanos-RR), Chico Rodrigues (PSB-RR), que&nbsp;preside&nbsp;do colegiado, al\u00e9m do senador Dr. Hiran. &nbsp;<\/p>\n\n\n\n<p>Com o acordo, o voto em separado foi retirado da pauta. Segundo Eliziane, o acordo foi uma \u201cdemonstra\u00e7\u00e3o do exerc\u00edcio da democracia e do di\u00e1logo. \u00c0s vezes a gente n\u00e3o consegue o ideal, mas consegue aquilo que \u00e9 poss\u00edvel\u201d. A parlamentar ainda acrescentou que o relator Hiran aceitou cerca de 90% das sugest\u00f5es das senadoras. &nbsp;<\/p>\n\n\n\n<p>Ao final da sess\u00e3o, o relator Dr. Hiran afirmou que o texto final buscou criar proposi\u00e7\u00f5es positivas para proteger as comunidades ind\u00edgenas, com mais sa\u00fade e assist\u00eancia alimentar, mas \u201ctamb\u00e9m propusemos algumas sugest\u00f5es ao poder Executivo para que possamos criar um ambiente de desenvolvimento no estado de Roraima que possa abarcar essas pessoas que digo que s\u00e3o os oper\u00e1rios do garimpo, n\u00e3o o crime organizado, mas aqueles oper\u00e1rios, aquelas pessoas humildes que v\u00e3o pra l\u00e1, que perderam seus postos de emprego nas cidades, mas que elas possam ser inseridas no mercado de trabalho fora dessa atividade ilegal\u201d, finalizou. &nbsp;<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Aline Leal<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Relator acatou sugest\u00f5es de quatro membros e incluiu na vers\u00e3o final Lucas Pordeus Le\u00f3n &#8211;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61547","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61547"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61547\/revisions"}],"predecessor-version":[{"id":61549,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61547\/revisions\/61549"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}