{"id":61556,"date":"2023-06-14T17:29:51","date_gmt":"2023-06-14T20:29:51","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61556"},"modified":"2023-06-14T17:29:52","modified_gmt":"2023-06-14T20:29:52","slug":"hoje-14-e-o-dia-mundial-do-doador-de-sangue-banco-do-santa-teresa-esta-com-estoque-55-abaixo-do-ideal","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/14\/hoje-14-e-o-dia-mundial-do-doador-de-sangue-banco-do-santa-teresa-esta-com-estoque-55-abaixo-do-ideal\/","title":{"rendered":"Hoje (14) \u00e9 o Dia Mundial do Doador de Sangue: banco do Santa Teresa est\u00e1 com estoque 55% abaixo do ideal"},"content":{"rendered":"\n<p>Nesta quarta-feira, 14 de junho, comemora-se o Dia Mundial do Doador de Sangue. Essa data foi institu\u00edda pela Organiza\u00e7\u00e3o Mundial da Sa\u00fade, em 2004, em homenagem ao nascimento de Karl Landsteiner, imunologista austr\u00edaco que descobriu o fator RH e as v\u00e1rias diferen\u00e7as entre os tipos sangu\u00edneos. Para celebrar a data e refor\u00e7ar a import\u00e2ncia das doa\u00e7\u00f5es, o Banco de Sangue do Santa Teresa est\u00e1 realizando a campanha \u201cA vida precisa de voc\u00ea \u2013 tome a iniciativa e doe sangue neste Junho Vermelho\u201d.<\/p>\n\n\n\n<p>At\u00e9 esta quinta-feira (15), ou enquanto os estoques durarem, os doadores est\u00e3o sendo homenageados com pequenos brindes, como uma forma de reconhecimento ao dia e \u00e0 pr\u00e1tica solid\u00e1ria. As a\u00e7\u00f5es tamb\u00e9m alertam para a necessidade de reabastecimento dos estoques. Isto porque eles est\u00e3o 55% abaixo do n\u00edvel ideal. \u201cA situa\u00e7\u00e3o est\u00e1 muito ruim para os estoques da nossa cidade. Hoje estamos colhendo menos da metade do que a gente precisa colher por dia para garantir a seguran\u00e7a das pessoas da nossa cidade. A gente precisa colher por dia de 55 a 60 bolsas de sangue, para que a gente fa\u00e7a um atendimento com seguran\u00e7a. Hoje a gente est\u00e1 conseguindo recolher de 28 a 30 bolsas de sangue por dia\u201d, disse a coordenadora t\u00e9cnica do Banco de Sangue do Santa Teresa, Marcela Colonese.<\/p>\n\n\n\n<p>Os n\u00fameros podem se acentuar ainda mais nos pr\u00f3ximos dias. Isto porque, com a chegada do inverno e as temperaturas mais baixas, h\u00e1 uma queda acentuada no n\u00famero de doadores. Neste ano, o frio chegou um pouco mais cedo a Petr\u00f3polis junto das doen\u00e7as respirat\u00f3rias t\u00edpicas da esta\u00e7\u00e3o. \u201cA gente pede que as pessoas se sensibilizem e venham doar. Venham realizar essa boa a\u00e7\u00e3o para que a gente garanta a seguran\u00e7a dos estoques\u201d, disse a coordenadora.<\/p>\n\n\n\n<p>A Organiza\u00e7\u00e3o Mundial de Sa\u00fade (OMS) recomenda que o percentual ideal de doadores, para um pa\u00eds, esteja entre 3,5% e 5% de sua popula\u00e7\u00e3o. No Brasil, esse n\u00famero \u00e9 preocupante, pois n\u00e3o chega a 2%, segundo o Minist\u00e9rio da Sa\u00fade.<\/p>\n\n\n\n<p>O GSH Banco de Sangue Santa Teresa atende a tr\u00eas hospitais da regi\u00e3o, fornecendo bolsas de sangue aos pacientes que est\u00e3o internados e precisam de transfus\u00e3o para se recuperarem. A institui\u00e7\u00e3o funciona diariamente, das 7h \u00e0s 18h, inclusive aos domingos e feriados, na Rua Doutor Paulo Herv\u00ea, 1130, no Bingen, ao lado do banco Bradesco. Para facilitar o acesso, a unidade disponibiliza transporte gratuito para grupos de 4 ou 15 pessoas. O transporte deve ser acionado pelo whatsapp: (24) 99269-4355.<\/p>\n\n\n\n<p>por Raphaela Cordeiro\/Foto: divulga\u00e7\u00e3o <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nesta quarta-feira, 14 de junho, comemora-se o Dia Mundial do Doador de Sangue. Essa data<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-61556","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61556"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61556\/revisions"}],"predecessor-version":[{"id":61558,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61556\/revisions\/61558"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}