{"id":61665,"date":"2023-06-16T12:56:18","date_gmt":"2023-06-16T15:56:18","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61665"},"modified":"2023-06-16T12:56:19","modified_gmt":"2023-06-16T15:56:19","slug":"municipios-recebem-r-89-milhoes-para-apoio-a-imigrantes-e-refugiados","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/16\/municipios-recebem-r-89-milhoes-para-apoio-a-imigrantes-e-refugiados\/","title":{"rendered":"Munic\u00edpios recebem R$ 8,9 milh\u00f5es para apoio a imigrantes e refugiados"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cidades beneficiadas devem apresentar plano de a\u00e7\u00e3o em 30 dias<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Fabiola Sinimbu &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205023.mp3\"><\/audio><\/h4>\n\n\n\n<p>O Minist\u00e9rio do Desenvolvimento e Assist\u00eancia Social, Fam\u00edlia e Combate \u00e0 Fome&nbsp;<a href=\"https:\/\/in.gov.br\/web\/dou\/-\/portaria-mds-n-893-de-14-de-junho-de-2023-490097376\" target=\"_blank\" rel=\"noreferrer noopener\">publicou, nesta sexta-feira (16), portaria<\/a>&nbsp;que libera R$ 8.971.200 para a\u00e7\u00f5es socioassistenciais aos imigrantes e refugiados. Ao todo, 15 munic\u00edpios, de dez estados, receber\u00e3o repasse emergencial de recursos federais para atendimento de 3.738 pessoas interiorizadas pelos programas de acolhimento ou por demanda espont\u00e2nea.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1538585&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1538585&amp;o=node\"><\/p>\n\n\n\n<p>Segundo o Painel Interativo sobre Ref\u00fagio no Brasil, mantido pela Ag\u00eancia da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para Refugiados (Acnur), o Brasil tem atualmente 65.811 pessoas reconhecidas nessa condi\u00e7\u00e3o e pouco mais de 155 mil pedidos em an\u00e1lise.<\/p>\n\n\n\n<p>Os recursos do Fundo Nacional de Assist\u00eancia Social servir\u00e3o para seis meses de atendimento, ao longo deste ano, e foram distribu\u00eddos conforme o volume de pessoas que cada munic\u00edpio acolheu, ou acolher\u00e1. O objetivo \u00e9 custear o programa de trabalho e o atendimento das necessidades dos imigrantes e refugiados e suas fam\u00edlias, em situa\u00e7\u00e3o de vulnerabilidade e risco.<\/p>\n\n\n\n<p>De acordo com a portaria, cada munic\u00edpio dever\u00e1 apresentar um plano de a\u00e7\u00e3o no prazo de 30 dias, caso contr\u00e1rio, o recurso ser\u00e1 recolhido pela Uni\u00e3o. E a presta\u00e7\u00e3o de contas ser\u00e1 acompanhada e fiscalizada pelos conselhos de assist\u00eancia social das cidades.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/imagens.ebc.com.br\/Ry24d59pLs1qMMVd3V7H9Q-87tI=\/754x0\/smart\/https:\/\/agenciabrasil.ebc.com.br\/sites\/default\/files\/thumbnails\/image\/tabela_de_recursos_para_imigrantes.jpg?itok=TDRvEcod\" alt=\"Recursos por munic\u00edpio para a\u00e7\u00f5es socioassistenciais no acolhimento de imigrantes e refugiados. Fonte: Di\u00e1rio Oficial da Uni\u00e3o\" title=\"Di\u00e1rio Oficial da Uni\u00e3o\"\/><\/figure>\n\n\n\n<h6 class=\"wp-block-heading\">Recursos por munic\u00edpio para a\u00e7\u00f5es socioassistenciais no acolhimento de imigrantes e refugiados. Fonte: Di\u00e1rio Oficial da Uni\u00e3o<\/h6>\n\n\n\n<p><em>*Mat\u00e9ria alterada \u00e0s 12h02 para corre\u00e7\u00e3o dos valores dispon\u00edveis. No total, ser\u00e3o R$ 8,9 milh\u00f5es<\/em><\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Fernando Fraga<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cidades beneficiadas devem apresentar plano de a\u00e7\u00e3o em 30 dias Por Fabiola Sinimbu &#8211; Rep\u00f3rter<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61665","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61665"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61665\/revisions"}],"predecessor-version":[{"id":61667,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61665\/revisions\/61667"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}