{"id":61717,"date":"2023-06-17T12:22:17","date_gmt":"2023-06-17T15:22:17","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61717"},"modified":"2023-06-17T12:22:18","modified_gmt":"2023-06-17T15:22:18","slug":"prefeito-de-queimados-faz-reuniao-de-emergencia-com-o-comando-da-policia-militar","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/17\/prefeito-de-queimados-faz-reuniao-de-emergencia-com-o-comando-da-policia-militar\/","title":{"rendered":"Prefeito de Queimados faz reuni\u00e3o de emerg\u00eancia com o comando da Pol\u00edcia Militar"},"content":{"rendered":"\n<p>Com o objetivo de tra\u00e7ar estrat\u00e9gias para conter a onda de viol\u00eancia que alcan\u00e7ou a cidade de Queimados nos \u00faltimos dias, o prefeito Glauco Kaizer teve uma reuni\u00e3o de emerg\u00eancia com o Secret\u00e1rio de Estado da Pol\u00edcia Militar, Cel. Luiz Henrique Marinho. O encontro foi realizado nesta sexta-feira, no Quartel General da Pol\u00edcia Militar, no Centro.<\/p>\n\n\n\n<p>No encontro, o gestor fez alguns pedidos que ajudariam no refor\u00e7o da seguran\u00e7a. Glauco Kaizer destacou a necessidade do aumento no efetivo de policiais do 24\u00ba BPM, a reativa\u00e7\u00e3o de quatros cabinas e a parceria para implanta\u00e7\u00e3o do Sistema de Monitoramento de C\u00e2meras com reconhecimento facial.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/queimados-2-1024x576.jpeg\" alt=\"\" class=\"wp-image-61719\"\/><\/figure>\n\n\n\n<p>Em resposta, o Secret\u00e1rio disse ao gestor que a Pol\u00edcia Militar prepara um concurso onde ser\u00e3o aprovados 2 mil novos policiais e o 24\u00ba BPM ser\u00e1 um dos batalh\u00f5es refor\u00e7ados. O 24\u00ba BPM, que fica em Queimados, atualmente, atende cinco munic\u00edpios da Baixada Fluminense. Al\u00e9m de Queimados, o batalh\u00e3o cobre as cidades de Japeri, Paracambi, Serop\u00e9dica e Itagua\u00ed.<\/p>\n\n\n\n<p>O prefeito destacou a import\u00e2ncia do encontro: \u201cQuero agradecer ao Secret\u00e1rio e pela reuni\u00e3o produtiva. Falamos de estrat\u00e9gias de seguran\u00e7a que j\u00e1 est\u00e3o em andamento e as que ser\u00e3o colocadas em pr\u00e1tica. Essas a\u00e7\u00f5es s\u00e3o muito importantes para que tenhamos uma cidade mais segura\u201d, disse.<\/p>\n\n\n\n<p>Uma rede integrada de monitoramento de c\u00e2meras tamb\u00e9m foi destacada na reuni\u00e3o. A Prefeitura j\u00e1 trabalha para a implanta\u00e7\u00e3o de c\u00e2meras com reconhecimento facial na cidade e o secret\u00e1rio de Pol\u00edcia Militar destacou que a PM tamb\u00e9m j\u00e1 tem l um projeto no mesmo sentido. Nos pr\u00f3ximos dias o Governo do Estado pretende realizar a licita\u00e7\u00e3o para a compra dos equipamentos e o 24\u00ba BPM ser\u00e1 um dos primeiros a receber a tecnologia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de tra\u00e7ar estrat\u00e9gias para conter a onda de viol\u00eancia que alcan\u00e7ou a<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61717","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61717"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61717\/revisions"}],"predecessor-version":[{"id":61720,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61717\/revisions\/61720"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}