{"id":61733,"date":"2023-06-17T14:53:48","date_gmt":"2023-06-17T17:53:48","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61733"},"modified":"2023-06-17T14:54:58","modified_gmt":"2023-06-17T17:54:58","slug":"cptrans-emite-comunicado-sobre-a-rua-washington-luiz","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/17\/cptrans-emite-comunicado-sobre-a-rua-washington-luiz\/","title":{"rendered":"CPTrans emite comunicado sobre a Rua Washington Luiz"},"content":{"rendered":"\n<p><em>Imagens: Marlus Al\u00e9ssio<\/em><\/p>\n\n\n\n<p>A Rua Washington Luiz, no Centro de Petr\u00f3polis, est\u00e1 em meia pista para a retirada de um poste e restabelecimento da energia el\u00e9trica na regi\u00e3o, servi\u00e7os que est\u00e3o sendo executados pela Enel. <\/p>\n\n\n\n<p>Durante a madrugada, ap\u00f3s um acidente, um poste caiu interditando a via na altura da Esta\u00e7\u00e3o de Tratamento da \u00c1guas do Imperador.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/enel-1.png\" alt=\"\" class=\"wp-image-61735\"\/><\/figure>\n\n\n\n<p>Agentes de tr\u00e2nsito da CPTrans e guardas civis municipais est\u00e3o na regi\u00e3o, desde o ocorrido, orientando o tr\u00e2nsito., que at\u00e9 o momento est\u00e1 sendo desviado para o Valpara\u00edso.<\/p>\n\n\n\n<p>A via ser\u00e1 totalmente liberada ap\u00f3s a conclus\u00e3o dos reparos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/enel-2.png\" alt=\"\" class=\"wp-image-61736\"\/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Imagens: Marlus Al\u00e9ssio A Rua Washington Luiz, no Centro de Petr\u00f3polis, est\u00e1 em meia pista<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-61733","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61733"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61733\/revisions"}],"predecessor-version":[{"id":61739,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61733\/revisions\/61739"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}