{"id":61742,"date":"2023-06-17T15:50:23","date_gmt":"2023-06-17T18:50:23","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61742"},"modified":"2023-06-17T15:50:23","modified_gmt":"2023-06-17T18:50:23","slug":"grupo-ligado-ao-estado-islamico-deixa-ao-menos-41-mortos-em-ataque-a-escola-em-uganda","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/17\/grupo-ligado-ao-estado-islamico-deixa-ao-menos-41-mortos-em-ataque-a-escola-em-uganda\/","title":{"rendered":"Grupo ligado ao Estado Isl\u00e2mico deixa ao menos 41 mortos em ataque \u00e0 escola em Uganda"},"content":{"rendered":"\n<p><em>Ag\u00eancia Brasil<\/em><\/p>\n\n\n\n<p>Rebeldes armados atacaram uma escola no oeste de\u00a0Uganda. De acordo com as autoridades de Uganda, pelo menos 41 pessoas foram mortas, a maioria estudantes. Al\u00e9m disso, outras seis foram sequestradas. <\/p>\n\n\n\n<p>O porta-voz militar Felix Kulayigye informou \u00e0 imprensa que cerca de 20 membros do grupo rebelde das For\u00e7as Democr\u00e1ticas Aliadas (ADF), ligado ao\u00a0Estado Isl\u00e2mico, atacaram a escola secund\u00e1ria de Lhubirira na noite desta sexta-feira (16).<\/p>\n\n\n\n<p>A escola fica numa regi\u00e3o que faz fronteira de Uganda com o Congo, na cidade de Kasese, e educa crian\u00e7as entre 13 e 18 anos. Dos mortos, 39 eram estudantes e dois eram da comunidade local.<\/p>\n\n\n\n<p>Na manh\u00e3 deste s\u00e1bado, autoridades ainda tentavam debelar o inc\u00eandio e para os militares, mais cad\u00e1veres podem ser encontrados. Na hora do ataque havia 62 pessoas na escola.<\/p>\n\n\n\n<p>O porta-voz das opera\u00e7\u00f5es militares de Uganda na Rep\u00fablica Democr\u00e1tica do Congo, Major Bilal Katamba, anunciou que os militares est\u00e3o em persegui\u00e7\u00e3o aos suspeitos.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia Brasil Rebeldes armados atacaram uma escola no oeste de\u00a0Uganda. De acordo com as autoridades<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61742","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61742"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61742\/revisions"}],"predecessor-version":[{"id":61744,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61742\/revisions\/61744"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}