{"id":61769,"date":"2023-06-18T09:00:00","date_gmt":"2023-06-18T12:00:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61769"},"modified":"2023-06-17T19:28:34","modified_gmt":"2023-06-17T22:28:34","slug":"oficinas-de-teatro-e-producao-de-video-com-celular-fazem-parte-da-programacao-da-bauernfest","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/18\/oficinas-de-teatro-e-producao-de-video-com-celular-fazem-parte-da-programacao-da-bauernfest\/","title":{"rendered":"Oficinas de teatro e produ\u00e7\u00e3o de v\u00eddeo com celular fazem parte da programa\u00e7\u00e3o da Bauernfest"},"content":{"rendered":"\n<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para as oficinas de teatro e produ\u00e7\u00e3o de v\u00eddeo com celular, promovidas pela Prefeitura, por meio do Instituto Municipal de Cultura (IMC). As capacita\u00e7\u00f5es fazem parte da programa\u00e7\u00e3o da 34\u00aa Bauernfest \u2013 Festa do Colono Alem\u00e3o. As inscri\u00e7\u00f5es devem ser feitas pela internet e as oficinas s\u00e3o gratuitas.<\/p>\n\n\n\n<p>A inscri\u00e7\u00f5es para a oficina de produ\u00e7\u00e3o de v\u00eddeo com celular &#8211; &#8220;Bauernfest em Doc&#8221; \u2013 devem ser feitas pelo link: https:\/\/forms.gle\/6jqaizKp3zpa7UC26. S\u00e3o 15 vagas destinadas a estudantes do Ensino M\u00e9dio, de cursos regulares ou t\u00e9cnicos, que desejam aprimorar suas habilidades de contar hist\u00f3rias e aprender t\u00e9cnicas de produ\u00e7\u00e3o audiovisual.<\/p>\n\n\n\n<p>A oficina ter\u00e1 dura\u00e7\u00e3o de tr\u00eas dias \u2013 30\/6, 1\/7 e 2\/7 \u2013 das 10h \u00e0s 18h, na Sala de Cinema Humberto Mauro, no Centro de Cultura Raul de Leoni. Ao final da oficina, os participantes ter\u00e3o produzido seus pr\u00f3prios v\u00eddeos curtos, capturando a ess\u00eancia e a atmosfera \u00fanica da Bauernfest, a maior e mais tradicional festa da nossa cidade.<\/p>\n\n\n\n<p>Os interessados na oficina teatral a partir do expressionismo alem\u00e3o, devem se inscrever pelo link: https:\/\/forms.gle\/3vaFnCnV6vRXrJ9J8. Ser\u00e3o disponibilizadas 20 vagas para todos os p\u00fablicos, a partir dos 14 anos. As aulas acontecem nos dias 01 e 02 de julho, das 14h \u00e0s 18h, na Sala Guiomar Novaes, no Centro de Cultura Raul de Leoni.<\/p>\n\n\n\n<p>A oficina teatral a partir do expressionismo alem\u00e3o ir\u00e1 abranger exerc\u00edcios que estimulam o corpo, voz e mimesis corp\u00f3reas \u2013 t\u00e9cnica que consiste em criar cenas e personagens a partir da observa\u00e7\u00e3o de imagens, corpos e mat\u00e9rias.<\/p>\n\n\n\n<p>A 34\u00aa Bauernfest come\u00e7a no dia 23 de junho e vai at\u00e9 o dia nove de julho. A Festa do Colono Alem\u00e3o acontece no Pal\u00e1cio de Cristal e arredores. Toda a programa\u00e7\u00e3o \u00e9 gratuita.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para as oficinas de teatro e produ\u00e7\u00e3o de v\u00eddeo com celular,<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-61769","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61769"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61769\/revisions"}],"predecessor-version":[{"id":61771,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61769\/revisions\/61771"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}