{"id":61798,"date":"2023-06-18T09:30:00","date_gmt":"2023-06-18T12:30:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61798"},"modified":"2023-06-17T20:26:02","modified_gmt":"2023-06-17T23:26:02","slug":"seeduc-perto-leva-mais-de-50-servicos-para-jardim-gramacho-em-duque-de-caxias","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/18\/seeduc-perto-leva-mais-de-50-servicos-para-jardim-gramacho-em-duque-de-caxias\/","title":{"rendered":"Seeduc + Perto leva mais de 50 servi\u00e7os para Jardim Gramacho\u200b, em Duque de Caxias"},"content":{"rendered":"\n<p><em>Neste s\u00e1bado (17), a regi\u00e3o recebeu um mutir\u00e3o especial de atendimento que contou com a participa\u00e7\u00e3o de diversos \u00f3rg\u00e3os p\u00fablicos<\/em><\/p>\n\n\n\n<p>A Secretaria de Estado de Educa\u00e7\u00e3o se uniu, neste s\u00e1bado (17), a um mutir\u00e3o de servi\u00e7os para levar mais cidadania e dignidade para os moradores de Duque de Caxias, na Baixada Fluminense. A a\u00e7\u00e3o aconteceu no Col\u00e9gio Estadual Lara Villela, em Jardim Gramacho, e teve a participa\u00e7\u00e3o dos programas \u201cSeeduc + Perto\u201d, \u00a0\u201cRJ para Todos\u201d, \u00a0Justi\u00e7a Itinerante do Tribunal de Justi\u00e7a, al\u00e9m da presen\u00e7a de representantes do Detran, do Procon, da Defensoria P\u00fablica e do Minist\u00e9rio P\u00fablico do Rio de Janeiro.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/Seeduc-RJ-1-1-1-1024x682.jpeg\" alt=\"\" class=\"wp-image-61801\"\/><\/figure>\n\n\n\n<p>O Seeduc + Perto \u00e9 um programa da Secretaria de Estado de Educa\u00e7\u00e3o e, h\u00e1 um ano, percorre todas as regi\u00f5es do estado em uma van oferecendo mais de 50 servi\u00e7os para servidores e estudantes.<\/p>\n\n\n\n<p>&#8220;O objetivo desse programa \u00e9 aproximar a Secretaria de Educa\u00e7\u00e3o da comunidade escolar. Foi criado justamente para que servidores e alunos, consigam resolver qualquer tipo de demanda que tenham com a Seeduc-RJ, como, por exemplo, emiss\u00e3o de certificados, orienta\u00e7\u00f5es sobre as regras de aposentadoria e contratos tempor\u00e1rios, entre outros,&#8221; afirma a secret\u00e1ria de Estado de Educa\u00e7\u00e3o, Roberta Barreto, durante a participa\u00e7\u00e3o na a\u00e7\u00e3o, que levou centenas de cidad\u00e3os \u00e0 unidade escolar na Baixada.<\/p>\n\n\n\n<p>A secret\u00e1ria destacou ainda que a parceria com os mais diferentes \u00f3rg\u00e3os p\u00fablicos foi pensada a fim de levar mais cidadania e dignidade para a popula\u00e7\u00e3o.<\/p>\n\n\n\n<p>Durante a a\u00e7\u00e3o, moradores da regi\u00e3o que abrigou durante 34 anos o maior lix\u00e3o da Am\u00e9rica Latina tiveram a oportunidade, tamb\u00e9m, de resolver quest\u00f5es como corre\u00e7\u00e3o de erro em Certid\u00f5es de Nascimento, Casamento ou \u00d3bito, registro de filhos ap\u00f3s o prazo oficial, pedidos de pens\u00e3o aliment\u00edcia para filhos, balc\u00e3o de empregos, defesa do consumidor, agendamentos do Detran e aferi\u00e7\u00e3o de press\u00e3o, entre outros servi\u00e7os.<\/p>\n\n\n\n<p>A moradora de Caxias, Adriana Silva aproveitou o mutir\u00e3o para pedir a primeira via da identidade do filho e resolver o RioCard dele.<\/p>\n\n\n\n<p>&#8220;Consegui resolver tudo. A iniciativa foi muito boa. Trazer essa a\u00e7\u00e3o aqui para o col\u00e9gio ajudou muito a gente. Ficou mais perto de casa\u201d, disse ela.<\/p>\n\n\n\n<p><strong>Foto: Sandra Barros Divulga\u00e7\u00e3o\/ Seeduc-RJ<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neste s\u00e1bado (17), a regi\u00e3o recebeu um mutir\u00e3o especial de atendimento que contou com a<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61798","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61798"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61798\/revisions"}],"predecessor-version":[{"id":61802,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61798\/revisions\/61802"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}