{"id":61956,"date":"2023-06-20T08:16:44","date_gmt":"2023-06-20T11:16:44","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61956"},"modified":"2023-06-20T08:16:45","modified_gmt":"2023-06-20T11:16:45","slug":"copom-inicia-quarta-reuniao-do-ano-para-definir-juros-basicos","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/20\/copom-inicia-quarta-reuniao-do-ano-para-definir-juros-basicos\/","title":{"rendered":"Copom inicia quarta reuni\u00e3o do ano para definir juros b\u00e1sicos"},"content":{"rendered":"\n<p><em>Ag\u00eancia Brasil<\/em><\/p>\n\n\n\n<p>O Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom) do Banco Central (BC) come\u00e7a nesta ter\u00e7a-feira (20), em Bras\u00edlia, a quarta reuni\u00e3o do ano para definir a taxa b\u00e1sica de juros, a Selic. O \u00f3rg\u00e3o deve manter o aperto monet\u00e1rio com a Selic em 13,75% ao ano, mesmo com a queda recente da infla\u00e7\u00e3o.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539043&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539043&amp;o=node\"><\/p>\n\n\n\n<p>Nesta segunda-feira (19), o ministro da Fazenda, Fernando Haddad, disse que os juros deveriam ter come\u00e7ado a cair em mar\u00e7o. Desde o in\u00edcio do ano, o presidente\u00a0Luiz In\u00e1cio Lula da Silva\u00a0tamb\u00e9m critica os juros. Em janeiro, ele afirmou que o atual n\u00edvel da taxa Selic atrapalha os investimentos\u00a0e que n\u00e3o existe nenhuma justificativa para que a Selic esteja neste momento nesse patamar.<\/p>\n\n\n\n<p>Embora a taxa b\u00e1sica tenha parado de subir em agosto do ano passado, est\u00e1 no n\u00edvel mais alto desde o in\u00edcio de 2017 e os efeitos de um aperto monet\u00e1rio s\u00e3o sentidos na desacelera\u00e7\u00e3o da economia.<\/p>\n\n\n\n<p>Segundo a edi\u00e7\u00e3o mais recente do boletim Focus, pesquisa semanal com analistas de mercado, a taxa b\u00e1sica dever\u00e1 ser mantida em 13,75% ao ano&nbsp;pela s\u00e9tima vez seguida. A expectativa do mercado financeiro, entretanto, \u00e9de que a Selic encerre o ano em 12,25% ao ano. Nesta quarta-feira (21), ao fim do dia, o Copom anunciar\u00e1 a decis\u00e3o.<\/p>\n\n\n\n<p>Na ata da \u00faltima reuni\u00e3o, em maio, o \u00f3rg\u00e3o informou que a decis\u00e3o da taxa de juros requer\u00a0paci\u00eancia e serenidade. Mais uma vez, o Copom refor\u00e7ou a possibilidade de aumentar a taxa Selic, \u201capesar de ser um cen\u00e1rio menos prov\u00e1vel\u201d. Para o BC, a aprova\u00e7\u00e3o do arcabou\u00e7o fiscal pode ajudar no equil\u00edbrio das contas p\u00fablicas, que impactam nas expectativas de infla\u00e7\u00e3o.<\/p>\n\n\n\n<p>Depois de subir no in\u00edcio do ano, as expectativas de infla\u00e7\u00e3o t\u00eam ca\u00eddo. Segundo o\u00a0\u00faltimo boletim Focus, a estimativa de infla\u00e7\u00e3o para 2023 passou de 5,42% para 5,12%.<\/p>\n\n\n\n<p>Em maio, puxado pela queda nos pre\u00e7os dos combust\u00edveis e de artigos de resid\u00eancia, o\u00a0IPCA caiu para 0,23%, de acordo com\u00a0o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE). Com o resultado, o indicador acumulou alta de 2,95% no ano e de 3,94% nos \u00faltimos 12 meses, percentual mais baixo do que os 4,18% acumulados at\u00e9 o m\u00eas anterior.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Taxa Selic<\/h2>\n\n\n\n<p>A taxa b\u00e1sica de juros \u00e9 usada nas negocia\u00e7\u00f5es de t\u00edtulos p\u00fablicos emitidos pelo Tesouro Nacional no Sistema Especial de Liquida\u00e7\u00e3o e Cust\u00f3dia (Selic) e serve de refer\u00eancia para as demais taxas da economia. Ela \u00e9 o principal instrumento do Banco Central para manter a infla\u00e7\u00e3o sob controle. O BC atua diariamente por meio de opera\u00e7\u00f5es de mercado aberto \u2013 comprando e vendendo t\u00edtulos p\u00fablicos federais \u2013 para manter a taxa de juros pr\u00f3xima do valor definido na reuni\u00e3o.<\/p>\n\n\n\n<p>Quando o Copom aumenta a taxa b\u00e1sica de juros, a finalidade \u00e9 conter a demanda aquecida, e isso causa reflexos nos pre\u00e7os porque os juros mais altos encarecem o cr\u00e9dito e estimulam a poupan\u00e7a. Desse modo, taxas mais altas tamb\u00e9m podem dificultar a expans\u00e3o da economia. Mas, al\u00e9m da Selic, os bancos consideram outros fatores na hora de definir os juros cobrados dos consumidores, como risco de inadimpl\u00eancia, lucro e despesas administrativas.<\/p>\n\n\n\n<p>Ao reduzir a Selic, a tend\u00eancia \u00e9 de que o cr\u00e9dito fique mais barato, com incentivo \u00e0 produ\u00e7\u00e3o e ao consumo, reduzindo o controle da infla\u00e7\u00e3o e estimulando a atividade econ\u00f4mica.<\/p>\n\n\n\n<p>O Copom re\u00fane-se a cada 45 dias. No primeiro dia do encontro, s\u00e3o feitas apresenta\u00e7\u00f5es t\u00e9cnicas sobre a evolu\u00e7\u00e3o e as perspectivas das economias brasileira e mundial e o comportamento do mercado financeiro. No segundo dia, os membros do Copom, formado pela diretoria do BC, analisam as possibilidades e definem a Selic.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Meta de infla\u00e7\u00e3o<\/h2>\n\n\n\n<p>Para 2023, a meta de infla\u00e7\u00e3o que deve ser perseguida pelo Banco Central, definida pelo Conselho Monet\u00e1rio Nacional, \u00e9 de 3,25%, com intervalo de toler\u00e2ncia de 1,5 ponto percentual para cima ou para baixo. Ou seja, o limite inferior \u00e9 1,75% e o superior \u00e9 4,75%. Para 2024 e 2025, as metas s\u00e3o de 3% para os dois anos, com o mesmo intervalo de toler\u00e2ncia. A meta para 2026 ser\u00e1 definida neste m\u00eas.<\/p>\n\n\n\n<p>No \u00faltimo\u00a0Relat\u00f3rio de Infla\u00e7\u00e3o, divulgado no fim de mar\u00e7o pelo BC,\u00a0a autoridade monet\u00e1ria reconhece a possibilidade do estouro da meta de infla\u00e7\u00e3o neste ano. No documento, a estimativa \u00e9 que o IPCA atingir\u00e1 5,8% em 2023. O pr\u00f3ximo relat\u00f3rio ser\u00e1 divulgado no fim do m\u00eas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ag\u00eancia Brasil O Comit\u00ea de Pol\u00edtica Monet\u00e1ria (Copom) do Banco Central (BC) come\u00e7a nesta ter\u00e7a-feira<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61956","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61956","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61956"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61956\/revisions"}],"predecessor-version":[{"id":61958,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61956\/revisions\/61958"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61956"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61956"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61956"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}