{"id":61963,"date":"2023-06-20T11:26:24","date_gmt":"2023-06-20T14:26:24","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61963"},"modified":"2023-06-20T11:26:25","modified_gmt":"2023-06-20T14:26:25","slug":"morre-segunda-vitima-de-tiroteio-em-escola-do-parana","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/20\/morre-segunda-vitima-de-tiroteio-em-escola-do-parana\/","title":{"rendered":"Morre segunda v\u00edtima de tiroteio em escola do Paran\u00e1"},"content":{"rendered":"\n<p>Morreu na madrugada desta ter\u00e7a-feira (20) a segunda v\u00edtima do tiroteio registrado no Col\u00e9gio Estadual Professora Helena Kolody, em Camb\u00e9, no Paran\u00e1, depois que um ex-aluno entrou armado na institui\u00e7\u00e3o. A informa\u00e7\u00e3o foi confirmada pelo Hospital Universit\u00e1rio de Londrina, onde o jovem estava internado. A fam\u00edlia do estudante autorizou a doa\u00e7\u00e3o dos \u00f3rg\u00e3os.&nbsp;O nome da segunda v\u00edtima ainda n\u00e3o foi divulgado.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539049&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539049&amp;o=node\"><\/p>\n\n\n\n<p>O ataque ocorreu na manh\u00e3 dessa segunda-feira (19). Em nota, o governo do Paran\u00e1 informou que o ex-aluno teria entrado na escola alegando que solicitaria o seu hist\u00f3rico escolar. O atirador foi detido e encaminhado para Londrina. O governador Ratinho Junior decretou luto oficial de tr\u00eas dias e lamentou o ocorrido.&nbsp;<\/p>\n\n\n\n<p>De acordo com a pol\u00edcia civil, o atirador afirmou que o objetivo era atacar jovens, pois, para ele, \u201cestaria retaliando aquele sofrimento\u201d e m\u00e1goa que guardava do tempo em que estudou no col\u00e9gio. O secret\u00e1rio de Seguran\u00e7a P\u00fablica do Paran\u00e1, Hudson Teixeira, disse que, em depoimento, o autor dos disparos confirmou n\u00e3o ter v\u00ednculo com as v\u00edtimas.&nbsp;<\/p>\n\n\n\n<p>O secret\u00e1rio informou ainda que o atirador j\u00e1 havia efetuado um ataque com faca em uma outra escola, no passado, e foi denunciado pelo minist\u00e9rio p\u00fablico. Na \u00e9poca, a pol\u00edcia militar foi acionada, mas ele fugiu.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Terceiro ataque&nbsp;<\/h2>\n\n\n\n<p>O tiroteio no Col\u00e9gio Estadual Professora Helena Kolody \u00e9 o mais recente de um total de tr\u00eas ataques com mortes contabilizados em escolas brasileiras este ano. Desde janeiro, pelo menos seis pessoas morreram em raz\u00e3o de atos violentos praticados em col\u00e9gios no pa\u00eds.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Den\u00fancias&nbsp;<\/h2>\n\n\n\n<p>O Disque 100 recebe den\u00fancias de amea\u00e7as de ataques a escolas. As informa\u00e7\u00f5es podem ser feitas por WhatsApp, pelo n\u00famero (61) 99611-0100. &nbsp;O Minist\u00e9rio da Justi\u00e7a e Seguran\u00e7a P\u00fablica tamb\u00e9m disp\u00f5e de um&nbsp;<a href=\"http:\/\/www.gov.br\/mj\/pt-br\/canais-de-denuncias\/escolasegura\" target=\"_blank\" rel=\"noreferrer noopener\">canal<\/a>&nbsp;para receber den\u00fancias de viol\u00eancia escolar. &nbsp;<\/p>\n\n\n\n<p>As informa\u00e7\u00f5es enviadas ao canal ser\u00e3o mantidas sob sigilo e n\u00e3o h\u00e1 identifica\u00e7\u00e3o do denunciante.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Morreu na madrugada desta ter\u00e7a-feira (20) a segunda v\u00edtima do tiroteio registrado no Col\u00e9gio Estadual<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61963","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61963"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61963\/revisions"}],"predecessor-version":[{"id":61964,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61963\/revisions\/61964"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}