{"id":61990,"date":"2023-06-20T12:08:50","date_gmt":"2023-06-20T15:08:50","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61990"},"modified":"2023-06-20T12:09:07","modified_gmt":"2023-06-20T15:09:07","slug":"conselho-eleva-subsidio-para-familias-do-minha-casa-minha-vida","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/20\/conselho-eleva-subsidio-para-familias-do-minha-casa-minha-vida\/","title":{"rendered":"Conselho eleva subs\u00eddio para fam\u00edlias do Minha Casa, Minha Vida"},"content":{"rendered":"\n<p>O Conselho Curador do Fundo de Garantia do Tempo de Servi\u00e7o (CCFGTS) decidiu, nesta ter\u00e7a-feira (20), em Bras\u00edlia, aumentar o subs\u00eddio para unidades habitacionais do programa Minha Casa, Minha Vida (MCMV) e reduzir a taxa de juros para fam\u00edlias de baixa renda nas faixas 1 e 2 do programa.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539088&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539088&amp;o=node\"><\/p>\n\n\n\n<p>Tamb\u00e9m hoje, o conselho decidiu pela corre\u00e7\u00e3o no valor dos im\u00f3veis que podem ser financiados pelo MCMV. Assim, o subs\u00eddio para fam\u00edlias de baixa renda com renda mensal de at\u00e9 R$ 2.640 (faixa 1) e at\u00e9 R$ 4,4 mil (faixa 2), passou de R$ 47 mil para at\u00e9 R$ 55 mil.<\/p>\n\n\n\n<p>O subs\u00eddio \u00e9 uma esp\u00e9cie de desconto e \u00e9 aplicado conforme a renda da fam\u00edlia e a localiza\u00e7\u00e3o do im\u00f3vel. Com a altera\u00e7\u00e3o, o teto dos im\u00f3veis para as faixas 1 e 2 do programa ser\u00e1 de R$ 264 mil para os munic\u00edpios com popula\u00e7\u00e3o de 750 mil habitantes ou mais; R$ 250 mil para as cidades com popula\u00e7\u00e3o entre 300 mil e 750 mil habitantes; R$ 230 mil para os que t\u00eam popula\u00e7\u00e3o entre 100 mil e 300 mil habitantes; e R$ 200 mil para cidades com popula\u00e7\u00e3o inferior a 100 mil habitantes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Valor do im\u00f3vel<\/h2>\n\n\n\n<p>Na mesma reuni\u00e3o, o conselho ampliou o valor m\u00e1ximo do im\u00f3vel que pode ser comprado pelas fam\u00edlias com renda que varia entre R$ 4,4 mil e R$ 8 mil (faixa 3): passou de R$ 264 mil para at\u00e9 R$ 350 mil em todos os estados.<\/p>\n\n\n\n<p>A estimativa \u00e9 que a medida traga um incremento de 57 mil novas contrata\u00e7\u00f5es na faixa 3, das quais 40 mil em 2023. Al\u00e9m disso, o conselho estima um crescimento de 12% nas contrata\u00e7\u00f5es, com cerca 330 mil unidades para as fam\u00edlias com renda de at\u00e9 R$ 3,3 mil. Em 2023, o or\u00e7amento do FGTS para subs\u00eddios \u00e9 de R$ 9,5 bilh\u00f5es.<\/p>\n\n\n\n<p>O conselho tamb\u00e9m fez a revis\u00e3o dos juros cobrados de fam\u00edlias com renda mensal de at\u00e9 R$ 2 mil. Os juros passaram de 4,25% ao ano para 4% nas regi\u00f5es Norte e Nordeste. Para as regi\u00f5es Sul, Sudeste e Centro-Oeste, a taxa caiu de 4,5% para 4,25% ao ano.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Por Luciano Nascimento &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Conselho Curador do Fundo de Garantia do Tempo de Servi\u00e7o (CCFGTS) decidiu, nesta ter\u00e7a-feira<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61990","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61990"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61990\/revisions"}],"predecessor-version":[{"id":61992,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61990\/revisions\/61992"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}