{"id":61997,"date":"2023-06-20T13:34:10","date_gmt":"2023-06-20T16:34:10","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=61997"},"modified":"2023-06-20T15:37:45","modified_gmt":"2023-06-20T18:37:45","slug":"tradicional-festa-da-fogueira-no-bairro-inema-acontece-no-dia-23-de-junho","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/20\/tradicional-festa-da-fogueira-no-bairro-inema-acontece-no-dia-23-de-junho\/","title":{"rendered":"Tradicional \u2018Festa da Fogueira\u2019 de Para\u00edba do Sul acontece no dia 23 de junho"},"content":{"rendered":"\n<p>Considerada como patrim\u00f4nio imaterial cultural do munic\u00edpio, a \u2018Festa da Fogueira\u2019 \u00e9 celebrada h\u00e1 tr\u00eas gera\u00e7\u00f5es no bairro Inema. A passagem com os p\u00e9s descal\u00e7os \u00e9 sempre na noite do dia 23 para 24 de junho, data em que se comemora Dia de S\u00e3o Jo\u00e3o.<br>\u201cEsses eventos tradicionais e culturais de nossa Para\u00edba do Sul propiciam o desenvolvimento econ\u00f4mico, atrav\u00e9s do turismo na cidade. Centenas de pessoas circulam pela festa consumindo nos bares, restaurantes e barracas. Al\u00e9m disso, a festa desperta na popula\u00e7\u00e3o o seu sentido religioso, com a tradicional ladainha nas casas da comunidade e as apresenta\u00e7\u00f5es culturais, com shows musicais, dan\u00e7as t\u00edpicas e capoeira. O turismo religioso da nossa cidade \u00e9 fort\u00edssimo. Para se ter uma ideia, somente no m\u00eas de junho temos tr\u00eas festas tradicionais\u201d, afirmou a prefeita Dayse Onofre.<\/p>\n\n\n\n<p>A tradicional programa\u00e7\u00e3o come\u00e7a \u00e0s 19h com Ladainha, em seguida haver\u00e1 apresenta\u00e7\u00e3o da quadrilha L\u00edrio e Orqu\u00eddea, \u00e0s 22h show com Claudinei e para fechar a noite a esperada passagem com os p\u00e9s descal\u00e7os pelas brasas da fogueira \u00e0s 0h. A festividade continua no s\u00e1bado e domingo com barracas de comes e bebes.<\/p>\n\n\n\n<p><strong>Entenda a hist\u00f3ria dessa cultura sul-paraibana:<\/strong><\/p>\n\n\n\n<p><br>A festa foi organizada durante muitos anos pelo Sr. Sebasti\u00e3o Menezes com a participa\u00e7\u00e3o da comunidade no bairro do Inema, tendo como ato inicial a \u201creza da ladainha\u201d na casa do organizador. Mantendo a tradi\u00e7\u00e3o centen\u00e1ria da fam\u00edlia Menezes e dos fi\u00e9is, a devo\u00e7\u00e3o a S\u00e3o Jo\u00e3o \u00e9 demonstrada atrav\u00e9s do tradicional ritual da passagem com p\u00e9s descal\u00e7os sobre brasas da fogueira, na madrugada do dia 23 para 24 de junho.<\/p>\n\n\n\n<p>Segundo relato do Sr. Sebasti\u00e3o, seu bisav\u00f4 contava que no per\u00edodo da escravid\u00e3o no Brasil, escravos de uma Fazenda de Engenho planejavam fuga em massa. Sendo delatados, receberam o castigo e foram obrigados a passar descal\u00e7os pela brasa quente. Quem conseguisse passar sem sentir dor e sem queimar os p\u00e9s, ficaria livre das chibatadas.<br><br>Provavelmente o senhor de engenho e seus capatazes acreditavam que seria imposs\u00edvel algu\u00e9m andar descal\u00e7o sobre brasas. Este fato acorreu por ocasi\u00e3o do dia de S\u00e3o Jo\u00e3o, e para surpresa todos os escravos conseguiram o feito. A partir da\u00ed os negros atribu\u00edram que aquele que tem f\u00e9 em Deus e em S\u00e3o Jo\u00e3o possui o poder de andar sobre brasas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerada como patrim\u00f4nio imaterial cultural do munic\u00edpio, a \u2018Festa da Fogueira\u2019 \u00e9 celebrada h\u00e1 tr\u00eas<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-61997","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61997","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=61997"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61997\/revisions"}],"predecessor-version":[{"id":62015,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/61997\/revisions\/62015"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=61997"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=61997"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=61997"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}