{"id":62038,"date":"2023-06-21T08:35:35","date_gmt":"2023-06-21T11:35:35","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62038"},"modified":"2023-06-21T08:35:36","modified_gmt":"2023-06-21T11:35:36","slug":"espetaculo-guadakan-mostra-necessidade-de-preservacao-do-pantanal","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/21\/espetaculo-guadakan-mostra-necessidade-de-preservacao-do-pantanal\/","title":{"rendered":"Espet\u00e1culo Guadakan mostra necessidade de preserva\u00e7\u00e3o do Pantanal"},"content":{"rendered":"\n<p>O espet\u00e1culo pantaneiro Guadakan sai de\u00a0Mato Grosso do Sul pela primeira vez e estreia nesta quinta-feira (22) no Rio de Janeiro, para duas apresenta\u00e7\u00f5es gratuitas no Teatro Odylo Costa, filho, da Universidade do Estado (Uerj). A primeira apresenta\u00e7\u00e3o, \u00e0s 15h, ser\u00e1 para alunos da rede p\u00fablica de ensino e, a segunda, \u00e0s 19h, para o p\u00fablico em geral. Os ingressos j\u00e1 est\u00e3o dispon\u00edveis no link\u00a0teatros Uerj. A classifica\u00e7\u00e3o \u00e9 dez\u00a0anos. A sess\u00e3o para estudantes ocorrer\u00e1\u00a0dentro da s\u00e9rie Palco das Escolas, da Uerj, que visa atrair alunos do ensino fundamental e m\u00e9dio ao teatro. Ap\u00f3s a apresenta\u00e7\u00e3o, haver\u00e1 debate.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539311&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539311&amp;o=node\"><\/p>\n\n\n\n<p>A pe\u00e7a re\u00fane a Companhia de Dan\u00e7a do Pantanal e a Orquestra de C\u00e2mara do Pantanal (OCAMP), projetos do Instituto Moinho Cultural Sul-Americano, de Corumb\u00e1. O patroc\u00ednio \u00e9 do Instituto Cultural Vale, por meio da Lei Rouanet, de incentivo \u00e0 cultura. O espet\u00e1culo j\u00e1 foi apresentado em 12 cidades de&nbsp;Mato Grosso do Sul, reunindo mais de 4&nbsp;mil espectadores.<\/p>\n\n\n\n<p>A diretora executiva do Instituto Moinho Cultural, M\u00e1rcia Rolon, disse\u00a0que a ideia \u00e9, usando o Rio de Janeiro como grande vitrine, conseguir vender o espet\u00e1culo para outras regi\u00f5es do Brasil. \u201cComo os produtos est\u00e3o muito bons e consolidados, pretendemos, a partir disso, vender o espet\u00e1culo para outras cidades. Mas precisamos de parcerias\u201d, destacou.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/danca-3.jpg\" alt=\"\" class=\"wp-image-62040\"\/><figcaption class=\"wp-element-caption\">Espet\u00e1culo Guadakan que estreia no Rio de Janeiro. Foto: Guadakan\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p><strong>Mudan\u00e7as clim\u00e1ticas<\/strong><\/p>\n\n\n\n<p>Para M\u00e1rcia, a pe\u00e7a tem tudo a ver com o momento atual do mundo, quando s\u00e3o discutidas as mudan\u00e7as clim\u00e1ticas, o aquecimento global e os impactos sobre as na\u00e7\u00f5es. \u201cO Instituto Moinho Cultural sempre trabalha com quest\u00f5es contempor\u00e2neas ligadas ao nosso bioma e ao nosso territ\u00f3rio\u201d. A pe\u00e7a \u00e9 concebida a partir do mito ind\u00edgena Guat\u00f3, etnia estabelecida na fronteira do Brasil com a Bol\u00edvia, e conta uma hist\u00f3ria que ressalta a necessidade da preserva\u00e7\u00e3o do Pantanal, unindo sustentabilidade, dan\u00e7a contempor\u00e2nea e m\u00fasica.<\/p>\n\n\n\n<p>\u201cEsse espet\u00e1culo, em especial, surge a partir do momento em que vivemos as queimadas no Pantanal. A gente n\u00e3o respirava. A partir disso, procuramos hist\u00f3rias para falar dessa quest\u00e3o espiritual da regi\u00e3o. Ent\u00e3o, encontramos esse mito Guadakan, que \u00e9 o esp\u00edrito do Pantanal e, dentro desse mito, na hist\u00f3ria, conta-se que, na verdade, um menino matou o grande deus. O que a gente est\u00e1 querendo dizer \u00e9 que quem est\u00e1 matando o Pantanal somos n\u00f3s, seres humanos. N\u00f3s n\u00e3o entendemos ainda essa rela\u00e7\u00e3o de sustentabilidade\u201d. Segundo M\u00e1rcia, a pe\u00e7a retrata o desprezo das pessoas pela regi\u00e3o&nbsp;e faz um grande alerta no final. \u201cEstamos falando n\u00e3o s\u00f3 do nosso bioma, mas de uma quest\u00e3o global\u201d.<\/p>\n\n\n\n<p>O Instituto Moinho Cultural Sul-Americano atende, em m\u00e9dia, a 500 crian\u00e7as. Esta \u00e9 a primeira vez que a OCAMP traz um maestro formado pela organiza\u00e7\u00e3o. A Orquestra Sinf\u00f4nica Brasileira (OSB) \u00e9 grande parceira na forma\u00e7\u00e3o dos m\u00fasicos. Dois estagi\u00e1rios \u2013 um menino de 12 anos e uma menina de 14\u00a0\u2013 estreiam na orquestra, nas apresenta\u00e7\u00f5es no Rio de Janeiro, bem como dois bailarinos de 17 e 18 anos, que atuam na Companhia de Dan\u00e7a do Pantanal. \u201cEst\u00e3o treinando para fazer parte, um dia, da orquestra e da companhia\u201d, afirmou a diretora executiva. Como o Moinho Cultural trabalha com a fronteira brasileira, h\u00e1 um argentino no bal\u00e9 cl\u00e1ssico e dois bolivianos na orquestra, nesse espet\u00e1culo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/danca-2.jpg\" alt=\"\" class=\"wp-image-62039\"\/><figcaption class=\"wp-element-caption\">Espet\u00e1culo Guadakan que estreia no Rio de Janeiro. Foto: Guadakan\/ Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p><strong>Instituto<\/strong><\/p>\n\n\n\n<p>O Instituto Moinho Cultural Sul-Americano atende, em m\u00e9dia, a 500 crian\u00e7as. \u00c9 uma organiza\u00e7\u00e3o da sociedade civil (OSC) que oferece h\u00e1 18 anos, para crian\u00e7as e adolescentes em situa\u00e7\u00e3o de vulnerabilidade social de Corumb\u00e1 (MS), Lad\u00e1rio (MS), Puerto Suarez e Puerto Quijarro (situadas na fronteira do Brasil com a Bol\u00edvia), aulas de dan\u00e7a, m\u00fasica, tecnologia e inform\u00e1tica. A forma\u00e7\u00e3o continuada oferecida pela institui\u00e7\u00e3o tem dura\u00e7\u00e3o de at\u00e9 oito anos. O instituto tem como miss\u00e3o diminuir a vulnerabilidade social na regi\u00e3o de fronteira Brasil-Bol\u00edvia, por meio do acesso a bens culturais e tecnol\u00f3gicos. Mais de 23 mil crian\u00e7as e adolescentes j\u00e1 foram atendidos pelo Moinho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O espet\u00e1culo pantaneiro Guadakan sai de\u00a0Mato Grosso do Sul pela primeira vez e estreia nesta<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62038","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62038"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62038\/revisions"}],"predecessor-version":[{"id":62042,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62038\/revisions\/62042"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}