{"id":62060,"date":"2023-06-21T15:11:38","date_gmt":"2023-06-21T18:11:38","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62060"},"modified":"2023-06-21T16:33:01","modified_gmt":"2023-06-21T19:33:01","slug":"crianca-de-10-anos-fica-ferida-em-acidente-de-carro-proximo-a-entrada-da-mosela-em-petropolis","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/21\/crianca-de-10-anos-fica-ferida-em-acidente-de-carro-proximo-a-entrada-da-mosela-em-petropolis\/","title":{"rendered":"Crian\u00e7a de 10 anos fica ferida em acidente de carro pr\u00f3ximo a entrada da Mosela, em Petr\u00f3polis"},"content":{"rendered":"\n<p>No in\u00edcio da tarde, desta quarta-feira, 21, um carro colidiu contra um poste, na Rua Carlos Gomes, no Centro, pr\u00f3ximo a sede da Cruz Vermelha, em Petr\u00f3polis. O ve\u00edculo ficou parcialmente destru\u00eddo e o Corpo de Bombeiros foi acionado para socorrer um menino de 10 anos, que ficou ferido no acidente. O estado de sa\u00fade dele n\u00e3o foi divulgado. Com o acidente, o tr\u00e2nsito ficou em meia pista e o congestionamento chegou a cerca de 1km. <\/p>\n\n\n\n<p>Foto: TVC<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No in\u00edcio da tarde, desta quarta-feira, 21, um carro colidiu contra um poste, na Rua<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62060","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62060"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62060\/revisions"}],"predecessor-version":[{"id":62064,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62060\/revisions\/62064"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}