{"id":62068,"date":"2023-06-21T18:16:08","date_gmt":"2023-06-21T21:16:08","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62068"},"modified":"2023-06-21T18:16:09","modified_gmt":"2023-06-21T21:16:09","slug":"professor-jonas-masetti-e-convidado-para-discursar-no-congresso-nacional-pelo-dia-do-yoga","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/21\/professor-jonas-masetti-e-convidado-para-discursar-no-congresso-nacional-pelo-dia-do-yoga\/","title":{"rendered":"Professor Jonas Masetti \u00e9 convidado para discursar no Congresso Nacional pelo Dia do Yoga"},"content":{"rendered":"\n<p><em>Comemorado internacionalmente em 21 de junho, o Yoga tem transformado a vida de milh\u00f5es de pessoas ao redor do mundo<\/em><\/p>\n\n\n\n<p>Reconhecido pelo governo indiano como embaixador da Tradi\u00e7\u00e3o V\u00e9dica nas Am\u00e9ricas, o professor tradicional de Vedanta Jonas Masetti, fundador e diretor do Instituto Vishva Vidya, em Petr\u00f3polis, esteve na C\u00e2mara dos Deputados, em Bras\u00edlia, na \u00faltima sexta-feira, para discursar pelo Dia Internacional do Yoga, comemorado nesta quarta-feira, 21 de junho. A sess\u00e3o solene requerida e presidida pela deputada \u00c9rika Kokay reuniu autoridades como o embaixador da \u00cdndia no Brasil, integrantes da Unesco e de outras institui\u00e7\u00f5es, professores e praticantes de yoga.<\/p>\n\n\n\n<p>Em sua fala, Masetti passou uma mensagem de paz e orienta\u00e7\u00e3o para os brasileiros que buscam suas respostas atrav\u00e9s do yoga e que \u00e9 poss\u00edvel encontr\u00e1-las tamb\u00e9m atrav\u00e9s da espiritualidade e das pr\u00e1ticas ancestrais. Ele explicou que, nos dias atuais, vivemos em uma sociedade mentalmente e espiritualmente doente, mas que existem pr\u00e1ticas ancestrais, como a Tradi\u00e7\u00e3o V\u00e9dica do qual o Yoga est\u00e1 inserido, que viajam com a humanidade prontas para resolver essas desarmonias.<\/p>\n\n\n\n<p>\u201cGra\u00e7as ao imenso trabalho da m\u00e3e \u00cdndia e do povo indiano, toda a Tradi\u00e7\u00e3o V\u00e9dica, que cont\u00e9m in\u00fameras pr\u00e1ticas, est\u00e1 disseminada pelo mundo contribuindo para a vida de milhares de pessoas. A gente conhece muitas delas aqui no Brasil: o Yoga, que traz sa\u00fade f\u00edsica e mental; os mantras; os cantos sagrados; a medita\u00e7\u00e3o, que \u00e9 cientificamente comprovado na redu\u00e7\u00e3o do estresse e da ansiedade; o Ayurveda, a medicina tradicional da \u00cdndia, que traz luz sobre problemas psicossom\u00e1ticos e autoimune; e a astrologia, que a gente usa a todo momento. Todas essas pr\u00e1ticas v\u00eam da Tradi\u00e7\u00e3o V\u00e9dica, s\u00e3o n\u00e3o religiosas e est\u00e3o dispon\u00edveis para qualquer um, sem distin\u00e7\u00e3o, desde que a pessoa esteja aberta para receb\u00ea-las\u201d, destacou Masetti.<\/p>\n\n\n\n<p>Devido \u00e0 seriedade, comprometimento e abrang\u00eancia de seu trabalho, Masetti foi reconhecido recentemente pelo primeiro-ministro da \u00cdndia, Narendra Modi, como embaixador da Tradi\u00e7\u00e3o V\u00e9dica nas Am\u00e9ricas. Al\u00e9m de cursos fechados e abertos com v\u00eddeos gratuitos de ensinamentos que impactam mensalmente mais de 500 mil pessoas de todo mundo, o professor Jonas mant\u00e9m uma institui\u00e7\u00e3o sem fins lucrativos que leva o seu nome, faz in\u00fameros trabalhos sociais e hoje desenvolve em Petr\u00f3polis o Pequena Tribo, programa educacional gratuito que oferece ensino extracurricular, no contraturno escolar, a crian\u00e7as em comunidades petropolitanas. Sem falar nos retiros sediados em Petr\u00f3polis e na promo\u00e7\u00e3o das manifesta\u00e7\u00f5es da cultura indiana com o Festival de Vedanta e Autoconhecimento, que acontece anualmente tamb\u00e9m em Petr\u00f3polis e traz milhares de pessoas ao munic\u00edpio.<\/p>\n\n\n\n<p>\u201cEsse di\u00e1logo sobre Vedanta, atrav\u00e9s de aulas e palestras, visa tirar de dentro da gente as ignor\u00e2ncias e ilus\u00f5es que fazem a gente sofrer. O nosso objetivo \u00e9 conhecer aquilo que a gente \u00e9 de verdade, tirar a felicidade que est\u00e1 projetada sobre os objetos, pessoas e situa\u00e7\u00f5es do lado de fora e trazer isso pra dentro, onde ningu\u00e9m pode tirar a felicidade de voc\u00ea. Vedanta fala sobre o conhecimento do ser que est\u00e1 al\u00e9m do corpo, al\u00e9m da mente, al\u00e9m das emo\u00e7\u00f5es, que \u00e9 sempre pleno e imut\u00e1vel. E esse processo, apesar de ser para o bem coletivo, ele passa pela individualidade de cada um\u201d, finalizou Masetti.<\/p>\n\n\n\n<p>Voc\u00ea pode assistir \u00e0 sess\u00e3o solene na \u00edntegra no YouTube da C\u00e2mara dos Deputados, acessando <a href=\"https:\/\/www.youtube.com\/live\/OTjAlIezttU?feature=share\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.youtube.com\/live\/OTjAlIezttU?feature=share<\/a><\/p>\n\n\n\n<p><strong>Mais sobre o Yoga e seus benef\u00edcios<\/strong><\/p>\n\n\n\n<p>O Yoga, tradicionalmente conhecido como \u00c1sana, \u00e9 uma pr\u00e1tica milenar indiana que vem da Tradi\u00e7\u00e3o V\u00e9dica e re\u00fane milh\u00f5es de adeptos ao redor do mundo. Em 2016, a Unesco declarou o yoga como patrim\u00f4nio imaterial da humanidade devido \u00e0 sua contribui\u00e7\u00e3o e import\u00e2ncia na transforma\u00e7\u00e3o de vidas. No Brasil, h\u00e1 uma forte comunidade de praticantes de yoga e estudiosos de Vedanta. Em 2017, o Minist\u00e9rio da Sa\u00fade incluiu a pr\u00e1tica no rol de servi\u00e7os da Aten\u00e7\u00e3o B\u00e1sica do SUS.<\/p>\n\n\n\n<p>Entre os benef\u00edcios do yoga est\u00e3o o bem-estar f\u00edsico e mental, redu\u00e7\u00e3o do estresse e da ansiedade, maior concentra\u00e7\u00e3o nas tarefas do dia a dia, calma e foco para a mente, refor\u00e7o da mem\u00f3ria, harmoniza\u00e7\u00e3o das emo\u00e7\u00f5es atrav\u00e9s da respira\u00e7\u00e3o, melhora da qualidade do sono, flexibilidade e fortalecimento do corpo, entre outros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comemorado internacionalmente em 21 de junho, o Yoga tem transformado a vida de milh\u00f5es de<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62068","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62068","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62068"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62068\/revisions"}],"predecessor-version":[{"id":62070,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62068\/revisions\/62070"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62068"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62068"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62068"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}