{"id":62106,"date":"2023-06-22T07:19:34","date_gmt":"2023-06-22T10:19:34","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62106"},"modified":"2023-06-22T13:13:03","modified_gmt":"2023-06-22T16:13:03","slug":"engavetamento-no-km-122-em-duque-de-caxias","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/22\/engavetamento-no-km-122-em-duque-de-caxias\/","title":{"rendered":"Engavetamento no Km 122 em Duque de Caxias"},"content":{"rendered":"\n<p>Um engavetamento envolvendo 2 carros de passeio e 2 caminh\u00f5es, aconteceu na manh\u00e3 desta quinta-feira (22), na BR-040, km 122, sentido Rio de Janeiro, na pista principal, na altura de Duque de Caxias. <\/p>\n\n\n\n<p>A Concession\u00e1ria Concer, que administra a via, est\u00e1 no local e informou que uma v\u00edtima, um homem, com ferimentos moderados foi socorrida pelos bombeiros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um engavetamento envolvendo 2 carros de passeio e 2 caminh\u00f5es, aconteceu na manh\u00e3 desta quinta-feira<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62106","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62106"}],"version-history":[{"count":2,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62106\/revisions"}],"predecessor-version":[{"id":62109,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62106\/revisions\/62109"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}