{"id":62119,"date":"2023-06-22T12:05:00","date_gmt":"2023-06-22T15:05:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62119"},"modified":"2023-06-22T12:05:01","modified_gmt":"2023-06-22T15:05:01","slug":"defesa-vai-combater-garimpo-ilegal-em-terra-indigena-yanomami","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/22\/defesa-vai-combater-garimpo-ilegal-em-terra-indigena-yanomami\/","title":{"rendered":"Defesa vai combater garimpo ilegal em Terra Ind\u00edgena Yanomami"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Decreto amplia atua\u00e7\u00e3o das For\u00e7as Armadas na regi\u00e3o<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"> Por Fab\u00edola Sinimbu &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205340.mp3\"><\/audio><\/h4>\n\n\n\n<p>O governo federal publicou, nesta quinta-feira (22),&nbsp;<a href=\"https:\/\/www.in.gov.br\/web\/dou\/-\/decreto-n-11.575-de-21-de-junho-de-2023-491518756\" target=\"_blank\" rel=\"noreferrer noopener\">decreto<\/a>&nbsp;que altera a atua\u00e7\u00e3o do Minist\u00e9rio da Defesa contra o garimpo ilegal e o enfrentamento da Emerg\u00eancia em Sa\u00fade P\u00fablica de Import\u00e2ncia Nacional, em territ\u00f3rio yanomami.&nbsp; Anteriormente, a pasta, que re\u00fane Ex\u00e9rcito, Marinha e Aeron\u00e1utica, era respons\u00e1vel apenas por fornecer dados de intelig\u00eancia e transporte a\u00e9reo e log\u00edstico.&nbsp;<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539672&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539672&amp;o=node\"><\/p>\n\n\n\n<p>Com a mudan\u00e7a, o Minist\u00e9rio da Defesa passa a atuar na execu\u00e7\u00e3o de a\u00e7\u00f5es preventivas e repressivas contra crimes transfronteiri\u00e7os e ambientais, na regi\u00e3o de fronteira terrestre e tamb\u00e9m nos rios e lagos da regi\u00e3o. Os militares atuar\u00e3o nas a\u00e7\u00f5es de patrulhamento, revista de pessoas, ve\u00edculos terrestres, embarca\u00e7\u00f5es e aeronaves, e de pris\u00f5es em flagrante.&nbsp;<\/p>\n\n\n\n<p>Antes, a atua\u00e7\u00e3o direta no territ\u00f3rio Yanomami estava sob a responsabilidade da For\u00e7a Nacional de Seguran\u00e7a, Pol\u00edcia Federal e Instituto Brasileiro do Meio Ambiente e dos Recursos Naturais Renov\u00e1veis (Ibama).&nbsp;A exce\u00e7\u00e3o era o espa\u00e7o a\u00e9reo que estava sob o comando da Aeron\u00e1utica.&nbsp;<\/p>\n\n\n\n<p>O acesso de pessoas ao territ\u00f3rio Yanomami permanece sendo controlado por medidas dos Minist\u00e9rios da Sa\u00fade e dos Povos Ind\u00edgenas, para o controle da transmiss\u00e3o de doen\u00e7as.<\/p>\n\n\n\n<p>Al\u00e9m das novas formas de atua\u00e7\u00e3o, foram mantidas as a\u00e7\u00f5es previstas no&nbsp;<a href=\"http:\/\/www.planalto.gov.br\/ccivil_03\/_ato2023-2026\/2023\/Decreto\/D11405.htm\" target=\"_blank\" rel=\"noreferrer noopener\">decreto anterior<\/a>.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Maria Claudia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Decreto amplia atua\u00e7\u00e3o das For\u00e7as Armadas na regi\u00e3o Por Fab\u00edola Sinimbu &#8211; Bras\u00edlia O governo<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62119","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62119"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62119\/revisions"}],"predecessor-version":[{"id":62121,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62119\/revisions\/62121"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}