{"id":62131,"date":"2023-06-22T12:39:31","date_gmt":"2023-06-22T15:39:31","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62131"},"modified":"2023-06-22T12:39:33","modified_gmt":"2023-06-22T15:39:33","slug":"termina-hoje-prazo-para-inscricoes-no-sisu","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/22\/termina-hoje-prazo-para-inscricoes-no-sisu\/","title":{"rendered":"Termina hoje prazo para inscri\u00e7\u00f5es no Sisu"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Interessados devem acessar o Portal \u00danico de Acesso ao Ensino Superior<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Pedro Peduzzi &#8211; Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205330.mp3\"><\/audio><\/h4>\n\n\n\n<p>Termina \u00e0s 23 horas e 59 minutos desta quinta-feira (23) o prazo para as inscri\u00e7\u00f5es no processo seletivo do Sistema de Sele\u00e7\u00e3o Unificada (Sisu) do segundo semestre de 2021. Para participar&nbsp;do certame, os interessados devem acessar o&nbsp;<a href=\"https:\/\/acessounico.mec.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Portal \u00danico de Acesso<\/a><a href=\"http:\/\/acessounico.mec.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;ao Ensino Superior<\/a>.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539637&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539637&amp;o=node\"><\/p>\n\n\n\n<p>A previs\u00e3o \u00e9 de que o resultado seja divulgado no dia 27 de junho. A&nbsp;classifica\u00e7\u00e3o dos estudantes tem por base a nota obtida na edi\u00e7\u00e3o de 2022 do Exame Nacional do Ensino M\u00e9dio (Enem). As matr\u00edculas devem ser feitas de 29 de junho a 4 de julho.<\/p>\n\n\n\n<p>O Sisu \u00e9 o programa do Minist\u00e9rio da Educa\u00e7\u00e3o (MEC) que re\u00fane as vagas oferecidas por institui\u00e7\u00f5es p\u00fablicas de ensino superior de todo o Brasil, sendo a maioria delas ofertada por institui\u00e7\u00f5es federais &#8211; universidades e institutos.<\/p>\n\n\n\n<p>As vagas s\u00e3o abertas semestralmente por meio de um sistema informatizado que executa a sele\u00e7\u00e3o dos estudantes com base na nota do Enem, de acordo com as escolhas dos candidatos inscritos. Para isso, o candidato n\u00e3o pode ter tirado zero na reda\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Processo seletivo<\/h2>\n\n\n\n<p>O estudante pode&nbsp;escolher at\u00e9 duas op\u00e7\u00f5es de curso em cada processo seletivo do Sisu. \u00c9 poss\u00edvel alterar as op\u00e7\u00f5es&nbsp;durante o per\u00edodo de inscri\u00e7\u00e3o, sendo que ter\u00e1 validade apenas a \u00faltima delas.&nbsp;<\/p>\n\n\n\n<p>Quem n\u00e3o for selecionado nas duas op\u00e7\u00f5es ainda pode disputar uma das vagas por meio da lista de espera. Para isso, \u00e9 preciso manifestar interesse em entrar na lista no per\u00edodo de 27 de julho a&nbsp;4 de julho. A convoca\u00e7\u00e3o dos&nbsp;candidatos&nbsp;ser\u00e1 feita pelas&nbsp;institui\u00e7\u00f5es a partir de 10 de julho.<\/p>\n\n\n\n<p>As vagas ofertadas s\u00e3o distribu\u00eddas conforme a Lei de Cotas (Lei n\u00ba 12.711\/2012). As institui\u00e7\u00f5es federais de educa\u00e7\u00e3o superior vinculadas ao MEC devem reservar, no m\u00ednimo, 50% das vagas para estudantes que tenham cursado integralmente o ensino m\u00e9dio em escolas p\u00fablicas. Metade das vagas&nbsp;s\u00e3o reservadas para estudantes oriundos de fam\u00edlias com renda igual ou inferior a 1,5 sal\u00e1rio m\u00ednimo per capita (renda por cabe\u00e7a).<\/p>\n\n\n\n<p>As institui\u00e7\u00f5es podem adotar as pr\u00f3prias pol\u00edticas e a\u00e7\u00f5es, como vagas reservadas e aplica\u00e7\u00e3o de b\u00f4nus sobre a nota do candidato que atenda ao perfil indicado pela institui\u00e7\u00e3o. De acordo com as especifica\u00e7\u00f5es da institui\u00e7\u00e3o, o Sisu faz o c\u00e1lculo automaticamente e gera nova nota.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Maria Claudia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Interessados devem acessar o Portal \u00danico de Acesso ao Ensino Superior Por Pedro Peduzzi &#8211;<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62131","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62131"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62131\/revisions"}],"predecessor-version":[{"id":62133,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62131\/revisions\/62133"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}