{"id":62258,"date":"2023-06-23T14:34:26","date_gmt":"2023-06-23T17:34:26","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62258"},"modified":"2023-06-23T14:34:28","modified_gmt":"2023-06-23T17:34:28","slug":"receita-abre-consulta-a-segundo-lote-de-restituicao-do-ir","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/23\/receita-abre-consulta-a-segundo-lote-de-restituicao-do-ir\/","title":{"rendered":"Receita abre consulta a segundo lote de restitui\u00e7\u00e3o do IR"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Cerca de 5,1 milh\u00f5es de contribuintes receber\u00e3o R$ 7,5 bilh\u00f5es<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Wellton M\u00e1ximo \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Bras\u00edlia<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205398.mp3\"><\/audio><\/h4>\n\n\n\n<p>A partir das 10h desta sexta-feira (23), cerca de 5 milh\u00f5es de contribuintes que entregaram a Declara\u00e7\u00e3o do Imposto de Renda Pessoa F\u00edsica acertar\u00e3o as contas com o Le\u00e3o. Nesse hor\u00e1rio, a Receita Federal liberar\u00e1 a consulta ao segundo dos cinco lotes de restitui\u00e7\u00e3o de 2023. O lote tamb\u00e9m contempla restitui\u00e7\u00f5es residuais de anos anteriores.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1539862&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1539862&amp;o=node\"><\/p>\n\n\n\n<p>Ao todo, 5.138.476 contribuintes receber\u00e3o R$ 7,5 bilh\u00f5es. Todo o valor, informou o Fisco, ir\u00e1 para contribuintes com prioridade no reembolso.<\/p>\n\n\n\n<p>A maior parte &#8211;&nbsp;3.490.513 contribuintes &#8211;&nbsp;informou a chave Pix do tipo Cadastro de Pessoas F\u00edsicas (CPF) na declara\u00e7\u00e3o do Imposto de Renda ou usou a declara\u00e7\u00e3o pr\u00e9-preenchida. Novidade na declara\u00e7\u00e3o a partir deste ano, a informa\u00e7\u00e3o da chave Pix d\u00e1 prioridade no recebimento.<\/p>\n\n\n\n<p>O restante dos contribuintes tem direito a prioridade legal, sendo 130.088 idosos acima de 80 anos; 978.397\u202fentre 60 e 79\u202fanos; 70.589\u202fcontribuintes\u202fcom alguma defici\u00eancia f\u00edsica ou mental ou doen\u00e7a grave e 468.889\u202fcontribuintes cuja maior fonte de renda seja o magist\u00e9rio.<\/p>\n\n\n\n<p>A consulta poder\u00e1 ser feita na&nbsp;<a href=\"https:\/\/www.gov.br\/receitafederal\/pt-br\" target=\"_blank\" rel=\"noreferrer noopener\">p\u00e1gina da Receita Federal<\/a>&nbsp;na internet. Basta o contribuinte clicar em \u201cMeu Imposto de Renda\u201d e, em seguida, no bot\u00e3o \u201cConsultar a Restitui\u00e7\u00e3o\u201d. Tamb\u00e9m \u00e9 poss\u00edvel fazer a consulta no aplicativo da Receita Federal para tablets e smartphones.<\/p>\n\n\n\n<p>O pagamento ser\u00e1 feito em 30 de junho, na conta ou na chave Pix do tipo CPF informada na declara\u00e7\u00e3o do Imposto de Renda. Caso o contribuinte n\u00e3o esteja na lista, dever\u00e1 entrar no&nbsp;<a href=\"https:\/\/cav.receita.fazenda.gov.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Centro Virtual de Atendimento ao Contribuinte<\/a>&nbsp;(e-CAC)&nbsp;e tirar o extrato da declara\u00e7\u00e3o. Se verificar uma pend\u00eancia, pode enviar uma declara\u00e7\u00e3o retificadora e esperar os pr\u00f3ximos lotes da malha fina.<\/p>\n\n\n\n<p>Se, por algum motivo, a restitui\u00e7\u00e3o n\u00e3o for depositada na conta informada na declara\u00e7\u00e3o, como no caso de conta desativada, os valores ficar\u00e3o dispon\u00edveis para resgate por at\u00e9 um ano no Banco do Brasil. Nesse caso, o cidad\u00e3o poder\u00e1 agendar o cr\u00e9dito em qualquer conta banc\u00e1ria em seu nome, por meio do&nbsp;<a href=\"https:\/\/www.bb.com.br\/irpf\" target=\"_blank\" rel=\"noreferrer noopener\">Portal BB<\/a>&nbsp;ou ligando para a Central de Relacionamento do banco, nos telefones 4004-0001 (capitais), 0800-729-0001 (demais localidades) e 0800-729-0088 (telefone especial exclusivo para deficientes auditivos).<\/p>\n\n\n\n<p>Caso o contribuinte n\u00e3o resgate o valor de sua restitui\u00e7\u00e3o depois de um ano, dever\u00e1 requerer o valor no Portal e-CAC. Ao entrar na p\u00e1gina, o cidad\u00e3o deve acessando o menu \u201cDeclara\u00e7\u00f5es e Demonstrativos\u201d, clicar em \u201cMeu Imposto de Renda\u201d e, em seguida, no campo &#8220;Solicitar restitui\u00e7\u00e3o n\u00e3o resgatada na rede banc\u00e1ria&#8221;.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Maria Claudia<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 5,1 milh\u00f5es de contribuintes receber\u00e3o R$ 7,5 bilh\u00f5es Por Wellton M\u00e1ximo \u2013 Rep\u00f3rter<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62258","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62258"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62258\/revisions"}],"predecessor-version":[{"id":62260,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62258\/revisions\/62260"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62258"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}