{"id":62305,"date":"2023-06-25T05:00:00","date_gmt":"2023-06-25T08:00:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62305"},"modified":"2023-06-24T10:15:45","modified_gmt":"2023-06-24T13:15:45","slug":"campanha-sobre-projeto-de-petropolis-que-treina-caes-resgatados-para-deteccao-do-cancer-de-mama-em-estagio-inicial-recebe-lions-de-ouro-em-cannes","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/25\/campanha-sobre-projeto-de-petropolis-que-treina-caes-resgatados-para-deteccao-do-cancer-de-mama-em-estagio-inicial-recebe-lions-de-ouro-em-cannes\/","title":{"rendered":"Campanha sobre projeto de Petr\u00f3polis que treina c\u00e3es resgatados para detec\u00e7\u00e3o do c\u00e2ncer de mama em est\u00e1gio inicial recebe Lions de Ouro em Cannes"},"content":{"rendered":"\n<p>A campanha sobre o projeto Kdog Brasil (Dog Without Borders), que ocorre em Petr\u00f3polis, treinando c\u00e3es resgatados para detec\u00e7\u00e3o do c\u00e2ncer de mama em est\u00e1gio inicial atrav\u00e9s do olfato, recebeu o Lions de Ouro em Cannes na tarde desta sexta-feira (23), na categoria: Sustentabilidade e Metas para o desenvolvimento. Com produ\u00e7\u00e3o da produ\u00e7\u00e3o da&nbsp;VMLY&amp;R&nbsp;New York, a&nbsp;campanha foi uma iniciativa da Sociedade Franco-Brasileira de Oncologia, presidida pela m\u00e9dica Carla Ismael, e visa atender, principalmente, pessoas que vivem em locais de dif\u00edcil acesso e com limita\u00e7\u00f5es aos servi\u00e7os de sa\u00fade.<\/p>\n\n\n\n<p>O Kdog Brasil \u00e9 um programa de pesquisa que come\u00e7ou em 2016 e tem como objetivo desenvolver uma t\u00e9cnica n\u00e3o invasiva de rastreamento do c\u00e2ncer de mama usando o olfato canino. O estudo revela que os c\u00e3es podem detectar o c\u00e2ncer com quase 100% de precis\u00e3o, mesmo antes de um tumor se formar.<\/p>\n\n\n\n<p>&nbsp;\u201cEstamos extasiados com esta conquista em Cannes sobre uma campanha que estimula a transforma\u00e7\u00e3o desses c\u00e3es resgatados em c\u00e3es que ajudam na detec\u00e7\u00e3o de uma doen\u00e7a. Esta \u00e9 uma maneira de identificarmos o c\u00e2ncer de mama mais rapidamente e com custos mais baixos. N\u00e3o \u00e9 \u00e0 toa que remetem os c\u00e3es como melhores amigos dos seres humanos. E eles s\u00e3o, comprovadamente, essenciais para o diagn\u00f3stico de uma doen\u00e7a que ainda mata muitas mulheres que descobrem tardiamente no Brasil\u201d, destaca a m\u00e9dica Carla Ismael.<\/p>\n\n\n\n<p>Ela explica que os c\u00e3es, que foram resgatados, s\u00e3o treinados para reconhecer o odor do c\u00e2ncer a partir de uma compressa simples. A pesquisa ocorre sem contato entre o paciente e o cachorro.<\/p>\n\n\n\n<p><strong>Sobre a pesquisa<\/strong><\/p>\n\n\n\n<p>O trabalho de pesquisa do Kdog Brasil chegou \u00e0 conclus\u00e3o de que o c\u00e2ncer de mama emite odores espec\u00edficos que s\u00e3o indetect\u00e1veis pelos humanos, mas que um c\u00e3o treinado nessa detec\u00e7\u00e3o pode identificar a presen\u00e7a de c\u00e2ncer em len\u00e7os umedecidos que s\u00f3 estiveram em contato com a pele.<\/p>\n\n\n\n<p>O pr\u00f3ximo passo da Kdog Brasil \u00e9 desenvolver um m\u00e9todo de triagem simples e confi\u00e1vel, n\u00e3o invasivo e acess\u00edvel. Ao todo, s\u00e3o quatro c\u00e3es treinados que fazem parte do projeto em Petr\u00f3polis.<\/p>\n\n\n\n<p>Carla Ismael destaca que o trabalho com os c\u00e3es vem para antecipar o diagn\u00f3stico e n\u00e3o substitui o protocolo de detec\u00e7\u00e3o da doen\u00e7a, como a mamografia e outros exames.<\/p>\n\n\n\n<p><strong>Como ocorre a detec\u00e7\u00e3o?<\/strong><\/p>\n\n\n\n<p>A amostra \u00e9 feita a partir de mulheres que s\u00e3o orientadas a lavar as m\u00e3os antes de dormir, com sabonete neutro, e colocar as compressas em um kit sobre as duas mamas, retirando-as ao acordar, ap\u00f3s nova lavagem das m\u00e3os com o sabonete neutro.<\/p>\n\n\n\n<p>Estas compressas s\u00e3o colocadas em um saco e enviadas para o Kdog Brasil, onde s\u00e3o submetidas ao olfato dos animais. Os c\u00e3es ficam est\u00e1ticos em frente \u00e0 amostrapositiva para o c\u00e2ncer de mama.\u00a0<\/p>\n\n\n\n<p>Foto: divulga\u00e7\u00e3o <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A campanha sobre o projeto Kdog Brasil (Dog Without Borders), que ocorre em Petr\u00f3polis, treinando<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62305","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62305"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62305\/revisions"}],"predecessor-version":[{"id":62307,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62305\/revisions\/62307"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}