{"id":62308,"date":"2023-06-25T05:00:00","date_gmt":"2023-06-25T08:00:00","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62308"},"modified":"2023-06-24T10:20:38","modified_gmt":"2023-06-24T13:20:38","slug":"inscricoes-prorrogadas-ate-7-de-julho-do-concurso-para-professores-efetivos-do-cefet-rj-unidade-petropolis-oferta-tres-vagas","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/25\/inscricoes-prorrogadas-ate-7-de-julho-do-concurso-para-professores-efetivos-do-cefet-rj-unidade-petropolis-oferta-tres-vagas\/","title":{"rendered":"Inscri\u00e7\u00f5es prorrogadas at\u00e9 7 de julho do concurso para professores efetivos do Cefet\/RJ; unidade Petr\u00f3polis oferta tr\u00eas vagas"},"content":{"rendered":"\n<p>Foram prorrogadas at\u00e9 o dia 7 de julho as inscri\u00e7\u00f5es para o concurso p\u00fablico para sele\u00e7\u00e3o de professores do Cefet\/RJ. O processo seletivo \u00e9 para preenchimento de vagas para o quadro permanente das oito unidadesda institui\u00e7\u00e3o. No Cefet\/RJ Petr\u00f3polis, foram disponibilizadas tr\u00eas vagas: duas para a \u00e1rea da Matem\u00e1tica (Ensino de Matem\u00e1tica) e uma para Computa\u00e7\u00e3o (Programa\u00e7\u00e3o\/Algoritmos). &nbsp;<\/p>\n\n\n\n<p>As inscri\u00e7\u00f5es podem ser realizadas pelo site do Cefet\/RJ (<a href=\"http:\/\/www.cefet-rj.br\/docentes\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.cefet-rj.br\/docentes<\/a>). Os interessados dever\u00e3o preencher o formul\u00e1rio e pagar a taxa de inscri\u00e7\u00e3o, no valor de R$ 120,00. &nbsp;<\/p>\n\n\n\n<p>O concurso ser\u00e1 realizado em tr\u00eas etapas: prova escrita (eliminat\u00f3ria e classificat\u00f3ria), prova p\u00fablica de aula (eliminat\u00f3ria e classificat\u00f3ria) e prova de t\u00edtulos (classificat\u00f3ria). A prova escrita ser\u00e1 realizada no fim de julho e a prova p\u00fablica de aula em setembro. O resultado final do processo seletivo ser\u00e1 divulgado em 13 de outubro. &nbsp;<\/p>\n\n\n\n<p><a href=\"http:\/\/www.cefet-rj.br\/index.php\/docentes\/7931-1-concurso-publico-para-professor-do-quadro-efetivo-2023\" target=\"_blank\" rel=\"noreferrer noopener\">Maiores informa\u00e7\u00f5es e acesso ao edital e anexos na p\u00e1gina do processo seletivo.<\/a>&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>Sobre o Cefet\/RJ Petr\u00f3polis<\/strong><\/p>\n\n\n\n<p>O Cefet\/RJ Petr\u00f3polis \u00e9 uma das oito unidades do sistema Cefet\/RJ, al\u00e9m de Maracan\u00e3, Maria da Gra\u00e7a, Nova Igua\u00e7u, Nova Friburgo, Itagua\u00ed, Valen\u00e7a e Angra dos Reis. Localizado na Rua do Imperador, no centro da cidade, o Cefet\/RJ Petr\u00f3polis oferta o curso t\u00e9cnico em Telecomunica\u00e7\u00f5es integrado ao ensino m\u00e9dio e quatro cursos de gradua\u00e7\u00e3o \u2013 Bacharelado em Engenharia de Computa\u00e7\u00e3o, Bacharelado em Turismo, Licenciatura em F\u00edsica e Licenciatura em Matem\u00e1tica. &nbsp;<\/p>\n\n\n\n<p><br><a rel=\"noreferrer noopener\" href=\"http:\/\/www.cefet-rj.br\/petropolis\" target=\"_blank\">http:\/\/www.cefet-rj.br\/petropolis<\/a>\u00a0\u00a0<\/p>\n\n\n\n<p>Foto: divulga\u00e7\u00e3o <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram prorrogadas at\u00e9 o dia 7 de julho as inscri\u00e7\u00f5es para o concurso p\u00fablico para<\/p>\n","protected":false},"author":2,"featured_media":49768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62308"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62308\/revisions"}],"predecessor-version":[{"id":62309,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62308\/revisions\/62309"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/49768"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}