{"id":62411,"date":"2023-06-26T14:12:48","date_gmt":"2023-06-26T17:12:48","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62411"},"modified":"2023-06-26T14:12:49","modified_gmt":"2023-06-26T17:12:49","slug":"bazar-de-inverno-da-appo-continua-de-portas-abertas-e-com-muitas-novidades","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/26\/bazar-de-inverno-da-appo-continua-de-portas-abertas-e-com-muitas-novidades\/","title":{"rendered":"Bazar de inverno da APPO continua de portas abertas e com muitas novidades"},"content":{"rendered":"\n<p>O Bazar da APPO j\u00e1 \u00e9 muito conhecido por aquelas pessoas que amam garimpar, tanto pela qualidade das pe\u00e7as, quanto pelos pre\u00e7os. Com reposi\u00e7\u00e3o cont\u00ednua, o Bazar de Inverno vai funcionar at\u00e9 14 de julho, sempre de segunda \u00e0 sexta-feira, das 10h \u00e0s 16h, e est\u00e1 sendo realizado na Sala de Conviv\u00eancia na sede da Institui\u00e7\u00e3o.<\/p>\n\n\n\n<p>Al\u00e9m de roupas, para adultos e crian\u00e7as, no Bazar da APPO tamb\u00e9m \u00e9 poss\u00edvel encontrar uma infinidade de itens como brinquedos, cal\u00e7ados, acess\u00f3rios, utilidades para o lar, objetos de decora\u00e7\u00e3o entre outros. Tudo a pre\u00e7os simb\u00f3licos, acess\u00edveis a todos.<\/p>\n\n\n\n<p>Todo valor arrecadado com a venda das pe\u00e7as ser\u00e1 utilizado para compor recursos necess\u00e1rios para manter a Casa de Apoio, que funciona durante o ano todo acolhendo pessoas que vem de outras cidades fazer o tratamento do c\u00e2ncer em Petr\u00f3polis. A Casa de Apoio tem capacidade para receber 30 pessoas e oferece al\u00e9m de seguran\u00e7a, conforto e alimenta\u00e7\u00e3o, assist\u00eancia total, por meio da equipe multidisciplinar, para a perman\u00eancia e conclus\u00e3o do tratamento.<\/p>\n\n\n\n<p>As edi\u00e7\u00f5es do Bazar da APPO, realizadas ao longo do ano, s\u00e3o importantes fontes de recurso para manter a Casa e garantir o sucesso no tratamento de c\u00e2ncer de pessoas que moram em v\u00e1rias cidades do interior do Rio de Janeiro. \u201cSem este recurso, muitas pessoas talvez n\u00e3o conseguissem fazer o tratamento, que \u00e9 t\u00e3o importante n\u00e3o s\u00f3 para o nosso acolhido, que enfrenta a doen\u00e7a, mas para todos os amigos e familiares. O Bazar \u00e9 sin\u00f4nimo de vida para essas pessoas\u201d, destacou Magna Souza, respons\u00e1vel pelo Bazar da APPO.<\/p>\n\n\n\n<p>Todos os itens que estar\u00e3o \u00e0 venda foram doados \u00e0 APPO e passam por sele\u00e7\u00e3o e cuidados criteriosos. Quando necess\u00e1rio, as pe\u00e7as s\u00e3o costuradas, lavadas, devidamente dobradas e empacotadas.<\/p>\n\n\n\n<p>Outras a\u00e7\u00f5es com o intuito de angariar recursos para a APPO continuam normalmente, uma delas \u00e9 o setor de Telemarketing Ativo. Coordenado por Alexandre de Carvalho Brito, o Telemarketing funciona de segunda a sexta-feira, sempre das 8h \u00e0s 14h. Em linhas gerais as operadoras entram em contato por meio de liga\u00e7\u00e3o para telefones fixos e celulares e tem como meta apresentar a institui\u00e7\u00e3o e o trabalho que a mesma executa diariamente na cidade. Caso a pessoa que atendeu se interesse pela causa e deseje se tornar um doador, as operadoras geram o cadastro do doador, solicitando nome completo, telefone e endere\u00e7o. A partir da\u00ed \u00e9 agendado o dia e hor\u00e1rio em que o mensageiro da Associa\u00e7\u00e3o vai retirar a doa\u00e7\u00e3o em esp\u00e9cie e entregar o recibo de oficializa\u00e7\u00e3o do apoio.<\/p>\n\n\n\n<p>As doa\u00e7\u00f5es captadas pelo setor de Telemarketing da APPO tamb\u00e9m podem ser encaminhadas para a institui\u00e7\u00e3o por meio de dep\u00f3sito banc\u00e1rio no Banco Ita\u00fa, Ag\u00eancia 9244 e conta corrente 09277-2. Seguindo o avan\u00e7o das rela\u00e7\u00f5es financeiras, as doa\u00e7\u00f5es tamb\u00e9m podem ser feitas por meio de Pix atrav\u00e9s da Chave PIX, que \u00e9 o CNPJ da institui\u00e7\u00e3o, o 36.548.949\/0001-78.<\/p>\n\n\n\n<p>Ap\u00f3s realizar as opera\u00e7\u00f5es banc\u00e1rias, os doadores devem via WhatsApp (24) 99276-9832, enviar o comprovante da transa\u00e7\u00e3o financeira e solicitar o recibo referente a doa\u00e7\u00e3o.<\/p>\n\n\n\n<p>Foto: divulga\u00e7\u00e3o <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Bazar da APPO j\u00e1 \u00e9 muito conhecido por aquelas pessoas que amam garimpar, tanto<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62411","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62411"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62411\/revisions"}],"predecessor-version":[{"id":62413,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62411\/revisions\/62413"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}