{"id":62446,"date":"2023-06-26T17:54:56","date_gmt":"2023-06-26T20:54:56","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62446"},"modified":"2023-06-26T17:54:57","modified_gmt":"2023-06-26T20:54:57","slug":"primeiro-final-de-semana-da-bauernfest-gera-resultados-positivos-para-comerciantes-e-guias","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/26\/primeiro-final-de-semana-da-bauernfest-gera-resultados-positivos-para-comerciantes-e-guias\/","title":{"rendered":"Primeiro final de semana da Bauernfest gera resultados positivos para comerciantes e guias"},"content":{"rendered":"\n<p>No \u00faltimo final de semana come\u00e7ou em Petr\u00f3polis a 34\u00aa edi\u00e7\u00e3o da Bauernfest, Festa do Colono Alem\u00e3o. O evento que busca valorizar a gastronomia e cultura alem\u00e3 atraiu um grande p\u00fablico tanto de moradores quanto de turistas, e valorizou o trabalho de grandes e pequenos comerciantes locais.<\/p>\n\n\n\n<p>O evento voltou a sua normalidade ap\u00f3s n\u00e3o ter sido promovido em 2020, ter ocorrido de forma online em 2021 e ter sido realizado fora de \u00e9poca em 2022. Esse ano, al\u00e9m da tradicional Rua Alfredo Pach\u00e1, o evento contou com programa\u00e7\u00e3o em diversos locais. \u201cAl\u00e9m do tradicional Pal\u00e1cio de Cristal, a Pra\u00e7a da Liberdade possui programa\u00e7\u00e3o infantil, e as Casas Petr\u00f3polis e Steffan Zweig tamb\u00e9m est\u00e3o com programa\u00e7\u00e3o. Al\u00e9m disso, vamos para os distritos de Cascatinha, Itaipava, Pedro do Rio e Posse. Haver\u00e1 programa\u00e7\u00e3o especial ainda Rua Teresa\u201d, disse Charles Rossi, membro do Conselho Municipal de Turismo.<\/p>\n\n\n\n<p><strong>Com\u00e9rcio<\/strong><\/p>\n\n\n\n<p>Para o com\u00e9rcio alguns vendedores puderam aproveitar o movimento positivo tanto de turistas quanto de moradores, \u00e9 o que comenta a confeiteira Beatriz Neves, um dos donos da B&amp;C Cuisine P\u00e2tisserie que est\u00e1 com uma barraca montada na Rua Teresa. \u201cO primeiro final de semana foi bom principalmente no s\u00e1bado, que teve mais movimento. A maioria eram turistas e o movimento foi bom tanto para eles, quanto para os lojistas. Todos estavam no clima da Bauernfest\u201d, disse a confeiteira.<\/p>\n\n\n\n<p>No Centro do evento no Pal\u00e1cio de Cristal tamb\u00e9m houve comerciante feliz com o resultado, Kadu de Paula, vendedor destacou o forte movimento no primeiro final de semana e comentou sobre a import\u00e2ncia da festa para a cidade. \u201cA Bauernfest \u00e9 a festa mais importante para a cidade e para o empreendedor. A festa beneficia de todos os lados, al\u00e9m dos empregos diretos, temos toda uma cadeia de produ\u00e7\u00e3o indireta, esse dinheiro que vem de fora \u00e9 muito importante para os empres\u00e1rios e seus funcion\u00e1rios\u201d, comentou o vendedor.<\/p>\n\n\n\n<p>Charles Rossi tamb\u00e9m destacou o impacto econ\u00f4mico do evento segundo ele, mais de duas mil pessoas trabalham durante o per\u00edodo, \u201cEla traz um benef\u00edcio muito grande econ\u00f4mico para cidade ela emprega na cidade nas barracas, s\u00f3 de dan\u00e7arinos temos mais de 400 pessoas\u201d, relata o representante.<\/p>\n\n\n\n<p><strong>Turismo<\/strong><\/p>\n\n\n\n<p>Para o turismo o evento tamb\u00e9m foi ben\u00e9fico, todo ano a festa atrai um valioso p\u00fablico de fora da cidade e esse ano n\u00e3o foi diferente, a guia tur\u00edstica Raquel Neves destacou a import\u00e2ncia de voltar a ver tantos turistas na cidade ap\u00f3s as chuvas de 2022. \u201cEconomicamente, \u00e9 fundamental para todos n\u00f3s. Passamos por muitas dificuldades, mas conseguimos super\u00e1-las, ver a cidade cheia de turistas pra n\u00f3s \u00e9 sin\u00f4nimo de esperan\u00e7a\u201d, relata a guia, que ainda completa que a procura por profissionais da \u00e1rea est\u00e1 forte.<\/p>\n\n\n\n<p>Por Guilherme Mattos\/Foto: Reprodu\u00e7\u00e3o instagram Bauernfest<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo final de semana come\u00e7ou em Petr\u00f3polis a 34\u00aa edi\u00e7\u00e3o da Bauernfest, Festa do<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62446","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62446"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62446\/revisions"}],"predecessor-version":[{"id":62448,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62446\/revisions\/62448"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}