{"id":62502,"date":"2023-06-27T13:07:14","date_gmt":"2023-06-27T16:07:14","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62502"},"modified":"2023-06-27T13:07:14","modified_gmt":"2023-06-27T16:07:14","slug":"internacoes-por-sindromes-respiratorias-aumentam-no-norte-e-nordeste","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/27\/internacoes-por-sindromes-respiratorias-aumentam-no-norte-e-nordeste\/","title":{"rendered":"Interna\u00e7\u00f5es por s\u00edndromes respirat\u00f3rias aumentam no Norte e Nordeste"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Boletim Infogripe foi divulgado hoje pela Fiocruz<\/h3>\n\n\n\n<h4 class=\"wp-block-heading\">Por Vin\u00edcius Lisboa \u2013 Rep\u00f3rter da Ag\u00eancia Brasil &#8211; Rio de Janeiro<audio src=\"https:\/\/tts-app.ebc.com.br\/media\/tts\/205612.mp3\"><\/audio><\/h4>\n\n\n\n<p>Os casos graves de v\u00edrus sincicial respirat\u00f3rio (VSR) em crian\u00e7as continuam a puxar para cima a tend\u00eancia de hospitaliza\u00e7\u00f5es por s\u00edndrome respirat\u00f3ria em parte do Norte e Nordeste do Brasil. A informa\u00e7\u00e3o consta do mais recente Boletim Infogripe, divulgado hoje (27) pela Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1540529&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1540529&amp;o=node\"><\/p>\n\n\n\n<p>Nos estados do Acre, Amap\u00e1, Par\u00e1, Rio Grande do Norte e Roraima, as hospitaliza\u00e7\u00f5es por S\u00edndrome Respirat\u00f3ria Aguda Grave (SRAG) est\u00e3o em alta nas \u00faltimas seis semanas fundamentalmente devido aos casos em crian\u00e7as e adolescentes. J\u00e1 em Sergipe, al\u00e9m da alta na mesma faixa et\u00e1ria, tamb\u00e9m foi registrado aumento em adultos de idade mais avan\u00e7ada.<\/p>\n\n\n\n<p>O coordenador do Infogripe Marcelo Gomes alerta que, ainda que haja tend\u00eancia de estabiliza\u00e7\u00e3o ou queda da SRAG no p\u00fablico infantil dos estados do Centro-Sul, o n\u00famero de casos j\u00e1 tinha chegado a um patamar alto.<\/p>\n\n\n\n<p>\u201cComo esses estados passaram por um longo per\u00edodo de aumento, semana ap\u00f3s semana, nos casos de SRAG nas crian\u00e7as pequenas, a interrup\u00e7\u00e3o ou revers\u00e3o dessa tend\u00eancia ainda levar\u00e1 um tempo para se refletir em diminui\u00e7\u00e3o nos leitos ocupados, j\u00e1 que parte dessas crian\u00e7as continua hospitalizada. Al\u00e9m disso, as baixas temperaturas favorecem as infec\u00e7\u00f5es respirat\u00f3rias nesse per\u00edodo do ano, de modo que \u00e9 importante mantermos os cuidados de ventila\u00e7\u00e3o adequada e uso de boas m\u00e1scaras por parte das pessoas que est\u00e3o apresentando sintomas gripais e n\u00e3o possuem condi\u00e7\u00f5es de fazer o repouso recomendado\u201d, disse Marcelo Gomes, segundo a Fiocruz.<\/p>\n\n\n\n<p>Nas quatro \u00faltimas semanas epidemiol\u00f3gicas, o v\u00edrus sincicial respirat\u00f3rio causou 40% das ocorr\u00eancias de SRAG com origem viral no pa\u00eds. O SARS-CoV-2, que causa a covid-19, respondeu por 22,8% dos casos, seguido por 17,5% do v\u00edrus da Influenza A, e 6,6% do daInfluenza B. Apesar disso, a covid-19 continua a responder por metade dos \u00f3bitos causados por s\u00edndromes respirat\u00f3rias agudas graves virais no pa\u00eds.<\/p>\n\n\n\n<p>A Fiocruz destaca ainda que o Sars-Cov-2 permanece em queda no n\u00famero de casos entre a popula\u00e7\u00e3o adulta na maioria dos estados. Em mar\u00e7o, o v\u00edrus respondia por 80% dos casos, participa\u00e7\u00e3o que caiu para 50% em maio.<\/p>\n\n\n\n<p>J\u00e1 a gripe causada pela Influenza A &#8211; majoritariamente H1N1 &#8211; registrou aumento ao longo do m\u00eas de maio e manteve presen\u00e7a importante em junho.<\/p>\n\n\n\n<p>Edi\u00e7\u00e3o: Denise Griesinger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Boletim Infogripe foi divulgado hoje pela Fiocruz Por Vin\u00edcius Lisboa \u2013 Rep\u00f3rter da Ag\u00eancia Brasil<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62502","post","type-post","status-publish","format-standard","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62502"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62502\/revisions"}],"predecessor-version":[{"id":62504,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62502\/revisions\/62504"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}