{"id":62505,"date":"2023-06-27T13:36:45","date_gmt":"2023-06-27T16:36:45","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62505"},"modified":"2023-06-27T13:36:46","modified_gmt":"2023-06-27T16:36:46","slug":"petropolis-perde-recursos-de-emenda-parlamentar-que-garantiriam-reforma-da-praca-de-skate-do-centro","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/27\/petropolis-perde-recursos-de-emenda-parlamentar-que-garantiriam-reforma-da-praca-de-skate-do-centro\/","title":{"rendered":"Petr\u00f3polis perde recursos de emenda parlamentar que garantiriam reforma da Pra\u00e7a de Skate do Centro"},"content":{"rendered":"\n<p><em><strong>Munic\u00edpio n\u00e3o conseguiu receber R$286,5 mil de emendas do deputado federal Hugo Leal por falhas irregularidades constatadas pelo Minist\u00e9rio da Economia em dezembro de 2022<\/strong><\/em><\/p>\n\n\n\n<p>Petr\u00f3polis perdeu R$ 286,5 mil do governo federal para a reforma da \u00fanica pista de skate do Centro da cidade, que funciona na Pra\u00e7a Duque de Caxias. As informa\u00e7\u00f5es constam no CAUC (cadastro que verifica o cumprimento de requisitos fiscais necess\u00e1rios \u00e0 celebra\u00e7\u00e3o de instrumentos para transfer\u00eancia de recursos do governo federal). A obra \u00e9 uma demanda antiga dos praticantes do esporte e seria realizada com recursos de emenda parlamentar do deputado federal Hugo Leal, conquistada ap\u00f3s pedido feito pelo vereador Hingo Hammes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/WhatsApp-Image-2023-06-27-at-13.35.07-1-1024x768.jpeg\" alt=\"\" class=\"wp-image-62508\"\/><\/figure>\n\n\n\n<p>\u201c\u00c9 um sentimento de frustra\u00e7\u00e3o tanto minha, que trabalhei para conseguir essa verba, quanto das pessoas que ficaram aguardando essa reforma. A gente tamb\u00e9m tem quadras que precisam de reforma e est\u00e3o na mesma situa\u00e7\u00e3o. Isso entristece a gente, que assumiu um compromisso com a popula\u00e7\u00e3o, mas infelizmente a prefeitura n\u00e3o conseguiu dar continuidade ao processo\u201d, afirmou Hugo Leal. A emenda parlamentar foi anunciada h\u00e1 um ano, quando Petr\u00f3polis criou o Dia Municipal do Skate, celebrado em 21 de junho.<\/p>\n\n\n\n<p>\u201cOs praticantes do esporte lutam h\u00e1 muito tempo por essas melhorias. L\u00e1 atr\u00e1s nos reunimos com o grupo, buscamos o apoio do deputado Hugo Leal e conseguimos a emenda. Esper\u00e1vamos ver a obra sair do papel este ano, mas, ao inv\u00e9s disso, estamos vendo todo este trabalho ser desperdi\u00e7ado. \u00c9 lament\u00e1vel. Valorizar aquele espa\u00e7o \u00e9 valorizar o esporte. \u00c9 dar oportunidades aos jovens e mostrar o quanto acreditamos no futuro deles\u201d, frisou o vereador Hingo Hammes, lembrando que importantes nomes do skate no Estado do Rio j\u00e1 surgiram naquela pista.<\/p>\n\n\n\n<p>Os recursos da emenda parlamentar garantiriam melhorias estruturais na pista, que, hoje, tem pontos quebrados ou desgastadas, aumentando os riscos de acidentes.<\/p>\n\n\n\n<p>Al\u00e9m da pista de skate do Centro, Petr\u00f3polis tamb\u00e9m tem espa\u00e7os para o esporte em Itaipava (Parque Municipal) e na Posse (CEU da Posse).<\/p>\n\n\n\n<p>Foto: Raphaela Cordeiro <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Munic\u00edpio n\u00e3o conseguiu receber R$286,5 mil de emendas do deputado federal Hugo Leal por falhas<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62505","post","type-post","status-publish","format-standard","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62505"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62505\/revisions"}],"predecessor-version":[{"id":62509,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62505\/revisions\/62509"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}