{"id":62542,"date":"2023-06-28T08:03:01","date_gmt":"2023-06-28T11:03:01","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62542"},"modified":"2023-06-28T08:03:03","modified_gmt":"2023-06-28T11:03:03","slug":"vida-e-obra-de-heitor-dos-prazeres-sao-tema-de-exposicao-no-rio","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/28\/vida-e-obra-de-heitor-dos-prazeres-sao-tema-de-exposicao-no-rio\/","title":{"rendered":"Vida e obra de Heitor dos Prazeres s\u00e3o tema de exposi\u00e7\u00e3o no Rio"},"content":{"rendered":"\n<p>&#8220;Este prazer que eu tenho no nome \u00e9 o prazer que eu divido com o povo. Este povo com quem eu reparto este prazer. Este povo que sofre, este povo que trabalha, este povo alegre que eu compartilho a alegria desse povo\u201d. O verso, escrito por Heitor dos Prazeres (1898-1966), al\u00e9m de uma apresenta\u00e7\u00e3o pessoal, ajuda a dimensionar a vida e a obra do artista. Algu\u00e9m com m\u00faltiplos talentos e habilidades, conectado intensamente com a cultura popular do pa\u00eds, especialmente da popula\u00e7\u00e3o afro-brasileira. A partir desta quarta-feira (28), Heitor \u00e9 o tema da nova exposi\u00e7\u00e3o em cartaz no Centro Cultural Banco do Brasil (CCBB) no Rio de Janeiro.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1540760&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1540760&amp;o=node\"><\/p>\n\n\n\n<p>Mais de 200 obras est\u00e3o presentes na mostra \u201cHeitor dos Prazeres \u00e9 meu nome\u201d, uma esp\u00e9cie de retrospectiva da produ\u00e7\u00e3o art\u00edstica nos campos visual, musical, liter\u00e1rio e da moda. Quem visitar as dez salas da exposi\u00e7\u00e3o vai ter uma pequena amostra de um trabalho que \u00e9 marcado pela variedade de materiais e linguagens. S\u00e3o pinturas, can\u00e7\u00f5es, partituras, projetos, desenhos, discos e indument\u00e1rias que marcaram a trajet\u00f3ria do pintor, sambista, compositor e instrumentista.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"463\" height=\"309\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/heitor-dos-prazeres-3.jpg\" alt=\"\" class=\"wp-image-62545\" srcset=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/heitor-dos-prazeres-3.jpg 463w, https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/heitor-dos-prazeres-3-300x200.jpg 300w\" sizes=\"auto, (max-width: 463px) 100vw, 463px\" \/><\/figure>\n\n\n\n<p>\u201cA produ\u00e7\u00e3o do Heitor era t\u00e3o rica e diversa que sempre vai faltar algo. Daria para fazer uma exposi\u00e7\u00e3o com \u00eanfase no samba, na m\u00fasica, no carnaval. Sobre qualquer um desses temas. Nossa op\u00e7\u00e3o foi pelas artes visuais e em apresentar o Heitor dos Prazeres \u00e0s novas gera\u00e7\u00f5es, a partir da complexidade da obra dele. Destacamos algumas tem\u00e1ticas, como a modernidade negra, o campo da afetividade e a sociabilidade\u201d, afirma uma das curadoras da exposi\u00e7\u00e3o, Raquel Barreto.<\/p>\n\n\n\n<p>Na carreira musical, Heitor dos Prazeres foi fundamental na cria\u00e7\u00e3o de blocos, ranchos e das primeiras escolas de samba do Rio: Mangueira, Portela e Deixa Falar, que mudaria de nome para Est\u00e1cio de S\u00e1. Ele comp\u00f4s mais de duzentas can\u00e7\u00f5es, em ritmos que inclu\u00edram tamb\u00e9m a marcha, o choro, a valsa e o bai\u00e3o. Ele frequentou a famosa casa de Tia Ciata, que reuniu nomes importantes do samba como Noel Rosa, Cartola, Paulo da Portela e Pixinguinha.<\/p>\n\n\n\n<p>Em um dos espa\u00e7os da mostra, uma reprodu\u00e7\u00e3o do jornal Di\u00e1rio da Noite traz a letra escrita pelo artista de um \u201cHino do Carnaval\u201d, o samba \u201cAlegria do Nosso Brasil\u201d. Logo ao lado, tamb\u00e9m est\u00e1 exposto o m\u00e9todo pr\u00e1tico de cavaquinho de cinco cordas, escrito por ele de forma manual em uma folha simples, amarelada pela a\u00e7\u00e3o do tempo.<\/p>\n\n\n\n<p>Na \u00e1rea das artes pl\u00e1sticas, as primeiras pinturas vieram depois que Heitor j\u00e1 era conhecido no meio do samba. Com um tra\u00e7o colorido e vivo, com temas do cotidiano urbano e rural, as obras ganharam import\u00e2ncia nacional e internacional. Ele venceu um pr\u00eamio na I Bienal de Arte de S\u00e3o Paulo, de 1951, na categoria pintura nacional. E participou da II Bienal de S\u00e3o Paulo, de 1953, com a exposi\u00e7\u00e3o de algumas obras. Participou ainda de mostras no Museu de Arte Moderna do Rio (MAM), em 1961, e do I Festival de Artes Negras em Dakar, no Senegal, em 1966.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"463\" height=\"309\" src=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/heitor-dos-prazeres-2-1.jpg\" alt=\"\" class=\"wp-image-62546\" srcset=\"https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/heitor-dos-prazeres-2-1.jpg 463w, https:\/\/tvc16.com\/portal\/wp-content\/uploads\/2023\/06\/heitor-dos-prazeres-2-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 463px) 100vw, 463px\" \/><\/figure>\n\n\n\n<p>Na mostra em cartaz no CCBB, as pinturas destacam o contexto p\u00f3s-aboli\u00e7\u00e3o da escravid\u00e3o (1898) e as manifesta\u00e7\u00f5es das experi\u00eancias coletivas negras. Nascido no Rio de Janeiro, Heitor cresceu na regi\u00e3o conhecida hoje como Pequena \u00c1frica. Nome que os organizadores da mostra explicam derivar de um t\u00edtulo criado pelo artista: a \u00c1frica em miniatura, que compreende os bairros da Sa\u00fade, Gamboa e Santo Cristo, na zona portu\u00e1ria.<\/p>\n\n\n\n<p>Esse ambiente seria frequente em suas pinturas, como \u00e9 o caso das obras que retratam o Morro da Provid\u00eancia. Em uma delas, de 1965, enquanto o fluxo de ve\u00edculos e de pessoas acontece em um primeiro plano, ao fundo uma s\u00e9rie de casinhas coloridas se amontoam e parecem formar um grande mosaico em meio aos morros da capital carioca. Em outra tela do mesmo ano, o c\u00e9u nublado e as constru\u00e7\u00f5es em tons predominantemente cinzas da Pra\u00e7a XV contrastam com as cores vivas das roupas dos homens e mulheres que circulam pelo local. Nas duas obras, todas as pessoas s\u00e3o negras.<\/p>\n\n\n\n<p>\u201cEle foi um artista que colocou a popula\u00e7\u00e3o brasileira no centro de tudo e tornou as pessoas negras sujeitas da pr\u00f3pria hist\u00f3ria. E o Heitor foi protagonista da pr\u00f3pria vida. Apesar de todas as adversidades estruturais, que tendem a diminuir a capacidade do povo negro de estar no mundo, ele foi capaz de produzir uma obra e deixar registros primorosos com in\u00fameras possibilidades visuais, como podemos perceber pelas pinturas aqui da exposi\u00e7\u00e3o\u201d, explica Raquel Barreto.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Servi\u00e7o<\/h2>\n\n\n\n<p>Exposi\u00e7\u00e3o &#8220;Heitor dos Prazeres \u00e9 meu nome&#8221;<\/p>\n\n\n\n<p>De 28 de junho a 18 de setembro de 2023<\/p>\n\n\n\n<p>Centro Cultural Banco do Brasil<\/p>\n\n\n\n<p>Endere\u00e7o: Rua Primeiro de Mar\u00e7o 66 \u2013 1\u00ba andar &#8211; Centro, Rio de Janeiro<\/p>\n\n\n\n<p>Funcionamento: Segundas, quartas, quintas, sextas e s\u00e1bados, das 9h \u00e0s 21h; e Domingos, das 9h* \u00e0s 20h.<\/p>\n\n\n\n<p>*Aberto ao p\u00fablico com defici\u00eancia mental \/ intelectual das 8h \u00e0s 9h, em atendimento \u00e0 Lei Municipal n\u00ba 6.278\/2017.<\/p>\n\n\n\n<p>Entrada Gratuita<\/p>\n\n\n\n<p><em>Ag\u00eancia Brasil<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Este prazer que eu tenho no nome \u00e9 o prazer que eu divido com o<\/p>\n","protected":false},"author":2,"featured_media":62543,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[17],"tags":[],"class_list":["post-62542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outras-noticias"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62542"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62542\/revisions"}],"predecessor-version":[{"id":62547,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62542\/revisions\/62547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/62543"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}