{"id":62571,"date":"2023-06-28T13:41:24","date_gmt":"2023-06-28T16:41:24","guid":{"rendered":"https:\/\/tvc16.com\/portal\/?p=62571"},"modified":"2023-06-28T13:41:25","modified_gmt":"2023-06-28T16:41:25","slug":"camara-municipal-vai-requerer-acesso-a-laudo-da-policia-sobre-incendio-na-garagem-da-petro-ita","status":"publish","type":"post","link":"https:\/\/tvc16.com\/portal\/2023\/06\/28\/camara-municipal-vai-requerer-acesso-a-laudo-da-policia-sobre-incendio-na-garagem-da-petro-ita\/","title":{"rendered":"C\u00e2mara Municipal vai requerer acesso a laudo da pol\u00edcia sobre inc\u00eandio na garagem da Petro Ita"},"content":{"rendered":"\n<p>A C\u00e2mara Municipal vai requerer, por meio de processo de execu\u00e7\u00e3o, a apresenta\u00e7\u00e3o do laudo da pol\u00edcia sobre o inc\u00eandio na garagem da empresa Petro Ita. O inc\u00eandio foi no in\u00edcio de maio e destruiu mais de 70 ve\u00edculos da empresa e tamb\u00e9m da via\u00e7\u00e3o Cascatinha. As investiga\u00e7\u00f5es correm em sigilo.<\/p>\n\n\n\n<p>O pedido de acesso ao documento ser\u00e1 feito ap\u00f3s solicita\u00e7\u00e3o, na \u00faltima ter\u00e7a-feira (27), da Comiss\u00e3o Especial criada para acompanhar a apura\u00e7\u00e3o. Em reuni\u00e3o com a presen\u00e7a dos vereadores L\u00e9o Fran\u00e7a, Domingos Protetor, Gil Magno, Dr. Mauro Peralta e representante da vereadora J\u00falia Casamasso, o grupo definiu os pr\u00f3ximos passos do trabalho.<\/p>\n\n\n\n<p>\u201cO Departamento Jur\u00eddico da C\u00e2mara vai adotar os procedimentos legais para que tenhamos acesso ao documento. J\u00e1 existe um laudo que aponta ind\u00edcios de crime e precisamos saber se a investiga\u00e7\u00e3o da pol\u00edcia tamb\u00e9m levanta essa suspeita. O inc\u00eandio agravou ainda mais os problemas que j\u00e1 t\u00ednhamos no servi\u00e7o de transporte p\u00fablico, prejudicando milhares de pessoas. Temos que acompanhar toda esta apura\u00e7\u00e3o de perto. Ainda h\u00e1 muitas perguntas sem resposta\u201d, frisou o presidente da Casa, vereador J\u00fanior Coruja.<\/p>\n\n\n\n<p>O presidente da Comiss\u00e3o, vereador L\u00e9o Fran\u00e7a, informou que a investiga\u00e7\u00e3o est\u00e1 em sigilo e que a delegada n\u00e3o pode fornecer o laudo, por\u00e9m, a per\u00edcia \u00e9 p\u00fablica. &#8220;Atrav\u00e9s do jur\u00eddico da Casa Legislativa iremos entrar com um processo de execu\u00e7\u00e3o de apresenta\u00e7\u00e3o de documentos para que possamos ter acesso \u00e0 c\u00f3pia da per\u00edcia e do inqu\u00e9rito sobre inc\u00eandio&#8221;, explicou.<\/p>\n\n\n\n<p>Uma nova reuni\u00e3o ficou agendada para o pr\u00f3ximo dia 5 de julho, \u00e0s 14h, na Sala de Comiss\u00f5es da C\u00e2mara Municipal e o objetivo ser\u00e1 ouvir os funcion\u00e1rios que estavam presentes no local no momento do inc\u00eandio e os s\u00f3cios da empresa Petro Ita.<\/p>\n\n\n\n<p>A comiss\u00e3o tem o prazo de 180 dias (a contar do dia 14 de junho) para os trabalhos e tem como membros os vereadores Gil Magno, Dr. Mauro Peralta, J\u00falia Casamasso e Marcelo Lessa.<\/p>\n\n\n\n<p>Foto: divulga\u00e7\u00e3o <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A C\u00e2mara Municipal vai requerer, por meio de processo de execu\u00e7\u00e3o, a apresenta\u00e7\u00e3o do laudo<\/p>\n","protected":false},"author":2,"featured_media":62572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[],"class_list":["post-62571","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cidade"],"_links":{"self":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62571","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/comments?post=62571"}],"version-history":[{"count":1,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62571\/revisions"}],"predecessor-version":[{"id":62573,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/posts\/62571\/revisions\/62573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media\/62572"}],"wp:attachment":[{"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/media?parent=62571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/categories?post=62571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tvc16.com\/portal\/wp-json\/wp\/v2\/tags?post=62571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}